{"id":204919,"date":"2022-09-11T14:23:21","date_gmt":"2022-09-11T12:23:21","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=204919"},"modified":"2022-09-11T14:25:52","modified_gmt":"2022-09-11T12:25:52","slug":"francesco-mandoi-a-galatone-martedi-13","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/09\/11\/francesco-mandoi-a-galatone-martedi-13\/","title":{"rendered":"FRANCESCO MANDOI A GALATONE MARTEDI&#8217; 13"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1536\" height=\"1536\" class=\"wp-image-204922\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/fm.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/fm.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/fm-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/fm-1024x1024.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/fm-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/fm-768x768.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/fm-60x60.jpg 60w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/p>\n\n\n\n<p>(g.p.) ______\u00a0<\/p>\n\n\n\n<p><em>\u201cSar\u00e0 un&#8217;importante occasione  per discutere delle riforme del M5S sulla giustizia e per la sicurezza e per parlare del programma che con il Presidente Giuseppe Conte vogliamo mettere in atto per il contrasto alle mafie e per la lotta alla corruzione. Trasparenza, legalit\u00e0, lotta alla mafia sono da sempre temi cardine per il MoVimento 5 Stelle. Confrontarci su questo con i cittadini sar\u00e0 un momento di arricchimento per tutti noi\u201d.<\/em><\/p>\n\n\n\n<p>Cos\u00ec il coordinatore regionale del M5S e candidato alla Camera dei Deputati Leonardo Donno ha presentato il convegno del M5S che si terr\u00e0 marted\u00ec 13 settembre alle 20.00, a Galatone, nel Frantoio Ipogeo in via Castello, intitolato <em>\u201cDalla parte della Legalit\u00e0&#8221;<\/em>, che vedr\u00e0 la presenza dell\u2019ex ministro della Giustizia Alfonso Bonafede, e di Francesco Mandoi (nella foto),  ex Procuratore Aggiunto Nazionale Antimafia e candidato nel collegio uninominale alla Camera dei Deputati.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/09\/11\/francesco-mandoi-a-galatone-martedi-13\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/09\/11\/francesco-mandoi-a-galatone-martedi-13\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.) ______\u00a0 \u201cSar\u00e0 un&#8217;importante occasione per discutere delle riforme del M5S sulla giustizia e per la sicurezza e per parlare del programma che con il Presidente Giuseppe Conte vogliamo mettere in atto per il contrasto alle mafie e per la lotta alla corruzione. Trasparenza, legalit\u00e0, lotta alla mafia sono da sempre temi cardine per il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":204922,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/204919"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=204919"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/204919\/revisions"}],"predecessor-version":[{"id":204923,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/204919\/revisions\/204923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/204922"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=204919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=204919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=204919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}