{"id":20585,"date":"2013-10-10T07:57:12","date_gmt":"2013-10-10T07:57:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20585"},"modified":"2013-10-10T08:00:45","modified_gmt":"2013-10-10T08:00:45","slug":"estimi-condannata-lagenzia-del-territorio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/estimi-condannata-lagenzia-del-territorio\/","title":{"rendered":"ESTIMI CONDANNATA L&#8217;AGENZIA DEL TERRITORIO"},"content":{"rendered":"<p><strong>Estimi, la Commissione Tributaria accoglie altri ricorsi e condanna l\u2019Agenzia del Territorio al pagamento delle spese processuali. <\/strong><\/p>\n<p><strong><em>Per la Commissione: le variazioni catastali imporranno l\u2019aumento della contribuzione fiscale per tutta la vita degli immobili senza tuttavia conoscerne i motivi specifici, n\u00e8<\/em><\/strong> <strong><em>\u00e8 stata raggiunta la perequazione voluta dalla legge.<br \/>\n<\/em><\/strong>Anche la V Sezione della Commissione Tributaria Provinciale di Lecce (Pres. <strong>Lamorgese<\/strong> e Rel. <strong>Cal\u00f2<\/strong>), con due sentenze depositate lo scorso 25 settembre, ha annullato il riclassamento degli estimi catastali operato a Lecce, da parte della Agenzia del Territorio.<\/p>\n<p>Dopo gli annullamenti e le prime sentenze della CTP di Lecce, in particolare della III Sezione, presieduta da <strong>Mario Buffa<\/strong>, anche la Sezione presieduta da Lamorgese ha annullato gli accertamenti degli estimi catastali dell\u2019Agenzia del Territorio di Lecce e condannato, anche in questo caso, l\u2019Agenzia al pagamento delle spese processuali liquidate nell\u2019importo di \u20ac 350,00 per ogni singola causa, oltre agli accessori di legge.<\/p>\n<p>Nelle diffuse motivazioni la Commissione, in accoglimento di tutti i motivi di ricorso proposti dai legali dei ricorrenti, gli <strong>Avv.ti Alfredo Matranga e Marilia Renna<\/strong>, ha censurato l\u2019operato dell\u2019Agenzia del Territorio poich\u00e9, tra l\u2019altro, \u201c<em>in nessuno degli atti presupposti all\u2019avviso impugnato si rinvengono elementi o dati di fatto interessanti gli immobili di propriet\u00e0 del ricorrente, contenendo tali atti, invece, solo affermazioni generali, generiche e non provate, e del tutto estranee agli immobili stessi<\/em>\u201d.<\/p>\n<p>Secondo la Commissione ci\u00f2 ha comportato per il contribuente l\u2019attribuzione ai propri immobili \u2013 senza che a questi sia stata portata modifica o miglioramento alcuno \u2013 di classi di qualit\u00e0 superiore e delle rendite sensibilmente superiori a quelle preesistenti \u2013 variazioni che gli imporranno l\u2019aumento della contribuzione fiscale per tutta la vita degli stessi \u2013 non potendone tuttavia conoscere i motivi specifici.<\/p>\n<p>Ed ancora, per la Commissione Tributaria, la mancanza delle suesposte motivazioni atte a giustificare la maggiore rendita attribuita con l\u2019avviso di accertamento impugnato, induce a ritenere, da un lato, che lo stesso sia carente dei requisiti motivazionali voluti dall\u2019art. 7 dello Statuto del Contribuente e, dall\u2019altro, che non si sia raggiunta la perequazione voluta dalla legge ed inseguita dal Comune di Lecce e dall\u2019Agenzia, ma che addirittura, operando in tal modo, ossia con l\u2019indiscriminata elevazione di una classe per ogni unit\u00e0 immobiliare, si sia ulteriormente ampliato il divario prima esistente fra immobili che, pur ricadendo nella stessa microzona, siano situati in posizione diversa e tali da ricevere, in riflesso al citato diverso contesto urbano e socioeconomico nel quale sono inseriti, un diverso incremento di valore.<\/p>\n<p>Infine, la Commissione ha accolto anche l\u2019ulteriore motivo di ricorso formulato dal ricorrente, ritenendo l\u2019accertamento carente anche del sopralluogo sulle unit\u00e0 immobiliari necessario per stabilire le caratteristiche intrinseche di tali unit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/estimi-condannata-lagenzia-del-territorio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/estimi-condannata-lagenzia-del-territorio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Estimi, la Commissione Tributaria accoglie altri ricorsi e condanna l\u2019Agenzia del Territorio al pagamento delle spese processuali. Per la Commissione: le variazioni catastali imporranno l\u2019aumento della contribuzione fiscale per tutta la vita degli immobili senza tuttavia conoscerne i motivi specifici, n\u00e8 \u00e8 stata raggiunta la perequazione voluta dalla legge. Anche la V Sezione della Commissione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20585"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20585"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20585\/revisions"}],"predecessor-version":[{"id":20587,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20585\/revisions\/20587"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}