{"id":20597,"date":"2013-10-10T08:16:58","date_gmt":"2013-10-10T08:16:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20597"},"modified":"2013-10-10T08:16:58","modified_gmt":"2013-10-10T08:16:58","slug":"7-corso-di-aggiornamento-ambiente-e-salute","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/7-corso-di-aggiornamento-ambiente-e-salute\/","title":{"rendered":"7\u00b0 CORSO DI AGGIORNAMENTO \u201cAMBIENTE E SALUTE\u201d"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/SERRAVEZZA.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/SERRAVEZZA-300x274.jpg\" alt=\"\" width=\"300\" height=\"274\" class=\"alignleft size-medium wp-image-20598\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/SERRAVEZZA-300x274.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/SERRAVEZZA.jpg 302w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Sulla scorta del successo ottenuto dalle precedenti iniziative, la LILT di Lecce terr\u00e0 sabato 12 Ottobre 2013, la settima edizione del Corso di Aggiornamento \u201cAmbiente e Salute\u201d, presso l\u2019Universit\u00e0 del Salento (Centro Ecotekne &#8211; Aula D10 &#8211; Via per Monteroni).<br \/>\nLa manifestazione \u00e8 diretta ad operatori del mondo della scuola, ad educatori e cittadini.<br \/>\nVuole costituire un fattivo contributo alla conoscenza delle tematiche legate alla salvaguardia dell\u2019ambiente ed all\u2019impatto che determinati squilibri possono avere sulla salute di ognuno di noi, potendo causare patologie anche gravi, come i tumori.<br \/>\nL\u2019auspicio che ci proponiamo \u00e8 che, grazie alla nostra iniziativa, si possano acquisire ulteriori strumenti per farsi, ad ogni livello, promotori di salute.<br \/>\nQuest\u2019anno, il Corso vedr\u00e0 la partecipazione di autorevoli esperti, come il\u00a0<strong>Prof. Silvio Garattini, Direttore dell\u2019Istituto \u201cM. Negri\u201ddi Milano e il Prof. Giorgio Assennato, Direttore Generale dell\u2019Agenzia ARPA Puglia.<br \/>\n<\/strong>Il programma dell\u2019evento.<br \/>\n<strong>Ore 9.00 &#8211; Saluto delle Autorit\u00e0 (Prof. Domenico LAFORGIA, Rettore (uscente) Universit\u00e0 del Salento)<\/strong><\/p>\n<p><strong>Ore 9.15 &#8211; LECTIO MAGISTRALIS &#8211;\u00a0<em>Perch\u00e9 \u00e8 difficile curare i tumori\u00a0<\/em>(Prof. Silvio GARATTINI &#8211;\u00a0<em>Direttore Istituto \u201cM. Negri\u201d \u2013 Milano<\/em>)<\/strong><\/p>\n<p>Ore 9.45 &#8211;\u00a0<em>La prevenzione primaria dei tumori e le emissioni industriali<\/em>\u00a0(Prof. Giorgio ASSENNATO<em>\u00a0&#8211; Direttore Generale ARPA Puglia<\/em>)<\/p>\n<p>Ore 10.15\u00a0<em>Sicurezza alimentare : si pu\u00f2 fare a meno dei pesticidi ?<\/em><\/p>\n<p>(Dr. Giovanni MUIA \u2013\u00a0<em>Agronomo,\u00a0<\/em>Dr. Walter INGROSSO &#8211;\u00a0<em>Presidente Cooperativa S. Lorenzo, Leverano<\/em>)<\/p>\n<p>Ore 11.00 &#8211;\u00a0<em>Disconnect, il sapere chiuso nel cassetto\u00a0<\/em>(<strong>Dr. Giuseppe SERRAVEZZA\u00a0<em>&#8211; Presidente LILT &#8211; Sez. Prov. di Lecce<\/em>)<\/strong><\/p>\n<p>Ore 11.30 &#8211;\u00a0<em>La societ\u00e0 paziente\u00a0<\/em>(Dr.ssa Marianna BURLANDO &#8211;\u00a0<em>Psicologa, U.O. Oncologia \u2013 Casarano<\/em>)<\/p>\n<p>Ore 12.00 &#8211;\u00a0<em>Come comunicare la buona scienza nell\u2019epoca di Internet\u00a0<\/em>(<strong>Dr. Giovanni DELLE DONNE \u2013\u00a0<em>Giornalista<\/em>)<\/strong><\/p>\n<p><strong>Ore 12.30 &#8211; Discussione e conclusione<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Dr. Giuseppe Serravezza<\/p>\n<p><em>Presidente LILT \u2013 Sez. Prov. di Lecce<\/em><\/p>\n<p><em>\u00a0<\/em>Lega Italiana per la Lotta contro i Tumori (LILT)<\/p>\n<p>Sezione Provinciale di LECCE<\/p>\n<p>73042 CASARANO (LE) \u2013 Via Alpestre, 4<\/p>\n<p>Tel. e Fax : 0833512777<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/7-corso-di-aggiornamento-ambiente-e-salute\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/7-corso-di-aggiornamento-ambiente-e-salute\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sulla scorta del successo ottenuto dalle precedenti iniziative, la LILT di Lecce terr\u00e0 sabato 12 Ottobre 2013, la settima edizione del Corso di Aggiornamento \u201cAmbiente e Salute\u201d, presso l\u2019Universit\u00e0 del Salento (Centro Ecotekne &#8211; Aula D10 &#8211; Via per Monteroni). La manifestazione \u00e8 diretta ad operatori del mondo della scuola, ad educatori e cittadini. Vuole [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20598,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20597"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20597"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20597\/revisions"}],"predecessor-version":[{"id":20600,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20597\/revisions\/20600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20598"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}