{"id":20627,"date":"2013-10-10T17:12:29","date_gmt":"2013-10-10T17:12:29","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20627"},"modified":"2013-10-10T17:13:50","modified_gmt":"2013-10-10T17:13:50","slug":"lu-paniri-te-site","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/lu-paniri-te-site\/","title":{"rendered":"LU PANIRI TE SITE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><span style=\"color: #c00000;font-family: 'Arial Black';font-size: medium\">La melagrana fa festa nel Salento\u00a0<\/span><span style=\"color: #c00000;font-family: 'Arial Black';font-size: medium\">con \u201cLu paniri te e site\u201d<\/span><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong><span style=\"font-family: Arial;font-size: small\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/MELEGRANA.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/MELEGRANA-300x211.jpg\" alt=\"\" width=\"300\" height=\"211\" class=\"alignleft size-medium wp-image-20628\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/MELEGRANA-300x211.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/MELEGRANA.jpg 401w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>A Palmariggi tre giorni ricchi di colori, sapori, suoni e profumi\u00a0<\/span><\/strong><strong><span style=\"font-family: Arial;font-size: small\">l\u2019invito di Pro_Salento a riscoprire il frutto della salute.<br \/>\n<\/span><\/strong><span style=\"font-family: Arial;font-size: x-small\">Al riaprire della stagione autunnale torna puntuale uno degli appuntamenti pi\u00f9 caratteristici dell&#8217;ottobre salentino, \u201c<strong>Lu Paniri te e Site<\/strong>\u201d, \u00e8 la festa in onore della melagrana (detta \u201csita\u201d, dalla stessa derivazione dal nome greco del grano, \u201csitos\u201d), simbolo di fecondit\u00e0. Tre giorni di festa,\u00a0<strong>dall&#8217;11 al 13 Ottobre<\/strong>, per le strade del piccolo ma accogliente comune di Palmariggi, nel Salento, dedicati alla variet\u00e0 tipica del frutto di questo centro\u00a0<\/span><span style=\"font-family: Arial;font-size: x-small\">idruntino denominata \u201c<em>dente di cavallo a coccio duro<\/em>\u201d.<\/span><br \/>\n<span style=\"font-family: Arial;font-size: x-small\">L\u2019ottimo frutto dai rossi chicchi dolcissimi troneggia nei \u201cpaniri\u201d (cesti di vimini), che gli artigiani del luogo creano lavorando il giunco. Quando la festa si accende le vie del borgo antico di Palmariggi si animano di curiosi che passeggiano qua e l\u00e0 in una particolarissima esplosione di colori, sapori, suoni e profumi. \u201cPaniri te e site\u201d \u00e8 un evento antichissimo che risale a 4 secoli fa; come da tradizione, la domenica mattina si svolge la fiera-mercato e gi\u00e0 all\u2019alba in tutto il centro abitato prendono posizione le numerose bancarelle.<\/span><br \/>\n<span style=\"font-family: Arial;font-size: x-small\">Tante le pietanze, molte a base proprio di melagrana, che saranno a disposizione di tutti i palati, anche dei pi\u00f9 esigenti: dagli antipasti ai primi piatti, dagli arrosti di carne alla porchetta Dop di Ariccia. E poi, ancora, i piatti della tradizione contadina salentina (come\u00a0<em>cicore creste<\/em>,<em>gnummareddrhi, pittule<\/em>, pezzetti di cavallo, \u2026); i dolci tipici e le caldarroste, il tutto accompagnato dall\u2019ottimo Negroamaro.<\/span><br \/>\n<span style=\"font-family: Arial;font-size: x-small\">E la musica? Popolare! Tra pizzica e folk, si alterneranno sul palco nei tre giorni di festa i \u201c<strong>Briganti di Terra d&#8217;Otranto<\/strong>\u201d, i \u201c<strong>Mute Terre<\/strong>\u201d, e gli \u201c<strong>Scianari<\/strong>\u201d.<\/span><br \/>\n<span style=\"font-family: Arial;font-size: x-small\">E\u2019 bene sapere inoltre che si celebrano frutti che, oltre ad essere buonissimi, fanno anche tanto bene alla salute. Conosciute sin da tempi antichi per le loro propriet\u00e0 benefiche, le melegrane (o balauste) hanno infatti propriet\u00e0 astringenti e diuretiche, grazie alla presenza del tannino, e sono ricche di vitamina A e vitamina B, tanto che nell\u2019antica Grecia erano prescritte come antielmintico e antinfiammatorio. Nel succo della melagrana sono presenti potenti agenti antiossidanti che agiscono sullo stato di benessere del nostro organismo ed hanno un ruolo importante nelle molteplici azioni contro diverse patologie. Il melograno \u00e8 inoltre simbolo di fertilit\u00e0, abbondanza e longevit\u00e0.<\/span><br \/>\n<span style=\"font-family: Arial;font-size: x-small\">Una nota di colore, se mai ce ne fosse bisogno, \u00e8 data dall\u2019organizzazione dell\u2019evento che \u00e8 curata dall\u2019omonima Associazione \u201c<strong>Lu paniri te e site<\/strong>\u201d la quale \u00e8 stata costituita appositamente per la manifestazione e non ha scopi di lucro ma devolve gli utili in beneficenza e per servizi utili alla collettivit\u00e0.<\/span><\/p>\n<p><span style=\"font-family: Arial;font-size: x-small\">\u00a0<\/span><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/lu-paniri-te-site\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/10\/lu-paniri-te-site\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La melagrana fa festa nel Salento\u00a0con \u201cLu paniri te e site\u201d A Palmariggi tre giorni ricchi di colori, sapori, suoni e profumi\u00a0l\u2019invito di Pro_Salento a riscoprire il frutto della salute. Al riaprire della stagione autunnale torna puntuale uno degli appuntamenti pi\u00f9 caratteristici dell&#8217;ottobre salentino, \u201cLu Paniri te e Site\u201d, \u00e8 la festa in onore della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20628,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20627"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20627"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20627\/revisions"}],"predecessor-version":[{"id":20630,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20627\/revisions\/20630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20628"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}