{"id":207495,"date":"2022-11-10T16:03:05","date_gmt":"2022-11-10T15:03:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=207495"},"modified":"2022-11-10T17:56:22","modified_gmt":"2022-11-10T16:56:22","slug":"e-giallo-sullomicidio-a-francavilla-fontana-paolo-stasi-avrebbe-aperto-la-porta-al-suo-killer","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/11\/10\/e-giallo-sullomicidio-a-francavilla-fontana-paolo-stasi-avrebbe-aperto-la-porta-al-suo-killer\/","title":{"rendered":"E\u2019 GIALLO SULL\u2019OMICIDIO A FRANCAVILLA FONTANA, PAOLO STASI AVREBBE APERTO LA PORTA AL SUO KILLER"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"574\" height=\"695\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/Immagine-WhatsApp-2022-11-10-ore-16.00.21.jpg\" alt=\"\" class=\"wp-image-207496\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/Immagine-WhatsApp-2022-11-10-ore-16.00.21.jpg 574w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/Immagine-WhatsApp-2022-11-10-ore-16.00.21-248x300.jpg 248w\" sizes=\"(max-width: 574px) 100vw, 574px\" \/><\/figure>\n\n\n\n<p>di <strong>Flora Fina<\/strong>______<\/p>\n\n\n\n<p>Avrebbe spontaneamente aperto la porta al suo killer, Paolo Stasi (nella foto) il giovane ragazzo di 19 anni, freddato a colpi di arma da fuoco nel tardo pomeriggio di &nbsp;ieri a Francavilla Fontana.<\/p>\n\n\n\n<p>A dare prontamente l\u2019allarme sono stati i vicini di casa, che &nbsp;sentendo gli spari hanno immediatamente chiamato i soccorsi e le Forze dell\u2019ordine. Ma per il giovane non c\u2019\u00e8 stato nulla da fare, nonostante l\u2019intervento degli stessi genitori, che subito accorsi sul posto, hanno trasportato il figlio per strada nel tentativo disperato di salvargli la vita.<\/p>\n\n\n\n<p>Dalle prime indagini &#8211; condotte attualmente dai carabinieri&nbsp;della Compagnia di Francavilla Fontana e dal Comando provinciale di Brindisi &#8211; emergono nuovi fondamentali dettagli, uno tra i pi\u00f9 importanti, quello relativo ai due colpi di pistola che lo avrebbero raggiunto mentre il giovane tentava di fuggire dal suo aggressore: un primo colpo infatti lo avrebbe preso di striscio al torace, mentre il secondo, in pieno petto, gli \u00e8 stato fatale.<\/p>\n\n\n\n<p>Non solo: stando alle prime ricostruzioni da parte degli inquirenti, l\u2019assassino, prima di uccidere il ragazzo lasciandolo esanime sulle scale -che dal portone conducevano all\u2019abitazione situata in Via Occhi Bianchi- avrebbe citofonato per farsi aprire dalla vittima.<\/p>\n\n\n\n<p>Tuttavia, sempre dalle indagini tuttora in corso, emerge un dettaglio sconvolgente: del bossolo della pistola a tamburo che l\u2019assassino avrebbe impugnato non v\u2019\u00e8 traccia.<\/p>\n\n\n\n<p>Restano pertanto al vaglio dei militari dell\u2019Arma &#8211; coordinati dal pm di turno Giuseppe De Nozza \u2013 i filmati delle telecamere di videosorveglianza private della zona che fortunatamente sono riuscite ad immortalare la figura di un uomo che nelle ore in cui si \u00e8 consumato l\u2019omicidio, abbandonava a passo sostenuto la zona.<\/p>\n\n\n\n<p>Sempre in queste ore concitate pertanto, \u00e8 compito degli inquirenti cercare di capire se si tratti o meno del killer, procedendo inoltre, anche con l\u2019ascolto di familiari, amici e i vicini di casa.<\/p>\n\n\n\n<p>Il mistero pertanto, continua ad infittirsi, soprattutto in virt\u00f9 del fatto che Paolo fosse un ragazzo per bene, diplomatosi appena l\u2019anno scorso, incensurato e con un contesto familiare dai tratti garbati e tranquilli.<\/p>\n\n\n\n<p>Una certezza tuttavia, da parte degli inquirenti rimane: la tragedia appena consumatasi appare come un vero e proprio agguato, di cui si cerca alacremente movente e assassino, in quella che sembra una vicenda torbida e dal panorama pi\u00f9 che sfocato, e a cui si spera, nei prossimi giorni, di far luce.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/11\/10\/e-giallo-sullomicidio-a-francavilla-fontana-paolo-stasi-avrebbe-aperto-la-porta-al-suo-killer\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/11\/10\/e-giallo-sullomicidio-a-francavilla-fontana-paolo-stasi-avrebbe-aperto-la-porta-al-suo-killer\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Flora Fina______ Avrebbe spontaneamente aperto la porta al suo killer, Paolo Stasi (nella foto) il giovane ragazzo di 19 anni, freddato a colpi di arma da fuoco nel tardo pomeriggio di &nbsp;ieri a Francavilla Fontana. A dare prontamente l\u2019allarme sono stati i vicini di casa, che &nbsp;sentendo gli spari hanno immediatamente chiamato i soccorsi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":207496,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/207495"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=207495"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/207495\/revisions"}],"predecessor-version":[{"id":207499,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/207495\/revisions\/207499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/207496"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=207495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=207495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=207495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}