{"id":20774,"date":"2013-10-17T07:18:25","date_gmt":"2013-10-17T07:18:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20774"},"modified":"2013-10-17T07:19:25","modified_gmt":"2013-10-17T07:19:25","slug":"idrusa-indomita-nella-bonaccia-della-barcolana","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/17\/idrusa-indomita-nella-bonaccia-della-barcolana\/","title":{"rendered":"IDRUSA INDOMITA NELLA BONACCIA DELLA BARCOLANA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/barca.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/barca-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" class=\"alignleft size-medium wp-image-20775\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/barca-300x178.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/barca-1024x607.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/barca.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>E dopo le due regate triestine domenica la partecipazione alla Veleziana\u00a0per concludere il trittico di regate in Nord Adriatico.<br \/>\nL\u2019avventura di Idrusa nell\u2019Adriatico \u00e8 stato anche nel 2013 ricco di successi, soddisfazioni e riconoscimenti. Dal basso all\u2019alto Adriatico l\u2019imbarcazione pugliese ha raccolto vittorie ed ottimi piazzamenti, il suo equipaggio apprezzamenti e considerazione. Il primo posto parziale domenica alla Barcolana davanti ad oltre 1.600 scafi in acqua, prima che l\u2019ennesimo salto di vento tradisse i sogni del team, \u00e8 stato l\u2019ennesimo lampo di luce delle potenzialit\u00e0 tecniche e sportive di questo scafo. Nella bonaccia che ha costretto al ritiro oltre la met\u00e0 dei concorrenti il piazzamento finale al 7\u00b0 posto tra i Maxi rimane infatti onorevole.<\/p>\n<p>Dopo la vittoria in tempo reale alla Brindisi-Corf\u00f9 l\u2019avvicinamento di Idrusa alla Barcolana \u00e8 passato\u00a0 da Ancona dove l\u2019imbarcazione salentina coglie l\u2019ennesimo succeso in acque doriche. Abbinati al team del pluri campione mondiale \u00a0Alberto Rossi\u00a0(al timone con Paolo Montefusco alla tattica)\u00a0e sostenuti dagli sponsor\u00a0Brinmar Shop, Titi Shipping, Audi Domina e Assonautica, gli uomini del Montefusco Sailing Project sono stati sempre al comando vincendo con abbondante margine la classifica assoluta.<\/p>\n<p>La seconda tappa e&#8217; stata in acque istriane, quelle del trofeo Bernetti di Trieste. Iscritta alla regata insieme al team del Sail Academy BMW (con Roberto Ferrarese alla tattica\u00a0e Paolo Montefusco al timone) Idrusa &#8211; BMW nella bonaccia ha difeso un sesto posto di tutto rispetto su 300 barche in competizione.<\/p>\n<p>Si arriva cos\u00ec alla Barcolana dove per il decimo anno \u00e8 confermato il prestigioso abbinamento con Calvi Network in qualit\u00e0 di main sponsor, affiancato dall&#8217; austriaca Bar e Iconsulting insieme con i sostenitori\u00a0brindisini Brinmar Shop, Titi Shipping e Assonautica. La barca e&#8217; preparata con attenzione nell\u2019arco della settimana ricontrollando attrezzature e vele, allenandosi con pioggia e vento, simulazioni di percorso e manovre, ma si sapeva gi\u00e0 che l&#8217;incognita sarebbe stato il vento perch\u00e9 le previsioni per la domenica ripetevano\u00a0 continuamente bonaccia. Anche l&#8217;anno scorso lo scenario era stato simile e le barche grandi come Idrusa non erano state protagoniste.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La determinazione di tutti non subiva flessioni e la speranza di far bene si avvertiva comunque. La regata ha presentato molti rovesci di fronte, tanto da portare Idrusa con una sapiente condotta tattica a superare addirittura il 100 piedi supertecnologico Esimit ed essere prima a meta&#8217; del primo lato grazie a due bordi precisi nel vento a due nodi mentre gli altri erano fermi. Merito anche di uno degli uomini storici del team Giuseppe Maglietta, sempre perfetto in tutte queste regate nel delicatissimo compito di regolatore di vele se consideriamo gli oltre 230 mq della randa.<\/p>\n<p>Poi i continui rimbalzi di leggerissimo vento hanno sfavorito Idrusa, costretta a frenare le ambizioni ed accusare il ritardo che l\u2019ha portata al 19\u00b0 posto assoluto al traguardo su quasi 2.000 imbarcazioni e al 7\u00b0 tra i Maxi.<\/p>\n<p>Regata sempre spettacolare quella di Trieste e partecipata da velisti ma anche da tutta la citt\u00e0 e grande apprezzamento per Idrusa e il Montefusco Sailing Project, che \u00e8 alla decima partecipazione Barcolana come societ\u00e0 armatrice di Maxi. Un dato che esprime tutta la passione, il sacrificio e la dedizione di un team che non molla mai e che \u00e8 tra gli orgogli velici della Puglia.<\/p>\n<p>L\u2019equipaqggio era costituito da Andrea Quartulli, Agostino Marottoli, Obelix\u00a0 Luciano Lippolis, Peppino Dell&#8217;Anna, Corrado Capece, Paolo Bucciarelli, Giuseppe Miglietta, Roberto Ferrarese, Paolo Montefusco, il team Calvi Network, Bar, Brinmar Shop, Assonautica .<\/p>\n<p>Ma neppure il tempo di rifiatare ed il prossimo imminente impegno agonistico \u00e8 gi\u00e0 fissato per domenica a Venezia. Idrusa partecipa alla suggestiva Veleziana, regata tra i canali della citt\u00e0 d\u2019acqua con 200 barche e diversi Maxi. La sfida nella sfida \u00e8 poi nel confronto diretto con il Farr 80 gemello Weddell. Uno stimolo in pi\u00f9 per Idrusa, che ambisce a chiudere in bellezza la stagione tagliando per prima il nastro posto nel Canal Grande sotto piazza S. Marco mentre il team \u00e8 gi\u00e0 pronto a definire il nuovo programma agonistico per il 2014.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/17\/idrusa-indomita-nella-bonaccia-della-barcolana\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/17\/idrusa-indomita-nella-bonaccia-della-barcolana\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>E dopo le due regate triestine domenica la partecipazione alla Veleziana\u00a0per concludere il trittico di regate in Nord Adriatico. L\u2019avventura di Idrusa nell\u2019Adriatico \u00e8 stato anche nel 2013 ricco di successi, soddisfazioni e riconoscimenti. Dal basso all\u2019alto Adriatico l\u2019imbarcazione pugliese ha raccolto vittorie ed ottimi piazzamenti, il suo equipaggio apprezzamenti e considerazione. Il primo posto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20775,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20774"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20774"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20774\/revisions"}],"predecessor-version":[{"id":20777,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20774\/revisions\/20777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20775"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}