{"id":207831,"date":"2022-11-18T12:08:58","date_gmt":"2022-11-18T11:08:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=207831"},"modified":"2022-11-18T12:10:29","modified_gmt":"2022-11-18T11:10:29","slug":"nuovo-sbarco-di-migranti-sulle-nostre-coste-97","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/11\/18\/nuovo-sbarco-di-migranti-sulle-nostre-coste-97\/","title":{"rendered":"NUOVO SBARCO DI MIGRANTI SULLE NOSTRE COSTE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1200\" class=\"wp-image-207832\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/bunaimmi.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/bunaimmi.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/bunaimmi-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/bunaimmi-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/bunaimmi-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/bunaimmi-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/11\/bunaimmi-400x300.jpg 400w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p>(e.l.) ______ L\u2019ultimo, il 30 ottobre scorso a Santa Maria di Leuca..<\/p>\n\n\n\n<p>Sono ripresi gli sbarchi di migranti sulle nostre coste, a parte gli arrivi \u2018organizzati\u2019 dalle organizzazioni non governative a Taranto degli ultimi giorni.<\/p>\n\n\n\n<p>Continua dunque l\u2019emergenza immigrazione incontrollata sull\u2019intero territorio nazionale, mentre l\u2019Unione Europea, malgrado promesse, assicurazioni e trattati carta straccia, continua a lasciare sola l\u2019Italia.<\/p>\n\n\n\n<p>Una questione ritornata prepotentemnte in questi giorni nell&#8217;attualit\u00e0 politica.<\/p>\n\n\n\n<p>Nel Salento,&nbsp;l\u2019 immigrazione irregolare dei, se si pu\u00f2 usare il termine, \u2018privilegiati\u2019: pagano di pi\u00f9, e hanno pi\u00f9 \u2018servizi\u2019, da parte dei trafficanti di esseri umani, partendo a gruppi di piccola o media consistenza dalla Turchia a bordo di velieri.<\/p>\n\n\n\n<p>A Taranto invece approdano gli immigrati che lasciano le coste della Libia \u2013 dove arrivano a piedi da numerosi Stati africani \u2013 sui gommoni messi a disposizione a pagamento da trafficanti di esseri umani senza scrupoli,&nbsp;contando di essere recuperati in mare dalle grossi navi delle organizzazioni non governative che li&nbsp; portano subito dopo in Italia, l\u2019unico paese del Mediterraneo che lo consente, aprendo da anni i propri porti agli sbarchi incontrollati.<\/p>\n\n\n\n<p>Fra l\u2019altro, la Libia continua pericolosamente a essere divisa fra clan rivali, che hanno ripreso una specie di guerra civile strisciante con conseguente instabilit\u00e0 politica per il governo, o, per meglio dire, i governi sul territorio, e difficolt\u00e0 economiche per tutti.<\/p>\n\n\n\n<p>Questa mattina sono arrivate, ancora a Santa Maria di Leuca, altre centodue\u00a0 persone, fra cui donne e bambini, di varia nazionalit\u00e0.<\/p>\n\n\n\n<p>Erano a bordo di una grossa imbarcazione, individuata al largo dai mezzi della Guardia di Finanza e scortata in porto, dove sono scattate poi le consuete operazioni di assistenza della Croce Rossa (nella foto).<\/p>\n\n\n\n<p>Purtroppo per uno di loro, un uomo di 46 anni di nazionalit\u00e0 irachena, il viaggio \u00e8 stato fatale. Dai primi accertamenti effettuati, \u00e8 emerso che la morte \u00e8 stata causata da una crisi ipoglicemica per il diabete di cui egli soffriva.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/11\/18\/nuovo-sbarco-di-migranti-sulle-nostre-coste-97\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/11\/18\/nuovo-sbarco-di-migranti-sulle-nostre-coste-97\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ L\u2019ultimo, il 30 ottobre scorso a Santa Maria di Leuca.. Sono ripresi gli sbarchi di migranti sulle nostre coste, a parte gli arrivi \u2018organizzati\u2019 dalle organizzazioni non governative a Taranto degli ultimi giorni. Continua dunque l\u2019emergenza immigrazione incontrollata sull\u2019intero territorio nazionale, mentre l\u2019Unione Europea, malgrado promesse, assicurazioni e trattati carta straccia, continua a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":207832,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/207831"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=207831"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/207831\/revisions"}],"predecessor-version":[{"id":207835,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/207831\/revisions\/207835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/207832"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=207831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=207831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=207831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}