{"id":20787,"date":"2013-10-18T07:56:53","date_gmt":"2013-10-18T07:56:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20787"},"modified":"2013-10-18T07:56:53","modified_gmt":"2013-10-18T07:56:53","slug":"supermercato-emetteva-gli-scontrini-ma-non-presentava-le-dichiarazioni-fiscali","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/18\/supermercato-emetteva-gli-scontrini-ma-non-presentava-le-dichiarazioni-fiscali\/","title":{"rendered":"SUPERMERCATO EMETTEVA GLI SCONTRINI MA NON PRESENTAVA LE DICHIARAZIONI FISCALI"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><em><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/Foto-3.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/Foto-3-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" class=\"alignleft size-medium wp-image-20788\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/Foto-3-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/Foto-3.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>SOTTRATTI ALL\u2019ERARIO RICAVI PER<\/em><em> UN MILIONE E 400 MILA EURO E I.V.A. PER 200 MILA EURO.<br \/>\n<\/em>La Compagnia della Guardia di Finanza di Gallipoli ha eseguito una verifica fiscale nei confronti di una societ\u00e0 che gestisce 4 supermercati, scoprendo l\u2019omessa dichiarazione di ricavi per circa 1 milione e 400 mila Euro e di I.V.A. per circa 200 mila Euro.<br \/>\nL\u2019attivit\u00e0 ispettiva, che ha interessato l\u2019arco temporale 2007 \u2013 2011, ha fatto emergere che la societ\u00e0, pur emettendo gli scontrini fiscali ai clienti, non ha presentato le dichiarazioni fiscali e, pertanto, non ha pagato le relative imposte.<br \/>\nAnche in questo caso, l\u2019azienda sottoposta a controllo ha assunto la veste di \u201cevasore totale\u201d.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/18\/supermercato-emetteva-gli-scontrini-ma-non-presentava-le-dichiarazioni-fiscali\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/18\/supermercato-emetteva-gli-scontrini-ma-non-presentava-le-dichiarazioni-fiscali\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>SOTTRATTI ALL\u2019ERARIO RICAVI PER UN MILIONE E 400 MILA EURO E I.V.A. PER 200 MILA EURO. La Compagnia della Guardia di Finanza di Gallipoli ha eseguito una verifica fiscale nei confronti di una societ\u00e0 che gestisce 4 supermercati, scoprendo l\u2019omessa dichiarazione di ricavi per circa 1 milione e 400 mila Euro e di I.V.A. per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20788,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20787"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20787"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20787\/revisions"}],"predecessor-version":[{"id":20789,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20787\/revisions\/20789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20788"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}