{"id":208696,"date":"2022-12-10T15:30:00","date_gmt":"2022-12-10T14:30:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=208696"},"modified":"2022-12-10T15:37:36","modified_gmt":"2022-12-10T14:37:36","slug":"finisce-in-carcere-per-violenza-sessuale-in-lavanderia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/12\/10\/finisce-in-carcere-per-violenza-sessuale-in-lavanderia\/","title":{"rendered":"UOMO FINISCE IN CARCERE PER VIOLENZA SESSUALE IN UNA LAVANDERIA DEL CENTRO DI BRINDISI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"275\" height=\"183\" class=\"wp-image-208697\" style=\"width: 600px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/CBR.jpg\" alt=\"\"><\/p>\n\n\n\n<p>(e.l.) ______  Un inquietante episodio di cronaca nera arriva oggi da Brindisi &#8211; reso noto dalla Questura questa mattina a distanza di alcuni giorni dai fatti &#8211; dove gli agenti della Polizia di Stato hanno arrestato un uomo con l&#8217;accusa di violenza sessuale.<\/p>\n\n\n\n<p>Secondo la ricostruzione degli inquirenti, ha aggredito una donna all&#8217;interno di una lavanderia del centro storico, tentando di baciarla e di toccarla, fino a quando lei \u00e8 riuscita a scappare, e poi a fotografare l&#8217;aggressore mentre si allontanava.<\/p>\n\n\n\n<p>E&#8217; stato identificato proprio sulla base di queste foto e arrestato.<\/p>\n\n\n\n<p>Si trova ora nel carcere di Brindisi&nbsp;(nella foto), come disposto dal pm di turno presso la Procura della Repubblica.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/12\/10\/finisce-in-carcere-per-violenza-sessuale-in-lavanderia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/12\/10\/finisce-in-carcere-per-violenza-sessuale-in-lavanderia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Un inquietante episodio di cronaca nera arriva oggi da Brindisi &#8211; reso noto dalla Questura questa mattina a distanza di alcuni giorni dai fatti &#8211; dove gli agenti della Polizia di Stato hanno arrestato un uomo con l&#8217;accusa di violenza sessuale. Secondo la ricostruzione degli inquirenti, ha aggredito una donna all&#8217;interno di una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":208697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/208696"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=208696"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/208696\/revisions"}],"predecessor-version":[{"id":208700,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/208696\/revisions\/208700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/208697"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=208696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=208696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=208696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}