{"id":20910,"date":"2013-10-19T07:33:30","date_gmt":"2013-10-19T07:33:30","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20910"},"modified":"2013-10-19T07:36:53","modified_gmt":"2013-10-19T07:36:53","slug":"lecce-zona-franca","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/19\/lecce-zona-franca\/","title":{"rendered":"LECCE ZONA FRANCA"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/lecce.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/lecce-300x191.jpg\" alt=\"\" width=\"300\" height=\"191\" class=\"alignleft size-medium wp-image-20913\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/lecce-300x191.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/lecce.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Lecce non pu\u00f2 pi\u00f9 attendere. I leccesi dicono basta alle false promesse, ai continui rinvii ed ai rimpalli di competenze tra amministrazione comunale e regione e viceversa. A Lecce deve essere urgentemente costituita la \u201czona franca urbana\u201d e la \u201czona a burocrazia zero\u201d, come ha precisato l\u2019avvocato Maurizio Villani nell\u2019intervista a Report andata in onda luned\u00ec 07 ottobre 2013 su Raitre nella quale la troupe dei giornalisti della trasmissione televisiva, accompagnati in tour dall\u2019avvocato Francesco D\u2019Agata,\u00a0ha potuto constatare visivamente la situazione della periferia leccese nella quale da anni viene promessa l\u2019attuazione della normativa nazionale rilanciata dal recente \u201cDecreto del Fare\u201d.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">L\u2019associazione \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d che con l\u2019avvocato Villani ha riportato a livello nazionale questa scandalosa situazione, ribadisce ancora una volta che \u00e8 un\u2019occasione da non perdere, soprattutto in questo difficile momento di crisi economica e finanziaria.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">E rilancia la proposta di costituire un Comitato professionale per sollecitare l\u2019istituzione a Lecce delle due zone, anche in collaborazione con il Prefetto, entro e non oltre il 31 dicembre di quest\u2019anno.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Giovanni D&#8217;Agata, \u00a0rivolge pertanto un appello alla politica salentina perch\u00e9 si attivi, indipendentemente dalle appartenenze e dai colori politici nel pi\u00f9 breve tempo possibile. Ed in tal senso, \u00e8 pronta una lettera aperta da far sottoscrivere anche tramite email a tutti i cittadini leccesi.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Di seguito, peraltro, riportiamo anche un articolo a firma degli avvocati tributaristi Maurizio Villani e Iolanda Pansardi e pubblichiamo sul sito istituzionale dello \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d la documentazione utile per comprendere l\u2019importanza dell\u2019accelerazione dell\u2019iter burocratico.<\/span><\/p>\n<p><span style=\"color: black;font-family: 'Times New Roman';font-size: small\">\u201cA healthy eye with full visual capacities is of no use in a dead body,\u201d he said.<\/span>Lecce, 17 ottobre 2013<strong>\u00a0\u00a0<em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/em><\/strong><\/p>\n<p><strong><em><span style=\"font-family: 'Times New Roman';font-size: small\">Giovanni D\u2019AGATA<\/span><\/em><\/strong><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">\u00a0<\/span><\/p>\n<p><strong><span style=\"font-family: 'Times New Roman';font-size: small\">Zona a burocrazia zero<\/span><\/strong><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Al fine di snellire l\u2019iter burocratico delle imprese l&#8217;articolo 37 del decreto legge n. 69 del 21 giugno 2013, convertito in legge, con modifiche dall\u2019art. 1, L. 09.08.2013, n. 98\u00a0 propone un rilancio delle forme di semplificazione che, peraltro, non sono nuove nel nostro ordinamento.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Si tratta, in particolare, degli accordi sperimentali tra amministrazioni e associazioni di categoria, introdotti dal Governo Monti con l&#8217;articolo 12 del decreto legge n. 5 del 2012, convertito in legge n. 35 del 2012 (e poi ulteriormente disciplinate con successiva decretazione d&#8217;urgenza), ossia di convenzioni che possono essere stipulate tra le amministrazioni competenti e le varie associazioni di categoria \u00abper attivare percorsi sperimentali di semplificazione amministrativa per gli impianti produttivi e le iniziative e attivit\u00e0 delle imprese sul territorio, in ambiti delimitati e a partecipazione volontaria, anche mediante deroghe alle procedure e ai termini per l&#8217;esercizio delle competenze facenti esclusivamente capo ai soggetti partecipanti, dandone preventiva e adeguata informazione pubblica\u00bb (cos\u00ec la definizione offerta dall&#8217;art. 12, comma 1, del decreto legge n. 5 del 2012).<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Ed infatti, grazie al Governo Letta le zone a burocrazia zero, gi\u00e0 adottate nell\u2019ambito di queste attivit\u00e0 di sperimentazione dal Governo Monti, sono estese a tutto il territorio nazionale.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Sebbene vi sia confusione interpretativa su cosa in realt\u00e0 consistano, si pu\u00f2 evincere dall&#8217;articolo 37-bis, comma 1, del decreto legge n. 179 del 2012 (Governo Monti), convertito dalla legge n. 221 del 2012, che\u201c le zone a burocrazia zero\u201d sono delle zone franche del territorio nazionale le quali sono state espressamente sottratte (addirittura) a ogni \u00abvincolo paesaggistico-territoriale o del patrimonio storico-artistico\u00bb e dove il rilascio delle autorizzazioni sono sostituite da una comunicazione che l&#8217;interessato deposita presso lo sportello unico delle attivit\u00e0 produttive.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">In ogni caso l\u2019obiettivo rimane quello di semplificare, snellire e accelerare le procedure burocratiche per lo start-up d\u2019impresa, al fine di incoraggiare le imprese nel dare impulso allo sviluppo socio- economico del paese.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Peraltro, a complicare le cose, sempre dallo stesso articolo 37 bis, emerge la nozione affine di \u201czona franca urbana\u201d che nello specifico, al comma 3, cos\u00ec recita: &lt;&lt; Per le aree ubicate nelle regioni Abruzzo, Basilicata, Calabria, Campania, Molise, Puglia, Sardegna e Sicilia, ove la zona a burocrazia zero coincida con una delle zone franche urbane di cui all&#8217;articolo 37, le risorse previste per tali zone franche urbane, ai sensi dell&#8217;articolo 1, comma 340, della legge 27 dicembre 2006, n. 296, sono utilizzate dal sindaco territorialmente competente per la concessione di contributi diretti alle nuove iniziative produttive avviate nelle zone a burocrazia zero&gt;&gt;.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Va ricordato che la storia delle zone franche urbane \u00e8 molto complessa. La loro istituzione era stata prevista originariamente con la legge 296\/2006 (Finanziaria 2007), pensata dal governo guidato da Romano Prodi come agevolazione per le nuove iniziative produttive in alcune zone del paese, attraverso l&#8217;esenzione fiscale e contributiva. La realizzazione del progetto si era arenata sul fatto che le agevolazioni previste erano eccessivamente ampie e la copertura prevista sarebbe stata probabilmente insufficiente per tutti i benefici: esenzione da imposte sui redditi, Irap, Ici ed esonero dal versamento dei contributi previdenziali. Perci\u00f2 successivamente la Finanziaria 2007 aveva circoscritto i benefici (anche dal punto di vista territoriale), lasciando a un successivo decreto dell&#8217;Economia il compito di circoscrivere ulteriormente l&#8217;agevolazione.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">La norma, di poi, viene ancora modificata dal comma 4 dell\u2019articolo 9 Dl 194\/2009, convertito dall\u2019articolo 1, comma 1, legge 25\/2010.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">E\u2019 l&#8217;articolo 43 del Dl 78\/2010 (Manovra estiva) a introdurre come misura tesa a rivitalizzare l\u2019economia \u201cla zona a burocrazia zero\u201d.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Ebbene, se pur entrambe le nozioni mirino agli stessi obiettivi, si passa da una misura, le Zone franche urbane, che \u2013 con costi per l\u2019erario \u2013 si caratterizzava per la previsione di misure di fiscalit\u00e0 agevolata, a una misura, le Zone a burocrazia zero, che \u2013 sostanzialmente senza costi per l\u2019erario \u2013 si caratterizza invece per una enunciata semplificazione delle procedure autorizzatorie.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Ci\u00f2 detto, vediamo pur sommariamente di cosa si tratta. Intanto l&#8217;istituzione di tali Zbz spetta al presidente del Consiglio che procede con decreto su proposta del ministro dell&#8217;Economia e delle finanze, di concerto con il ministro dell&#8217;Interno. Nelle zone cos\u00ec individuate, le nuove iniziative produttive godono di una serie di vantaggi il pi\u00f9 rilevante dei quali \u00e8 dato dalla possibilit\u00e0 che i provvedimenti conclusivi dei procedimenti amministrativi di qualsiasi natura e oggetto avviati su istanza di parte sono adottati in via esclusiva da un Commissario di Governo che vi provvede, ove occorrente, previe apposite conferenze di servizi ai sensi della legge 241\/1990. A ci\u00f2 si aggiunge la previsione del silenzio-assenso ove un provvedimento espresso non intervenga entro 30 giorni dall&#8217;avvio del procedimento.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">A riprova dell&#8217;implicita sostituzione delle Zfu con le Zbz, c&#8217;\u00e8 la previsione che le Zbz individuate in Abruzzo, Basilicata, Calabria, Campania, Molise, Puglia, Sardegna e Sicilia, ove coincidenti con una delle Zfu individuate dalla delibera Cipe 14\/2009, nonch\u00e9 in quella dell&#8217;Aquila individuata con deliberazione Cipe del 13 maggio 2010, le risorse previste per tali Zfu, sono utilizzate dal sindaco territorialmente competente per la concessione di contributi diretti alle nuove iniziative produttive avviate nelle zone a burocrazia zero.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Sul punto, peraltro, la Corte costituzionale con sentenza n. 232\/2011 ha statuito l&#8217;illegittimit\u00e0 costituzionale laddove queste semplificazioni coinvolgano procedimenti amministrativi afferenti a materie di competenza regionale concorrente e\/o residuale giacch\u00e8 le zone a burocrazia zero prevedendo l&#8217;adozione di tutti gli atti amministrativi, in modo indifferenziato, da parte di un commissario del Governo, realizzavano cos\u00ec una chiamata in sussidiariet\u00e0 allo Stato delle varie funzioni amministrative di competenza regionale.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Le zone a burocrazia zero reintrodotte invece dal Governo Monti nel 2012, non prevedono pi\u00f9 l&#8217;accentramento di tutte le competenze in capo al commissario di Governo, limitandosi a una semplificazione pi\u00f9 blanda.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Ora le recentissime disposizioni inserite dal decreto legge &#8220;del fare&#8221; mirano all&#8217;estensione a tutto il territorio nazionale di queste sperimentazioni, anche al fine di creare un sistema integrato di dati telematici tra le varie amministrazioni coinvolte e di permetterne un monitoraggio complessivo che \u00e8 affidato al ministero dello sviluppo economico.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Ebbene, a complicare ancor di pi\u00f9 il quadro normativo delineato dall\u2019art. 37 del D.l. 69\/2013, \u00e8 il nuovo comma 3 bis introdotto dalla legge di conversione secondo cui: &lt;&lt; Si intendono non sottoposte a controllo tutte le attivit\u00e0 delle imprese per le quali le competenti pubbliche amministrazioni non ritengano necessarie l&#8217;autorizzazione, la segnalazione certificata di inizio attivit\u00e0, con o senza asseverazioni, ovvero la mera comunicazione\u00bb. Si precisa, poi, che spetter\u00e0 alle pubbliche amministrazioni indicare, sul proprio sito Internet istituzionale, quali attivit\u00e0 imprenditoriali continueranno a essere sottoposte ai controlli. Ed \u00e8 tale potere discrezionale affidato alle amministrazioni ovvero individuare quali attivit\u00e0 saranno soggette al controllo impedendo cos\u00ec un intervento ex lege del controllo, e, vieppi\u00f9, l\u2019assenza di un criterio in base a cui formare \u201cl\u2019elenco apposito\u201d a destare le maggiori perplessit\u00e0. Oltretutto non si comprende in base alla disposizione, di quali controlli si stia parlando laddove si pu\u00f2 pensare unicamente ai controlli che la legge stabilisce per l&#8217;intrapresa dell&#8217;attivit\u00e0, ovvero a quelli che dovrebbero attivarsi in vista del rilascio dell&#8217;autorizzazione o a seguito della ricezione della Scia o della comunicazione; e non anche ai controlli successivi all&#8217;inizio dell&#8217;attivit\u00e0, concernenti i pi\u00f9 svariati aspetti della vita dell&#8217;impresa, da quelli tributari a quelli sanitari, da quelli edilizi a quelli concernenti la tutela dei lavoratori, ecc.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Infine a completamento dell\u2019intreccio di norme di cui sopra previste dal citato art. 37, il comma 5, stabilisce che le uniche limitazioni alle attivit\u00e0 economiche cos\u00ec liberalizzate, consistano nella tutela dei \u00abprincipi fondamentali della Costituzione, la sicurezza, la libert\u00e0 e la dignit\u00e0 dell&#8217;uomo e l&#8217;utilit\u00e0 sociale, il rispetto della salute, dell&#8217;ambiente, del paesaggio e del patrimonio artistico e culturale&gt;&gt;.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Ci si chiede se con tale ultimo paletto si sia riusciti davvero a dare impulso alla semplificazione e se venga concretamente rispettato il concetto di \u201cburocrazia zero\u201d giacch\u00e8 sar\u00e0 davvero arduo non ricondurre ogni scelta imprenditoriale tra i limiti posti a tutela della carta costituzionale.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\"><br \/>\n<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/19\/lecce-zona-franca\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/19\/lecce-zona-franca\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Lecce non pu\u00f2 pi\u00f9 attendere. I leccesi dicono basta alle false promesse, ai continui rinvii ed ai rimpalli di competenze tra amministrazione comunale e regione e viceversa. A Lecce deve essere urgentemente costituita la \u201czona franca urbana\u201d e la \u201czona a burocrazia zero\u201d, come ha precisato l\u2019avvocato Maurizio Villani nell\u2019intervista a Report andata in onda [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20910"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20910"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20910\/revisions"}],"predecessor-version":[{"id":20912,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20910\/revisions\/20912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20913"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}