{"id":20993,"date":"2013-10-21T08:00:44","date_gmt":"2013-10-21T08:00:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20993"},"modified":"2013-10-21T09:27:04","modified_gmt":"2013-10-21T09:27:04","slug":"ruffano-evade-dai-domiciliari-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/21\/ruffano-evade-dai-domiciliari-arrestato\/","title":{"rendered":"RUFFANO. EVADE DAI DOMICILIARI: ARRESTATO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/esplosivo-e-droga-scatta-larresto\/carabinieri-6\/\" rel=\"attachment wp-att-19895\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/carabinieri-150x150.jpg\" alt=\"\" title=\"carabinieri\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-19895\" \/><\/a>A Ruffano invece i militari della locale Stazione CC procedevano all\u2019arresto per il reato di evasione dagli arresti domiciliari nei confronti di D\u2019Amico Mariella cl. 73 di Ruffano, non occupata gi\u00e0 nota alle FF.PP. Nello specifico la D\u2019Amico, gi\u00e0 agli arresti domiciliari da luglio del 2013 poich\u00e9 sorpresa in simili violazione di obblighi nel Comune di Ugento, veniva notata da un militare libero dal servizio all\u2019interno di un supermercato di Ruffano. Il militare consapevole che la D\u2019Amico fosse sottoposta a limitazioni della libert\u00e0 personale ha immediatamente allertato i CC di Ruffano che giunti sul posto hanno constatato come la prevenuta si fosse arbitrariamente allontanata da casa. Ci\u00f2 posto, su disposizione del sostituto PM di turno presso la Procura della Repubblica di Lecce informato dell\u2019accaduto, la stessa veniva riaccompagnata presso la propria abitazione e sottoposta nuovamente al regime degli arresti domiciliari.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/21\/ruffano-evade-dai-domiciliari-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/21\/ruffano-evade-dai-domiciliari-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>A Ruffano invece i militari della locale Stazione CC procedevano all\u2019arresto per il reato di evasione dagli arresti domiciliari nei confronti di D\u2019Amico Mariella cl. 73 di Ruffano, non occupata gi\u00e0 nota alle FF.PP. Nello specifico la D\u2019Amico, gi\u00e0 agli arresti domiciliari da luglio del 2013 poich\u00e9 sorpresa in simili violazione di obblighi nel Comune [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20993"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20993"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20993\/revisions"}],"predecessor-version":[{"id":21002,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20993\/revisions\/21002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19895"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}