{"id":21028,"date":"2013-10-22T08:22:32","date_gmt":"2013-10-22T08:22:32","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21028"},"modified":"2013-10-22T08:27:09","modified_gmt":"2013-10-22T08:27:09","slug":"il-comune-di-lecce-non-risponde-ai-cittadini-intervenga-il-prefetto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/22\/il-comune-di-lecce-non-risponde-ai-cittadini-intervenga-il-prefetto\/","title":{"rendered":"Il Comune di Lecce non risponde ai cittadini. Intervenga il Prefetto"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/22\/il-comune-di-lecce-non-risponde-ai-cittadini-intervenga-il-prefetto\/comune-di-lecce-2\/\" rel=\"attachment wp-att-21029\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/Comune-di-Lecce-150x150.jpg\" alt=\"\" title=\"Comune di Lecce municipio\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-21029\" \/><\/a>Alcuni cittadini hanno segnalato allo \u201cSportello dei Diritti\u201d che il Comune di Lecce nonostante il grande apparato di dipendenti, funzionari e dirigenti non risponderebbe alle istanze in autotutela dei cittadini, legittime o illegittime che siano.<\/p>\n<p>Alcuni casi riguarderebbero l\u2019Ufficio Tributi, certamente uno tra i settori cui i cittadini rivolgono maggiormente le proprie richieste, ma dove purtroppo si assisterebbe ad una scarsa sensibilit\u00e0 nei confronti della cittadinanza dove forse sarebbe maggiormente richiesta, in un momento nel quale tasse e imposte sono uno dei motivi di principale scontro tra cittadino, Stato ed enti. Equitalia docet.<\/p>\n<p>Per Giovanni D&#8217;Agata, presidente dello \u201cSportello dei Diritti\u201d \u00e8 un comportamento che la dice lunga sull\u2019attuale situazione dell\u2019amministrazione del capoluogo salentino ed una tendenza che affonda le radici dietro la difficile e onerosa possibilit\u00e0 di proporre ricorsi giurisdizionali ai silenzi o ai rifiuti delle pubbliche amministrazioni che si fanno forti, coi deboli, e si arroccano dietro queste difficolt\u00e0 e alle farraginosit\u00e0 della macchina burocratica.<\/p>\n<p>Pertanto, stante i sottolineati ostacoli a proporre azioni giurisdizionali a tutela delle ragioni dei cittadini, \u00e8 stato chiesto un intervento del Prefetto nella funzione di massimo rappresentante del Governo nella provincia di Lecce per alcuni casi sottoposti all\u2019attenzione dell\u2019associazione.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/22\/il-comune-di-lecce-non-risponde-ai-cittadini-intervenga-il-prefetto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/22\/il-comune-di-lecce-non-risponde-ai-cittadini-intervenga-il-prefetto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Alcuni cittadini hanno segnalato allo \u201cSportello dei Diritti\u201d che il Comune di Lecce nonostante il grande apparato di dipendenti, funzionari e dirigenti non risponderebbe alle istanze in autotutela dei cittadini, legittime o illegittime che siano. Alcuni casi riguarderebbero l\u2019Ufficio Tributi, certamente uno tra i settori cui i cittadini rivolgono maggiormente le proprie richieste, ma dove [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21028"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21028"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21028\/revisions"}],"predecessor-version":[{"id":21034,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21028\/revisions\/21034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21029"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}