{"id":210513,"date":"2023-01-21T18:20:01","date_gmt":"2023-01-21T17:20:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=210513"},"modified":"2023-01-21T18:32:01","modified_gmt":"2023-01-21T17:32:01","slug":"il-post-partita-di-verona-lecce-gendrey-e-umtiti-ko","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/21\/il-post-partita-di-verona-lecce-gendrey-e-umtiti-ko\/","title":{"rendered":"IL POST PARTITA DI VERONA-LECCE. GENDREY E UMTITI KO"},"content":{"rendered":"\n<p><strong>(m.a.) ______<\/strong><\/p>\n\n\n\n<p>Di seguito i commenti del post partita di <strong>Verona-Lecce<\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"512\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/BAroni-6920e454-7287-4852-9ea0-a7729367ad6c.jpg\" alt=\"\" class=\"wp-image-204761\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/BAroni-6920e454-7287-4852-9ea0-a7729367ad6c.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/BAroni-6920e454-7287-4852-9ea0-a7729367ad6c-300x150.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/BAroni-6920e454-7287-4852-9ea0-a7729367ad6c-768x384.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/09\/BAroni-6920e454-7287-4852-9ea0-a7729367ad6c-600x300.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>MARCO BARONI <\/strong>(allenatore del Lecce, nella foto): <em>&#8220;Nel primo tempo la squadra ha fatto un calcio di personalit\u00e0 e idee. Abbiamo avuto buone opportunit\u00e0 per segnare e abbiamo subito un gol evitabile. Nel secondo tempo i ragazzi non sono andati in confusione, sul 2-0 la gara \u00e8 diventata complessa. Non era facile, loro poi hanno preso dagli episodi maggiore fiducia, hanno fatto un tiro pazzesco con Ilic, mentre noi non abbiamo avuto la giusta determinazione nell&#8217;entrare in area. <\/em><\/p>\n\n\n\n<p><em>Gallo aveva una contusione, mentre Umtiti e Gendrey dobbiamo valutarli. Ceesay? Non l&#8217;ho dimenticato, non \u00e8 stato bene. Abbiamo messo Persson, devo portare tutti alle stesse condizioni. <\/em><\/p>\n\n\n\n<p><em>Bilancio di met\u00e0 stagione? La squadra \u00e8 cresciuta, venire a giocare uno scontro diretto e giocare quel primo tempo mi fa stare tranquillo. Sar\u00e0 un girone di ritorno intenso, ma la squadra \u00e8 pronta&#8221;<\/em>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"237\" height=\"306\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/FEDERICO-DI-FRANCESCO-3.jpg\" alt=\"\" class=\"wp-image-203252\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/FEDERICO-DI-FRANCESCO-3.jpg 237w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/FEDERICO-DI-FRANCESCO-3-232x300.jpg 232w\" sizes=\"(max-width: 237px) 100vw, 237px\" \/><\/figure>\n\n\n\n<p><strong>FEDERICO DI FRANCESCO<\/strong> (esterno offensivo del Lecce, nella foto):<em> &#8220;Ci dispiace per il ko, nel primo tempo potevamo andare in vantaggio. Queste sono gare sporche che si decidono con gli episodi. Non abbiamo mai mollato ma non siamo stati molto lucidi nel cercare di pareggiare.  <\/em><\/p>\n\n\n\n<p><em>Nella seconda frazione di gioco il mister mi ha detto di giocare da terminale offensivo per attaccare la profondit\u00e0 e dare fastidio alla retroguardia avversaria., ma non sono arrivate palle pulite, ma non per colpa dei miei compagni. <\/em><\/p>\n\n\n\n<p><em>Dispiace per i tanti tifosi venuti fin qui, ma ora dobbiamo resettare tutto e pensare alla Salernitana. Sono incidenti di percorso che aiutano a crescere. <\/em><\/p>\n\n\n\n<p><em>Umtiti? Non l&#8217;ho visto, spero non sia nulla di che. Verona? E&#8217; una compagine forte che merita rispetto, ultimamente sta crescendo. Lo scorso anno forse giocavano palla a terra, mentre ora cercano di pi\u00f9 Djuric&#8221;.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>MARCO ZAFFARONI<\/strong> (allenatore del Verona): <em>&#8220;Grande partita, i ragazzi sono stati bravissimi. I giallorossi all&#8217;inizio si sono mostrati in grande condizione, ma abbiamo tenuto e alla fine siamo venuti fuori. Complessivamente abbiamo fatto un&#8217;ottima gara, ora dobbiamo proseguire su questa strada. C&#8217;\u00e8 il potenziale per salvarci<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>UMTITI E GENDREY INFORTUNATI<\/strong><\/p>\n\n\n\n<p>Intanto la societ\u00e0 informa  che la squadra riprender\u00e0 la preparazione  domani mattina all&#8217;<strong>Acaya Golf Resort<\/strong> in vista del confronto casalingo con la <strong>Salernitana<\/strong> il prossimo venerd\u00ec. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"305\" height=\"952\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/gendrey.jpg\" alt=\"\" class=\"wp-image-192247\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/gendrey.jpg 305w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/gendrey-96x300.jpg 96w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/><\/figure>\n\n\n\n<p>Non arrivano, per\u00f2, buone notizie per quanto concerne <strong>Gendrey<\/strong> (nella foto sopra) e <strong>Umtiti<\/strong> (nella foto sotto). I due francesi, infatti, nel corso della gara odierna hanno subito un valido trauma rispettivamente alla spalla sinistra e destra. Da valutare i tempi di recupero.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/umtiti-3-1024x768.jpg\" alt=\"\" class=\"wp-image-204276\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/umtiti-3-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/umtiti-3-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/umtiti-3-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/umtiti-3-1536x1151.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/umtiti-3-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/umtiti-3.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>______<\/strong><\/p>\n\n\n\n<p>LA RICERCA  nel nostro articolo immediatamente precednte<\/p>\n\n\n\n<p><blockquote class=\"wp-embedded-content\" data-secret=\"XtwH5Qeoc2\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/21\/finisce-a-verona-la-serie-positiva-del-lecce\/\">FINISCE A VERONA LA SERIE POSITIVA DEL LECCE<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;FINISCE A VERONA LA SERIE POSITIVA DEL LECCE&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/21\/finisce-a-verona-la-serie-positiva-del-lecce\/embed\/#?secret=YsduZpbbRD#?secret=XtwH5Qeoc2\" data-secret=\"XtwH5Qeoc2\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/21\/il-post-partita-di-verona-lecce-gendrey-e-umtiti-ko\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/21\/il-post-partita-di-verona-lecce-gendrey-e-umtiti-ko\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(m.a.) ______ Di seguito i commenti del post partita di Verona-Lecce: MARCO BARONI (allenatore del Lecce, nella foto): &#8220;Nel primo tempo la squadra ha fatto un calcio di personalit\u00e0 e idee. Abbiamo avuto buone opportunit\u00e0 per segnare e abbiamo subito un gol evitabile. Nel secondo tempo i ragazzi non sono andati in confusione, sul 2-0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":203025,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/210513"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=210513"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/210513\/revisions"}],"predecessor-version":[{"id":210527,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/210513\/revisions\/210527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/203025"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=210513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=210513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=210513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}