{"id":210760,"date":"2023-01-27T15:42:26","date_gmt":"2023-01-27T14:42:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=210760"},"modified":"2023-01-27T15:50:11","modified_gmt":"2023-01-27T14:50:11","slug":"a-leccecronaca-it-lamaro-sfogo-di-un-nostro-lettore-truffato-sul-web-vi-racconto-come-mi-hanno-fregato-i-soldi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/27\/a-leccecronaca-it-lamaro-sfogo-di-un-nostro-lettore-truffato-sul-web-vi-racconto-come-mi-hanno-fregato-i-soldi\/","title":{"rendered":"A leccecronaca.it L&#8217;AMARO SFOGO DI UN LETTORE TRUFFATO SUL WEB: \u201cVi racconto come mi hanno fregato i soldi\u201d"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"600\" class=\"wp-image-210763\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/01\/trent.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/01\/trent.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/01\/trent-300x180.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/01\/trent-768x461.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>(Rdl)\u00a0_______ <em><strong>&#8220;Sembrava tutto regolare: l&#8217;offerta arrivava direttamente dal sito della compagnia con cui avevo gi\u00e0 sottoscritto la medesima assicurazione ormai in scadenza, e mi rimandava ad un numero verde con tanto call center&#8221;. <\/strong><\/em><\/p>\n\n\n\n<p>Inizia cos\u00ec il suo racconto un nostro lettore &#8211; del quale abbiamo verificato l&#8217;identit\u00e0, e la sostanza di quanto ci ha riferito &#8211; il quale dopo aver letto l&#8217;articolo che abbiamo pubblicato qualche giorno fa per denunciare una nuova truffa che sta prendendo piede tra i frequentatori del web, ha deciso di contattarci. <\/p>\n\n\n\n<p><em><strong>&#8220;Conoscevano i miei dati e sapevano il giorno della scadenza della polizza. Ovviamente mi propongono un preventivo conveniente, abbastanza simile al precedente e mi chiedono di effettuare il pagamento su una carta prepagata di cui mi forniscono utente e codice fiscale. <\/strong><\/em><\/p>\n\n\n\n<p><em><strong>Inizialmente ho avuto qualche dubbio, ho richiamato e rifatto la procedura e un altro operatore, questa volta con un numero di cellulare, mi rid\u00e0 gli stessi estremi e lo stesso importo&#8221;.<\/strong><\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p> Sicuramente la pratica di una ricarica su una prepagata Mooney avrebbe dovuto insospettire non poco il malcapitato, ma il sito, i dati a conoscenza dell&#8217;operatore e il numero di WhatsApp con tanto di logo assicurativo avrebbe tratto in inganno chiunque. <\/p>\n\n\n\n<p><em><strong>&#8220;Dopo aver effettuato la ricarica ho sollecitato l&#8217;invio del tagliando, di un eventuale contratto o di un qualcosa che attestasse il mio pagamento. Nulla di nulla. Dopo uno scambio di messaggi il mio numero risultava bloccato. <\/strong><\/em><\/p>\n\n\n\n<p><em><strong>Ho provato a ricontattare con altri numeri nei giorni successivi e il loro numero \u00e8 ancora attivo, funzionante e risponde sempre nello stesso modo, ovvero presentandosi come agenzia assicurativa&#8221;.<\/strong><\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Naturalmente, inutile dire che non esiste nessuna assicurazione, nessun tagliando, nessun contratto. <\/p>\n\n\n\n<p><em><strong>&#8220;Se si prova a chiamare quel numero \u00e8 ancora attivo e disponibile su internet per\u00f2 se si prova ad andare presso un ufficio di polizia postale lo scoraggiamemto ti pervade perch\u00e9 ti rendi conto che questa gente agisce indisturbata in quanto solo tempistiche immediate potrebbero bloccarne l&#8217;agire e salvaguardare altri utenti. Ma tant&#8217;\u00e8&#8230;&#8221;.<\/strong><\/em><\/p>\n\n\n\n<p>Ecco allora che ci ritroviamo a dare voce a questa vicenda per cercare di arginare il fenomeno e infornare ilmaggior numero di persone utenti web sempre possibili prede di truffatori incalliti quanto impuniti.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/27\/a-leccecronaca-it-lamaro-sfogo-di-un-nostro-lettore-truffato-sul-web-vi-racconto-come-mi-hanno-fregato-i-soldi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/27\/a-leccecronaca-it-lamaro-sfogo-di-un-nostro-lettore-truffato-sul-web-vi-racconto-come-mi-hanno-fregato-i-soldi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)\u00a0_______ &#8220;Sembrava tutto regolare: l&#8217;offerta arrivava direttamente dal sito della compagnia con cui avevo gi\u00e0 sottoscritto la medesima assicurazione ormai in scadenza, e mi rimandava ad un numero verde con tanto call center&#8221;. Inizia cos\u00ec il suo racconto un nostro lettore &#8211; del quale abbiamo verificato l&#8217;identit\u00e0, e la sostanza di quanto ci ha riferito [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":210763,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/210760"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=210760"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/210760\/revisions"}],"predecessor-version":[{"id":210765,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/210760\/revisions\/210765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/210763"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=210760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=210760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=210760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}