{"id":211321,"date":"2023-02-08T15:20:00","date_gmt":"2023-02-08T14:20:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=211321"},"modified":"2023-02-08T15:20:02","modified_gmt":"2023-02-08T14:20:02","slug":"grosso-sequestro-di-droga-a-lecce-un-arresto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/08\/grosso-sequestro-di-droga-a-lecce-un-arresto\/","title":{"rendered":"GROSSO SEQUESTRO DI DROGA A LECCE, UN ARRESTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1707\" class=\"wp-image-211322\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/DSC_0461-con-logo-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/DSC_0461-con-logo-scaled.jpg 2560w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/DSC_0461-con-logo-scaled-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/DSC_0461-con-logo-scaled-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/DSC_0461-con-logo-scaled-768x512.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/DSC_0461-con-logo-scaled-1536x1024.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/DSC_0461-con-logo-scaled-2048x1366.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n\n\n\n<p>(e.l.) ______ Ieri sera agenti della Polizia di Stato, in servizio presso la sezione antidroga della Squadra Mobile di Lecce, nell\u2019ambito dei\u00a0 mirati servizi di contrasto al diffuso fenomeno dello spaccio di sostanze stupefacenti nel capoluogo, disposti dal Questore di Lecce, hanno arrestato in flagranza di reato Massimo Malinconico, 40 anni, con precedenti specifci, con l&#8217;accusa di detenzione ai fini di spaccio di sostanze stupefacenti.<\/p>\n\n\n\n<p>Si trova ora nel carcere di Borgo San Nicola, come disposto dall&#8217;autorit\u00e0 giudiziaria.<\/p>\n\n\n\n<p>I poliziotti hanno trovato nel garage della sua abitazione oltre trentadue chili di marijuana, divisi in confezioni riposte in sacchi di platica (nella foto).<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/08\/grosso-sequestro-di-droga-a-lecce-un-arresto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/08\/grosso-sequestro-di-droga-a-lecce-un-arresto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Ieri sera agenti della Polizia di Stato, in servizio presso la sezione antidroga della Squadra Mobile di Lecce, nell\u2019ambito dei\u00a0 mirati servizi di contrasto al diffuso fenomeno dello spaccio di sostanze stupefacenti nel capoluogo, disposti dal Questore di Lecce, hanno arrestato in flagranza di reato Massimo Malinconico, 40 anni, con precedenti specifci, con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":211322,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/211321"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=211321"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/211321\/revisions"}],"predecessor-version":[{"id":211323,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/211321\/revisions\/211323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/211322"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=211321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=211321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=211321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}