{"id":21176,"date":"2013-10-24T08:48:19","date_gmt":"2013-10-24T08:48:19","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21176"},"modified":"2013-10-24T09:00:45","modified_gmt":"2013-10-24T09:00:45","slug":"viola-le-prescrizioni-antistalking-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/24\/viola-le-prescrizioni-antistalking-arrestato\/","title":{"rendered":"VIOLA LE PRESCRIZIONI ANTISTALKING: ARRESTATO"},"content":{"rendered":"<p style=\"text-align: justify;\">Nel pomeriggio di oggi i militari della stazione Carabinieri di Corsano hanno dato esecuzione ad un\u2019ordinanza di custodia cautelare agli arresti domiciliari nei confronti di un uomo classe 1957. L\u2019uomo, disoccupato, gi\u00e0 sottoposto dal 17 agosto 2013 alla misura personale dell\u2019allontanamento dalla casa coniugale, lo scorso 5 ottobre 2013 violando le prescrizioni emesse dal GIP del Tribunale di Lecce ha continuato a molestare ubriaco la moglie sotto casa; la donna rifugiatasi in casa ha subito allertato l\u2019Arma di Corsano e l\u2019uomo in risposta ha danneggiato l\u2019autovettura della donna rompendo un finestrino. Giunti sul posto i Carabinieri hanno raccolta la denuncia della donna e verificato i danni all\u2019auto ed \u00e8 scattata cos\u00ec la denuncia per l\u2019uomo. Il Giudice ravvisando cos\u00ec l\u2019inadeguatezza della prima misura coercitiva ha deciso per l\u2019aggravamento della stessa e cos\u00ec l\u2019uomo \u00e8 stato sottoposto agli arresti domiciliari. Esperite le formalit\u00e0 di rito lo stesso \u00e8 stato messo a disposizione dell\u2019AG mandante.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/24\/viola-le-prescrizioni-antistalking-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/24\/viola-le-prescrizioni-antistalking-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nel pomeriggio di oggi i militari della stazione Carabinieri di Corsano hanno dato esecuzione ad un\u2019ordinanza di custodia cautelare agli arresti domiciliari nei confronti di un uomo classe 1957. L\u2019uomo, disoccupato, gi\u00e0 sottoposto dal 17 agosto 2013 alla misura personale dell\u2019allontanamento dalla casa coniugale, lo scorso 5 ottobre 2013 violando le prescrizioni emesse dal GIP [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21176"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21176"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21176\/revisions"}],"predecessor-version":[{"id":21179,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21176\/revisions\/21179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19895"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}