{"id":211793,"date":"2023-02-17T00:02:00","date_gmt":"2023-02-16T23:02:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=211793"},"modified":"2023-02-17T13:32:21","modified_gmt":"2023-02-17T12:32:21","slug":"novita-editoriali-due-romanzi-mystery","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/17\/novita-editoriali-due-romanzi-mystery\/","title":{"rendered":"NOVITA\u2019 EDITORIALI \/ DUE ROMANZI MYSTERY"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"275\" height=\"183\" class=\"wp-image-211796\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/download-9.jpg\" alt=\"\"><\/p>\n\n\n\n<p>di <strong>Raffaele Polo <\/strong>\u00a0______\u00a0<\/p>\n\n\n\n<p>Sono due libri che, per diversi motivi, trattano argomenti simili e sicuramente piaceranno a tutti coloro che si occupano della letteratura legata al mistero ed ai fantasmi, quella per intenderci in cui furono maestri Lovecraft e Le Fanu. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"1528\" class=\"wp-image-211794\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/signor-morte.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/signor-morte.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/signor-morte-196x300.jpg 196w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/signor-morte-670x1024.jpg 670w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/signor-morte-768x1174.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Stavolta, per\u00f2, non sono solo i nebbiosi paesaggi della Gran Bretagna ad ospitare le inquietanti vicende, che pure in<em><strong> &#8216;Signor Morte&#8217;<\/strong><\/em> di <strong>Graeme Gibson <\/strong>(Besa Muci, 257 pagine, 17 euro) vedono i luoghi tipici fra Toronto e il Canada rurale, fra Londra e le isole Shetland, New York e la Scozia, protagonisti di storie di fantasmi che hanno come nucleo centrale la difficolt\u00e0 di confrontarsi con l\u2019idea della perdita e della mortalit\u00e0. <\/p>\n\n\n\n<p>Un vero e proprio percorso in cui il lettore \u00e8 guidato dalla voce narrante del protagonista, Robert Fraser, il quale nel comporre questo mosaico di storie intreccia il proprio passato al presente, cercando di venire a patti con la morte del fratello e pi\u00f9 in generale con la provvisoriet\u00e0 dell\u2019esistenza. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"1502\" class=\"wp-image-211795\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/case-infestate.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/case-infestate.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/case-infestate-200x300.jpg 200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/case-infestate-682x1024.jpg 682w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/case-infestate-768x1154.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p>In &#8216;Spiriti inquilini\/Le case &#8216;infestate&#8217; fra palcoscenici e tribunali&#8217;a cura di Gabriele Mina&#8217; (Besa Muci, 168 pagine, 15 euro) invece l&#8217;ambientazione ci \u00e8 molto vicina: nel 1907 la Pretura di Napoli si occupa di una risoluzione di contratto d\u2019affitto. Nulla di strano, se non che l\u2019inquilina, la Duchessa di Castelpoto, non intende pagare la proprietaria, la baronessa Englen, a causa delle inquietanti manifestazioni medianiche insediate nella casa. Sulla natura di questi spiriti molesti e sui diritti degli inquilini disserta il difensore della duchessa, l\u2019avvocato Francesco Zingaropoli. <\/p>\n\n\n\n<p>Ai brani pi\u00f9 felici delle <em>Case infestate dagli spiriti <\/em>di Zingaropoli (1917) si affiancano le note sulle case fantomatiche di Cesare Lombroso, il celebre autore di <em>Delitto, genio e follia<\/em>, alle prese con un\u2019osteria infestata di Torino. Una straordinaria pagina di costume \u201cpre-Eduardo\u201d, di una societ\u00e0 divisa fra sedute spiritiche, spettacoli medianici, tribunali.<\/p>\n\n\n\n<p>A corredo una serie di contributi, curati da diversi ricercatori, che rileggono i motivi della casa perturbante alla luce dei campi pi\u00f9 differenti: il diritto nelle case infestate, la stagione dell\u2019occulto psichico, i fantasmi teatrali, le architetture cinematografiche.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/17\/novita-editoriali-due-romanzi-mystery\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/17\/novita-editoriali-due-romanzi-mystery\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo \u00a0______\u00a0 Sono due libri che, per diversi motivi, trattano argomenti simili e sicuramente piaceranno a tutti coloro che si occupano della letteratura legata al mistero ed ai fantasmi, quella per intenderci in cui furono maestri Lovecraft e Le Fanu. Stavolta, per\u00f2, non sono solo i nebbiosi paesaggi della Gran Bretagna ad ospitare [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":211796,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/211793"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=211793"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/211793\/revisions"}],"predecessor-version":[{"id":211797,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/211793\/revisions\/211797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/211796"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=211793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=211793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=211793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}