{"id":212111,"date":"2023-02-24T15:56:22","date_gmt":"2023-02-24T14:56:22","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=212111"},"modified":"2023-02-24T16:17:30","modified_gmt":"2023-02-24T15:17:30","slug":"boni-state-boni-addio-a-maurizio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/24\/boni-state-boni-addio-a-maurizio\/","title":{"rendered":"\u201cBoni, state boni!\u201d&#8230; ADDIO A MAURIZIO COSTANZO \u00a0"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"311\" height=\"162\" class=\"wp-image-212112\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/MCTORTA.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/MCTORTA.jpg 311w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/MCTORTA-300x156.jpg 300w\" sizes=\"(max-width: 311px) 100vw, 311px\" \/><\/p>\n\n\n\n<p>di <strong>Raffaele Polo<\/strong> ______&nbsp;&nbsp;La morte, questa mattina a Roma in una clinica privata, dove era ricoverato da una settimana per diabete. Aveva 85 anni.<\/p>\n\n\n\n<p>Nel bene e nel male, Maurizio Costanzo \u00e8 stato sempre presente nel mondo della cultura e dello spettacolo. Nel suo prodigarsi in ogni settore, ha lasciato tangibili impronte e, si pu\u00f2 affermare con sicurezza, ha &#8216;inventato&#8217; un modo di fare televisione che, in Italia, non si era mai visto. Coinvolgendo attori e personaggi del momento, portandoli alla ribalta e gestendoli con la sua tradizionale ironia e raggiungendo il risultato pi\u00f9 ricercato dello spettacolo: ovvero la rappresentazione a &#8216;costo zero&#8217; che fa leva su quello che si dice e non sui lustrini, sulle ballerine e sugli addobbi&#8230; <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Oddio, con le Tv di Berlusconi, Costanzo e la sua socia e compagna Maria De Filippi, hanno imposto un modo di gestire il piccolo schermo che si \u00e8 rivelato fondamentale e che caratterizza, ormai, la nostra societ\u00e0, sempre pi\u00f9 vicina a quell&#8217; \u201caltro visto da s\u00e8\u201d che il sociologo Baudrillard ha analizzato e vivisezionato.<\/p>\n\n\n\n<p>Ma poi si scopre che sceneggiature televisive e cinematografiche, editoria e mondo della musica lo vedono protagonista con grandi successi e intuizioni geniali. Per esemplificare, \u00e8 lui che &#8216;inventa&#8217; il personaggio del presentatore che Paolo Villaggio porta sugli schermi, \u00e8 lui che regala a Mina il successo di &#8216;Se telefonando&#8217;, con musica di Ennio Morricone, \u00e8 lui sempre presente in quel ramo dell&#8217;editoria sempre pi\u00f9 frequentato che ci parla degli avvenimenti del momento, del sesso psicanalizzato nella nostra societ\u00e0, della poltica imcomprensibile, ma artefice di modelli che vanno interpretati e spiegati.<\/p>\n\n\n\n<p>Costanzo, insomma, c&#8217;\u00e8 sempre. E, anche quando non appare fisicamente, la sua mano, il suo pensiero cos\u00ec chiaramente legato allo &#8216;spettacolo&#8217;, finisce per coinvogerci e stupirci.<\/p>\n\n\n\n<p>Anche politicamente, Costanzo \u00e8 presente prima a sinistra, poi con l&#8217;attribuita partecipazione al clan di Licio Gelli, vittima di un agguato mafioso e infine deus ex machina di Berlusconi. Non manca nulla, insomma: e il suo faccione ilare e sogghignante \u00e8 una costante garanzia di quel successo che lo accompagna fino all&#8217;ultimo.<\/p>\n\n\n\n<p>Ecco, un ricordo particolare di Maurizio ce lo abbiamo: fu quando, mentre colloquiava con un Pannella giovanissimo, fu investito da una torta in faccia (nella foto)&nbsp;che Marina Ripa di Meana pens\u00f2 bene di appioppargli. La sua reazione fu veramente encomiabile: con perfetto aplomb non si scompose ma apostrof\u00f2 benevolmente la &#8216;duchessa&#8217;, rimproverandosi di averla invitata&#8230;<\/p>\n\n\n\n<p>Era cos\u00ec, Maurizio Costanzo: un intellettuale raffinato e completo che non esitava ad autoironizzare su s\u00e9 stesso e sul pubblico, con la sua frase pronunciata con accento romanesco che ci invitava a &#8216;stare boni&#8217;.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/24\/boni-state-boni-addio-a-maurizio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/24\/boni-state-boni-addio-a-maurizio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo ______&nbsp;&nbsp;La morte, questa mattina a Roma in una clinica privata, dove era ricoverato da una settimana per diabete. Aveva 85 anni. Nel bene e nel male, Maurizio Costanzo \u00e8 stato sempre presente nel mondo della cultura e dello spettacolo. Nel suo prodigarsi in ogni settore, ha lasciato tangibili impronte e, si pu\u00f2 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":212112,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212111"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=212111"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212111\/revisions"}],"predecessor-version":[{"id":212118,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212111\/revisions\/212118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/212112"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=212111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=212111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=212111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}