{"id":212148,"date":"2023-02-25T14:40:00","date_gmt":"2023-02-25T13:40:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=212148"},"modified":"2023-02-25T16:39:20","modified_gmt":"2023-02-25T15:39:20","slug":"immunita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/25\/immunita\/","title":{"rendered":"\u00a0\u201d25\/02\/2023, 55 ricoverati in oncologia pediatrica a Taranto\u201d. MANIFESTAZIONE QUESTA MATTINA DELLE ASSOCIAZIONI CHE CHIEDONO LA REVOCA DELL&#8217;IMMUNITA&#8217; PENALE CONCESSA DAL GOVERNO AI PADRONI DEL MOSTRO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1080\" height=\"810\" class=\"wp-image-212165\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNAQUATTRO-BUNA.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNAQUATTRO-BUNA.jpg 1080w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNAQUATTRO-BUNA-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNAQUATTRO-BUNA-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNAQUATTRO-BUNA-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNAQUATTRO-BUNA-400x300.jpg 400w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n\n\n\n<p>(g.p.) ______  S\u00ec, siamo con i Genitori Tarantini, lasciati soli alle loro sofferenze da una Politica che, pur cambiando vari governi, in realt\u00e0 non ha cambiato nulla, del suo asservimento alle logiche dei veri padroni economici, delle loro occulte strategie finanziarie senza confini, delle multinazionali del profitto a tutti i costi.<\/p>\n\n\n\n<p>E s\u00ec, ora pi\u00f9 di prima, chiudere l&#8217;Ilva, subito, senza se e senza ma.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Manifestazione questa mattina a Taranto indetta da numerose associazioni per chiedere l&#8217; abrogazione dell&#8217;immunit\u00e0 penale per chi inquina ribadita di recente dall&#8217;attuale governo, pur a fronte dell&#8217;<\/p>\n\n\n\n<p><em> \u201daumento  delle malattie e dei tumori nella nostra citt\u00e0. Quante altre morti dobbiamo piangere, per comprendere che l&#8217;acciaio green \u00e8 una favola? Basta con le promesse dei governi che si sono succeduti in questi venti anni\u201d.<\/em><\/p>\n\n\n\n<p>Luned\u00ec il nuovo decreto del nuovo governo dovrebbe essere licenziato in via definitiva dal Parlamento<strong>:<\/strong> gi\u00e0 approvato dal Senato, \u00e8 ora all&#8217;approvazione della Camera per la definitiva ratifica. Poi rimane solo la spetranza che ilpresidente della Repubblica Sergio Mattarella si rifiuti di firmarlo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Qui di seguito <strong>alcune altre voci dalla manifestazione<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>&nbsp;\u201d<\/strong>Ogni santa mattina, due\/tre tarantini si svegliano per andare a fare le analisi e scoprono di avere un tumore, ogni santo giorno, giorno dopo giorno, due\/tre tarantini comunicano ai loro cari che sono malati. Taranto definita dall&#8217;ONU zona di sacrificio, di genocidio, condannato si, ma impunito e soprattutto inarrestabile a quanto pare. <\/p>\n\n\n\n<p>Il cancro peggiore, poi, \u00e8 quello della rassegnazione della maggioranza dei cittadini, dell&#8217;assuefazione ad una condizione che di normale non ha niente. <\/p>\n\n\n\n<p>Oggi, alla manifestazione contro lo scudo penale, ho incontrato tanti volti amici, ma ho incontrato anche tanto dolore e, scusate se sono impopolare, quel dolore lo voglio conservare, non lo voglio dimenticare, perch\u00e9 in nome di quel dolore, per rispetto a quel dolore, continuer\u00f2 a presenziare in silenzio e a manifestare il mio dissenso a farmi ammazzare per ragion di stato<strong>\u201d<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"555\" height=\"710\" class=\"wp-image-212166\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNADUE.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNADUE.jpg 555w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/02\/BUNADUE-235x300.jpg 235w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/> <\/p>\n\n\n\n<p><strong><em>25\/02\/2023, 55 ricoverati in oncologia pediatrica a Taranto.<\/em><\/strong><\/p>\n\n\n\n<p><em><strong>Il resto \u00e8 fuffa.<\/strong><\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A sorpresa, era presente anche <mark style=\"background-color:rgba(0, 0, 0, 0);color:#cd3030\" class=\"has-inline-color\"><strong>Romina Powe<\/strong>r<\/mark><strong>:<\/strong>  <mark style=\"background-color:rgba(0, 0, 0, 0);color:#d12e2e\" class=\"has-inline-color\">qui di seguito una sintesi dei concetti che ha espresso.<\/mark><\/p>\n\n\n\n<p>&#8220;L&#8217;unica misura urgente di interesse \u00e8 la salute, quella dei nostri figli e quella del nostro ambiente e non dei loro impianti.<\/p>\n\n\n\n<p>Sono qui anche come una madre che ha perso le tracce della sua primogenita ben 29 anni fa per cause ignote. La morte dei giovani e del nostro futuro sono invece i fumi e le polveri cancerogene emesse dall&#8217;ex Ilva e da altri impianti industriali qui a Taranto. <\/p>\n\n\n\n<p>Sono qui per dirvi che \u00e8 un vostro diritto vivere, \u00e8 un nostro diritto inviolabile, \u00e8 scritto nella Costituzione italiana e nessun altro decreto potr\u00e0 toglierci questo nostro diritto. <\/p>\n\n\n\n<p>La Corte europea dei diritti dell&#8217;uomo \u00e8 tornata a pronunciarsi sulla situazione relativa all&#8217;inquinamento causata dall&#8217;attivit\u00e0 industriale del sito ex Ilva di Taranto, condannando l&#8217;Italia.<br>E&#8217; veramente vergognoso quello che sta accadendo. Io amo l&#8217;Italia, amo la Puglia, l&#8217;ho scelta come casa negli anni Sessanta e l&#8217;ho riscelta nel 2020. Bisogna far crescere la consapevolezza di questo enorme pericolo e il lento suicidio che potrebbe accadere con la produzione delle acciaierie senza i dovuti accorgimenti ecologici. La vita \u00e8 un nostro diritto inviolabile e noi siamo dei custodi di questa terra, siamo dei custodi temporanei di questo pianeta e quindi difendiamolo. Riconosciamo i nostri diritti e non abbiate paura di difenderli&#8221;. ______ <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>L&#8217;APPROFONDIMENTO nei nostri articoli del 29 dicenbre 2022, e del  6 gennaio e 1 febbraio scorsi<\/p>\n\n\n\n<p><blockquote class=\"wp-embedded-content\" data-secret=\"uwWiD2l95Q\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/12\/29\/come-matteo-renzi-anche-giorgia-meloni-fa-il-suo-bravo-decreto-salva-ilva-anzi-fa-anche-meglio-cioe-peggio-di-lui-sul-piano-penale-e-poi-regala-altri-680-milioni-di-euro-alla-multinazionale-i\/\">COME MATTEO RENZI, ANCHE GIORGIA MELONI FA IL SUO BRAVO DECRETO SALVA ILVA, ANZI FA ANCHE MEGLIO &#8211; CIOE&#8217; PEGGIO &#8211; DI LUI SUL PIANO DI IMMUNITA&#8217; PENALE, E POI REGALA ALTRI 680 MILIONI DI EURO ALLA MULTINAZIONALE INDIANA, MENTRE IL MOSTRO CONTINUA AD AVVEENARE E AD UCCIDERE TARANTO<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;COME MATTEO RENZI, ANCHE GIORGIA MELONI FA IL SUO BRAVO DECRETO SALVA ILVA, ANZI FA ANCHE MEGLIO &#8211; CIOE&#8217; PEGGIO &#8211; DI LUI SUL PIANO DI IMMUNITA&#8217; PENALE, E POI REGALA ALTRI 680 MILIONI DI EURO ALLA MULTINAZIONALE INDIANA, MENTRE IL MOSTRO CONTINUA AD AVVEENARE E AD UCCIDERE TARANTO&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/12\/29\/come-matteo-renzi-anche-giorgia-meloni-fa-il-suo-bravo-decreto-salva-ilva-anzi-fa-anche-meglio-cioe-peggio-di-lui-sul-piano-penale-e-poi-regala-altri-680-milioni-di-euro-alla-multinazionale-i\/embed\/#?secret=VRBeNrIvbG#?secret=uwWiD2l95Q\" data-secret=\"uwWiD2l95Q\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p><blockquote class=\"wp-embedded-content\" data-secret=\"SbJtXc63B4\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/06\/il-mostro-continua-ad-avvelenare-e-uccidere-altro-che-immunita-penale-tutto-lacciaio-del-mondo-non-vale-la-vita-di-un-solo-bambino\/\">IL MOSTRO CONTINUA AD AVVELENARE E UCCIDERE. ALTRO CHE IMMUNITA&#8217; PENALE!<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;IL MOSTRO CONTINUA AD AVVELENARE E UCCIDERE. ALTRO CHE IMMUNITA&#8217; PENALE!&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/06\/il-mostro-continua-ad-avvelenare-e-uccidere-altro-che-immunita-penale-tutto-lacciaio-del-mondo-non-vale-la-vita-di-un-solo-bambino\/embed\/#?secret=2XZasl4WyS#?secret=SbJtXc63B4\" data-secret=\"SbJtXc63B4\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p><blockquote class=\"wp-embedded-content\" data-secret=\"Wqke3JUGpX\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/01\/il-mostro-lavvelenamento-continua\/\">IL MOSTRO, L&#8217;AVVELENAMENTO CONTINUA<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;IL MOSTRO, L&#8217;AVVELENAMENTO CONTINUA&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/01\/il-mostro-lavvelenamento-continua\/embed\/#?secret=beBJ5vQPS1#?secret=Wqke3JUGpX\" data-secret=\"Wqke3JUGpX\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/25\/immunita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/02\/25\/immunita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.) ______ S\u00ec, siamo con i Genitori Tarantini, lasciati soli alle loro sofferenze da una Politica che, pur cambiando vari governi, in realt\u00e0 non ha cambiato nulla, del suo asservimento alle logiche dei veri padroni economici, delle loro occulte strategie finanziarie senza confini, delle multinazionali del profitto a tutti i costi. E s\u00ec, ora pi\u00f9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":212165,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212148"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=212148"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212148\/revisions"}],"predecessor-version":[{"id":212178,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212148\/revisions\/212178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/212165"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=212148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=212148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=212148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}