{"id":212831,"date":"2023-03-12T15:33:50","date_gmt":"2023-03-12T14:33:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=212831"},"modified":"2023-03-12T15:35:08","modified_gmt":"2023-03-12T14:35:08","slug":"le-tematiche-del-m5s-in-convegno-ad-aradeo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/12\/le-tematiche-del-m5s-in-convegno-ad-aradeo\/","title":{"rendered":"LE TEMATICHE DEL M5S IN CONVEGNO AD ARADEO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"900\" class=\"wp-image-212832\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/325969ce-7ffe-4fdb-99f8-f138c5b9a1bf.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/325969ce-7ffe-4fdb-99f8-f138c5b9a1bf.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/325969ce-7ffe-4fdb-99f8-f138c5b9a1bf-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/325969ce-7ffe-4fdb-99f8-f138c5b9a1bf-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/325969ce-7ffe-4fdb-99f8-f138c5b9a1bf-768x432.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/325969ce-7ffe-4fdb-99f8-f138c5b9a1bf-1536x864.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p>Dal Movimento 5 Stelle riveviamo e volentieri pubblichiamo ______\u00a0<\/p>\n\n\n\n<p>Si \u00e8 svolto nel pomeriggio di sabato 11 marzo ad Aradeo (LE) il convegno \u201cDalla parte dello Stato\u201d organizzato dal Movimento Cinque Stelle. <\/p>\n\n\n\n<p>All\u2019evento, che ha avuto come obiettivo quello di affrontare i temi che in questi anni hanno caratterizzato l\u2019azione del M5S all\u2019interno delle istituzioni, sono intervenuti anche Federico Cafiero De Raho, deputato M5S, vicepresidente commissione Giustizia e gi\u00e0 Procuratore nazionale antimafia, Alfonso Colucci, deputato M5S e capogruppo commissione Affari costituzionali alla Camera dei deputati, Leonardo Donno, deputato e coordinatore regionale M5S Puglia, Cristian Casili vicepresidente del Consiglio regionale Puglia. <\/p>\n\n\n\n<p>\u201cUn momento molto importante per il territorio in cui sono stati affrontati diversi temi che oggi\u00a0sono quantomai centrali nella vita politica e culturale del nostro Paese\u201d ha detto Leonardo Donno. \u201cDalla legalit\u00e0 alla giustizia, la lotta alle mafie, l\u2019etica pubblica, \u00e8 stato un percorso che grazie agli interventi che si sono succeduti, ha dato modo di approfondire i tanti aspetti che caratterizzano l\u2019azione e le responsabilit\u00e0 dello Stato e delle istituzioni. \u00c8 importante che questi temi vengano affrontati anche all\u2019interno delle comunit\u00e0 perch\u00e9 centrali nella vita quotidiana dei cittadini. Con il convegno abbiamo voluto anche manifestare il nostro sostegno a tutti quei rappresentanti delle istituzioni, cittadini e associazioni che ogni giorno, svolgendo il proprio ruolo con onest\u00e0 e coraggio, sono un presidio di legalit\u00e0 per il territorio&#8221;. <\/p>\n\n\n\n<p>Al convegno hanno partecipato anche Don Antonio Coluccia, prete antimafia fondatore di Opera Don Giustino Onlus, il sindaco di Aradeo Giovanni Mauro, il consigliere comunale M5S Antonio Tramacere. A coordinare i lavori Iunio Valerio Romano, coordinatore provinciale M5S Lecce e gi\u00e0 senatore.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/12\/le-tematiche-del-m5s-in-convegno-ad-aradeo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/12\/le-tematiche-del-m5s-in-convegno-ad-aradeo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dal Movimento 5 Stelle riveviamo e volentieri pubblichiamo ______\u00a0 Si \u00e8 svolto nel pomeriggio di sabato 11 marzo ad Aradeo (LE) il convegno \u201cDalla parte dello Stato\u201d organizzato dal Movimento Cinque Stelle. All\u2019evento, che ha avuto come obiettivo quello di affrontare i temi che in questi anni hanno caratterizzato l\u2019azione del M5S all\u2019interno delle istituzioni, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":212832,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212831"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=212831"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212831\/revisions"}],"predecessor-version":[{"id":212833,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/212831\/revisions\/212833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/212832"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=212831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=212831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=212831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}