{"id":213175,"date":"2023-03-20T10:42:08","date_gmt":"2023-03-20T09:42:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=213175"},"modified":"2023-03-20T16:42:04","modified_gmt":"2023-03-20T15:42:04","slug":"esplode-falo-abusivo-acceso-a-taranto-per-san-giseppe-venti-feriti-attimi-di-terroretanta-paura","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/20\/esplode-falo-abusivo-acceso-a-taranto-per-san-giseppe-venti-feriti-attimi-di-terroretanta-paura\/","title":{"rendered":"ESPLODE FALO&#8217; ABUSIVO ACCESO A TARANTO PER SAN GIUSEPPE. 20 FERITI, ATTIMI DI TERRORE, TANTA PAURA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" class=\"wp-image-213176\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/fta.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/fta.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/fta-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/fta-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/fta-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>(e.l.) ______  Festa col botto. Un fal\u00f2 abusivo acceso per strada per &#8216;festeggiare&#8217; San Giuseppe ieri sera a Taranto, in via Grazia Deledda, al quartiere Tamburi, all&#8217;improvviso \u00e8 esploso, verosimilmente per la presenza, nei rifiuti accatastati da irresponsabili per essere bruciati, di materiale pericoloso, surriscaldato dalle fiamme.<\/p>\n\n\n\n<p>Ci sono stati attimi di vero terrore, fra urla e lamenti.<\/p>\n\n\n\n<p>Il bilancio \u00e8 di una ventina di feriti, fra cui ragazzi e bambini, per lo pi\u00f9 in maniera non grave, tre dei quali pi\u00f9 seria, portati in ambulanza all&#8217;ospedale Santissima Annunziata. Sono stati colpiti dai frammenti del materiale scagliato dalla violenza dell&#8217;esplosione tutto intorno, dove erano in molti ad assistere allo &#8216;spettacolo&#8217;. <\/p>\n\n\n\n<p>Il pronto soccorso \u00e8 rimasto a lungo intasatio, anche per la presenza dei parenti dei feriti. <\/p>\n\n\n\n<p>Il ferito pi\u00f9 grave \u00e8 stato dimesso questa mattina con una prognosi di quindici giorni.<\/p>\n\n\n\n<p>Danni anche ad alcuni vetri delle abitazioni pi\u00f9 vicine,<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Erano giorni che l&#8217; &#8216;evento&#8217; era in preparazione, ed \u00e8 stato persegito nonostante la Polizia Locale avesse tentato in qualche modo di scoraggiarne la preparazione.<\/p>\n\n\n\n<p>Adesso la Polizia di Stato sta indagando per stabilire le cause di quanto successo ed individuarne le responsabilit\u00e0.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"500\" height=\"261\" class=\"wp-image-213177\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/ft.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/ft.jpg 500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/ft-300x157.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/20\/esplode-falo-abusivo-acceso-a-taranto-per-san-giseppe-venti-feriti-attimi-di-terroretanta-paura\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/20\/esplode-falo-abusivo-acceso-a-taranto-per-san-giseppe-venti-feriti-attimi-di-terroretanta-paura\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Festa col botto. Un fal\u00f2 abusivo acceso per strada per &#8216;festeggiare&#8217; San Giuseppe ieri sera a Taranto, in via Grazia Deledda, al quartiere Tamburi, all&#8217;improvviso \u00e8 esploso, verosimilmente per la presenza, nei rifiuti accatastati da irresponsabili per essere bruciati, di materiale pericoloso, surriscaldato dalle fiamme. Ci sono stati attimi di vero terrore, fra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":213176,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213175"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=213175"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213175\/revisions"}],"predecessor-version":[{"id":213219,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213175\/revisions\/213219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/213176"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=213175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=213175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=213175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}