{"id":213181,"date":"2023-03-20T00:03:00","date_gmt":"2023-03-19T23:03:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=213181"},"modified":"2023-03-22T15:42:08","modified_gmt":"2023-03-22T14:42:08","slug":"libri-nuova-edizione-per-le-poesie-di-bruce-hunter","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/20\/libri-nuova-edizione-per-le-poesie-di-bruce-hunter\/","title":{"rendered":"LIBRI \/ NUOVA EDIZIONE PER LE POESIE DI BRUCE HUNTER \u00a0"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"500\" height=\"775\" class=\"wp-image-213183\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/bh.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/bh.jpg 500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/bh-194x300.jpg 194w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n\n\n\n<p>(Rdl)\u00a0_______ Continua la tradizione editoriale de I Quaderni del Bardo Edizioni di Stefano Donno, rivolta al mondo della poesia internazionale. La nuova pubblicazione riguarda l&#8217;ultima opera del poeta canadese <strong>Bruce Hunter<\/strong> (nella foto) intitolata \u201cGalestro<em>\u201d<\/em>. <\/p>\n\n\n\n<p>A distanza di soli due mesi dalla prima edizione  ne arriva adesso una nuova. _______<\/p>\n\n\n\n<p>_______<\/p>\n\n\n\n<p>Per acquistare il libro<\/p>\n\n\n\n<p><a href=\"https:\/\/iquadernidelbardoedizionidistefanodonno.com\/posts\/6523527828113378760?hl=it\">https:\/\/iquadernidelbardoedizionidistefanodonno.com\/posts\/6523527828113378760?hl=it<\/a><\/p>\n\n\n\n<p>_______<\/p>\n\n\n\n<p>LA RICERCA  nel nostro articolo del 25 gennaio scorso<\/p>\n\n\n\n<p><blockquote class=\"wp-embedded-content\" data-secret=\"ruSmbCuROv\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/25\/novita-editoriali-galestro-di-bruce-hunter\/\">NOVITA\u2019 EDITORIALI \/ \u201cGalestro\u201c DI BRUCE HUNTER<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;NOVITA\u2019 EDITORIALI \/ \u201cGalestro\u201c DI BRUCE HUNTER&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/01\/25\/novita-editoriali-galestro-di-bruce-hunter\/embed\/#?secret=Am9vKoW1aN#?secret=ruSmbCuROv\" data-secret=\"ruSmbCuROv\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/20\/libri-nuova-edizione-per-le-poesie-di-bruce-hunter\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/20\/libri-nuova-edizione-per-le-poesie-di-bruce-hunter\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)\u00a0_______ Continua la tradizione editoriale de I Quaderni del Bardo Edizioni di Stefano Donno, rivolta al mondo della poesia internazionale. La nuova pubblicazione riguarda l&#8217;ultima opera del poeta canadese Bruce Hunter (nella foto) intitolata \u201cGalestro\u201d. A distanza di soli due mesi dalla prima edizione ne arriva adesso una nuova. _______ _______ Per acquistare il libro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":213183,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213181"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=213181"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213181\/revisions"}],"predecessor-version":[{"id":213272,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213181\/revisions\/213272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/213183"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=213181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=213181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=213181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}