{"id":213723,"date":"2023-03-30T19:56:42","date_gmt":"2023-03-30T17:56:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=213723"},"modified":"2023-03-30T20:11:32","modified_gmt":"2023-03-30T18:11:32","slug":"papa-francesco-stara-in-ospedale-alcuni-giorni-per-curarsi-uninfezione-respiratoria","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/30\/papa-francesco-stara-in-ospedale-alcuni-giorni-per-curarsi-uninfezione-respiratoria\/","title":{"rendered":"PAPA FRANCESCO STARA&#8217; IN OSPEDALE ALCUNI GIORNI PER CURARSI UN&#8217;INFEZIONE RESPIRATORIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"750\" height=\"422\" class=\"wp-image-213724\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/cq5dam.thumbnail.cropped.750.422-2.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/cq5dam.thumbnail.cropped.750.422-2.jpeg 750w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/03\/cq5dam.thumbnail.cropped.750.422-2-300x169.jpeg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n\n\n\n<p>(Rdl) ______ <strong>l Direttore della Sala Stampa della Santa Sede, Matteo Bruni ha comunicato ai giornalisti  che:<\/strong><br>&#8220;Nei giorni scorsi Papa Francesco ha lamentato alcune difficolt\u00e0 respiratorie e ieri pomeriggio si \u00e8 recato presso il Policlinico A. Gemelli per effettuare alcuni controlli medici.<\/p>\n\n\n\n<p>L\u2019esito degli stessi ha evidenziato un\u2019infezione respiratoria (esclusa l&#8217;infezione da Covid 19) che richieder\u00e0 alcuni giorni di opportuna terapia medica ospedaliera.<\/p>\n\n\n\n<p>Papa Francesco \u00e8 toccato dai tanti messaggi ricevuti ed esprime la propria gratitudine per la vicinanza e la preghiera.<\/p>\n\n\n\n<p>Sua Santit\u00e0 Papa Francesco ha riposato bene durante la notte.<\/p>\n\n\n\n<p>Il quadro clinico \u00e8 in progressivo miglioramento e prosegue le cure programmate.<\/p>\n\n\n\n<p>Questa mattina dopo aver fatto colazione, ha letto alcuni quotidiani ed ha ripreso il lavoro.<\/p>\n\n\n\n<p>Prima del pranzo si \u00e8 recato nella Cappellina dell\u2019appartamento privato, dove si \u00e8 raccolto in preghiera ed ha ricevuto l\u2019eucarestia&#8221;.&nbsp;______<\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo di ieri sera<\/p>\n\n\n\n<p><blockquote class=\"wp-embedded-content\" data-secret=\"QvW5lZXksH\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/29\/213702\/\">PAPA FRANCESCO RICOVERATO IN OSPEDALE PER &#8220;affaticamento respiratorio&#8221; AVVERTITO IN MATTINATA<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;PAPA FRANCESCO RICOVERATO IN OSPEDALE PER &#8220;affaticamento respiratorio&#8221; AVVERTITO IN MATTINATA&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/29\/213702\/embed\/#?secret=atX2cF6JHo#?secret=QvW5lZXksH\" data-secret=\"QvW5lZXksH\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/30\/papa-francesco-stara-in-ospedale-alcuni-giorni-per-curarsi-uninfezione-respiratoria\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/30\/papa-francesco-stara-in-ospedale-alcuni-giorni-per-curarsi-uninfezione-respiratoria\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ______ l Direttore della Sala Stampa della Santa Sede, Matteo Bruni ha comunicato ai giornalisti che:&#8220;Nei giorni scorsi Papa Francesco ha lamentato alcune difficolt\u00e0 respiratorie e ieri pomeriggio si \u00e8 recato presso il Policlinico A. Gemelli per effettuare alcuni controlli medici. L\u2019esito degli stessi ha evidenziato un\u2019infezione respiratoria (esclusa l&#8217;infezione da Covid 19) che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":213724,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213723"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=213723"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213723\/revisions"}],"predecessor-version":[{"id":213727,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/213723\/revisions\/213727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/213724"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=213723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=213723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=213723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}