{"id":21456,"date":"2013-11-03T10:00:45","date_gmt":"2013-11-03T10:00:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21456"},"modified":"2013-11-03T10:00:45","modified_gmt":"2013-11-03T10:00:45","slug":"oggi-a-cavallino-celebrati-tutti-i-caduti-in-guerra","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/03\/oggi-a-cavallino-celebrati-tutti-i-caduti-in-guerra\/","title":{"rendered":"OGGI A CAVALLINO CELEBRATI TUTTI I CADUTI IN GUERRA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Schermata-2013-11-03-a-10.57.36.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Schermata-2013-11-03-a-10.57.36-300x65.png\" alt=\"\" width=\"300\" height=\"65\" class=\"alignleft size-medium wp-image-21457\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Schermata-2013-11-03-a-10.57.36-300x65.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Schermata-2013-11-03-a-10.57.36.png 682w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La Civica Amministrazione di Cavallino, in collaborazione con la locale Associazione Arma Aeronautica &#8211; Sezione \u201cCap. Michele Grande\u201d, celebra la commemorazione dei Caduti in Guerra in occasione della Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate. Domenica 3 novembre 2013 la cerimonia in Largo Caduti di Nassiriya in Cavallino. Il soprano Raffaella Liccardi canter\u00e0 l\u2019Inno nazionale italiano.<br \/>\nIl Sindaco Michele Lombardi, la Civica Amministrazione e l\u2019intera Cittadinanza ricordano i Concittadini caduti per l\u2019indipendenza, l\u2019unit\u00e0 e la libert\u00e0 dell\u2019Italia. La cerimonia commemorativa, organizzata in collaborazione con la locale Associazione Arma Aeronautica &#8211; Sezione \u201cCap. Michele Grande\u201d e che avr\u00e0 luogo domenica 3 novembre 2013 alle ore 10 circa, vedr\u00e0 muoversi da Piazza Castromediano il Gonfalone del Comune di Cavallino, dell&#8217;Associazione Combattenti e Reduci e della locale Associazione Arma Aeronautica verso il Monumento ai Caduti in Largo Caduti di Nassiriya; seguiranno l\u2019alzabandiera e l&#8217;esecuzione dell&#8217;Inno Nazionale da parte del soprano Raffaella Liccardi, la deposizione di una corona d\u2019alloro dinanzi al Monumento dei Caduti, il saluto del Sindaco e la celebrazione della\u00a0 Santa Messa da parte del\u00a0 parroco don Gaetano Tornese. In occasione della celebrazione, in Largo Caduti di Nassiriya sar\u00e0 esposto un simulacro del pannello strumentazione di volo del velivolo NB 339, in uso presso la base di Lecce con la colorazione delle Frecce Tricolori. Prevista inoltre una dimostrazione del robot artificiere dell\u2019Arma dei Carabinieri.<\/p>\n<p>La Commemorazione dei Caduti di tutte le guerre costituisce una ricorrenza che, sia pur celebrata sobriamente, \u00e8 intrisa di forti contenuti e valori ideali verso i quali la Civica Amministrazione ha sempre rivolto particolare attenzione.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/03\/oggi-a-cavallino-celebrati-tutti-i-caduti-in-guerra\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/03\/oggi-a-cavallino-celebrati-tutti-i-caduti-in-guerra\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La Civica Amministrazione di Cavallino, in collaborazione con la locale Associazione Arma Aeronautica &#8211; Sezione \u201cCap. Michele Grande\u201d, celebra la commemorazione dei Caduti in Guerra in occasione della Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate. Domenica 3 novembre 2013 la cerimonia in Largo Caduti di Nassiriya in Cavallino. Il soprano Raffaella Liccardi canter\u00e0 l\u2019Inno nazionale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21457,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21456"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21456"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21456\/revisions"}],"predecessor-version":[{"id":21458,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21456\/revisions\/21458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21457"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}