{"id":214677,"date":"2023-04-21T00:02:00","date_gmt":"2023-04-20T22:02:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=214677"},"modified":"2023-04-21T15:44:16","modified_gmt":"2023-04-21T13:44:16","slug":"mostra-antologica-di-arnaldo-miccoli","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/04\/21\/mostra-antologica-di-arnaldo-miccoli\/","title":{"rendered":"MOSTRA ANTOLOGICA DI ARNALDO MICCOLI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"666\" class=\"wp-image-214678\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/04\/micco.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/04\/micco.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/04\/micco-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/04\/micco-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p>di<strong> Raffaele Polo<\/strong> ______ <\/p>\n\n\n\n<p>Si chiama <strong>\u00abPatti e Ricatti\u00bb<\/strong> la personale del pittore cavallinese <strong>Arnaldo Miccoli<\/strong> (nella foto), che per oltre cinquant\u2019anni ha vissuto a New York. <\/p>\n\n\n\n<p>Cerimonia di inaugurazione, sabato 22 aprile alle ore 18.30 nella Sala Consiliare \u00abMario Gorgoni\u00bb del Palazzo Ducale dei Castromediano. Ad aprirla saranno i saluti del sindaco di Cavallino Bruno Ciccarese Gorgoni. Presenta la mostra Toti Carpentieri, critico d\u2019arte. Con l&#8217;artista, interverranno Luigi De Luca, direttore del Museo Provinciale \u00abSigismondo Castromediano\u00bb di Lecce, Alessandro Laporta, direttore emerito della Biblioteca provinciale \u00abNicola Bernardini\u00bb di Lecce e Ludovico Malorgio, giornalista.<\/p>\n\n\n\n<p>L&#8217;artista cos\u00ec si presenta: \u00abLa mia produzione artistica si sviluppa in tre fasi. La prima fase che va dal 1969 al 1980; \u00e8 questo il periodo delle parate, teatrini lo splendore e le distrazioni delle feste del sud (Un immenso continente che, dall\u2019Adriatico e dallo Ionio scorre sin negli oceani che circondano il nuovo mondo, il tripudio dei colori, i palloncini fermi in un aria densa, i bastoni variegati, i simboli ripescati in profondissimi depositi umani. <\/p>\n\n\n\n<p>La seconda fase inizia nel 1981 e dura fino al 1988, \u00e8 il periodo Magico Grottesco. Caratterizzato dal prevalere per l\u2019elemento psichico, per la pulsione che viene dal profondo, per il viaggio nell\u2019al di la&nbsp; del reale, nei regni oscuri e magici del mito. La tematica dell\u2019inquinamento atmosferico e dei disastri ambientali \u00e8 tale da non potermi lasciare indifferente; questi eventi danno vita alla terza fase della mia produzione: queste opere sembrano molto pi\u00f9 lontane dai ciquanta anni fa, quando dipingevo La Contadina Pugliese e le Masserie Salentine. <\/p>\n\n\n\n<p>Ora le tele sono pregne di una specie di figure nate da una apocalisse post moderna in cui la terra brucia con i suoi esseri luciferini. Il divario tematico, stilistico, emotivo e ideologico \u00e8 fortissimo; ci\u00f2 indica il grande&nbsp; sviluppo come artista e un impegno sempre pi\u00f9 forte per la difesa di questo nostro Nobile Pianeta e di tutti gli esseri che lo costituiscono. Nasce cos\u00ec &#8216;Patti e Ricatti&#8217; ,ritratto attuale di un ennesimo conflitto generale, ove la demenza grave e irreversibile di questo millennio porta alla inevitabile sconfitta dell\u2019intera Genesi\u201d. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La mostra rester\u00e0 aperta sino al 12 maggio 2023 dal marted\u00ec al gioved\u00ec dalle ore 10.00 alle ore 12.30 e venerd\u00ec, sabato e domenica dalle ore 10.00 alle ore 12.30 e dalle ore 17 alle ore 20. <\/p>\n\n\n\n<p>Ingresso libero.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/04\/21\/mostra-antologica-di-arnaldo-miccoli\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/04\/21\/mostra-antologica-di-arnaldo-miccoli\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo ______ Si chiama \u00abPatti e Ricatti\u00bb la personale del pittore cavallinese Arnaldo Miccoli (nella foto), che per oltre cinquant\u2019anni ha vissuto a New York. Cerimonia di inaugurazione, sabato 22 aprile alle ore 18.30 nella Sala Consiliare \u00abMario Gorgoni\u00bb del Palazzo Ducale dei Castromediano. Ad aprirla saranno i saluti del sindaco di Cavallino [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":214678,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/214677"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=214677"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/214677\/revisions"}],"predecessor-version":[{"id":214680,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/214677\/revisions\/214680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/214678"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=214677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=214677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=214677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}