{"id":21479,"date":"2013-11-04T08:43:01","date_gmt":"2013-11-04T08:43:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21479"},"modified":"2013-11-04T08:43:06","modified_gmt":"2013-11-04T08:43:06","slug":"allarme-sbarchi-di-cannabis-nel-salento-dalla-svizzera-la-notizia-di-un-intero-villaggio-albanese-intossicato-dopo-aver-lavorato-nelle-piantagioni-di-canapa","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/04\/allarme-sbarchi-di-cannabis-nel-salento-dalla-svizzera-la-notizia-di-un-intero-villaggio-albanese-intossicato-dopo-aver-lavorato-nelle-piantagioni-di-canapa\/","title":{"rendered":"Allarme sbarchi di cannabis nel Salento. Dalla Svizzera la notizia di un intero villaggio albanese intossicato dopo aver lavorato nelle piantagioni di canapa."},"content":{"rendered":"<p><a title=\"Articolo Originale\" href=\"http:\/\/rt.com\/news\/cannabis-workers-hospital-albania-133\/\" target=\"_blank\">http:\/\/rt.com\/news\/cannabis-workers-hospital-albania-133\/<\/a><\/p>\n<p>Allarme sbarchi di cannabis nel Salento. Sembra essere tornati a qualche anno fa, mentre nel silenzio dei media italiani, viene dalla Svizzera la notizia di un intero villaggio albanese intossicato dopo aver lavorato nelle piantagioni di canapa.<\/p>\n<p>Mentre in Italia e nell\u2019estremo lembo del Tacco sembra che non accada nulla, tanta \u00e8 la routine dei continui recuperi o sequestri di quintali di cannabis imballata che approda sulle coste del Salento, addirittura dalla lontana Svizzera, giunge la notizia che quasi un intero villaggio nel sud dell&#8217;Albania ha richiesto l\u2019aiuto medico a causa di sintomi di intossicazione acuta per aver lavorato nelle locali piantagioni di cannabis. Sarebbero almeno 700, infatti, le persone, la maggior parte delle quali donne, affette da &#8220;grave interferenza da avvelenamento cannabis&#8221;.<\/p>\n<p>Un medico dell&#8217;ospedale della vicina citt\u00e0 di Argirocastro, il dottor Hysni Luka, ha fatto sapere che le loro denunce sarebbero ovviamente connesse dal lavoro per l\u2019impianto, la raccolta, pressatura e imballaggio della cannabis. Di conseguenza, tutti i pazienti avrebbero sofferto di vomito, dolore addominale, problemi cardiaci e pressione alta.<\/p>\n<p>Secondo il medico sono stati coinvolti anche molti giovani e persino bambini tra le vittime. Per le autorit\u00e0 dell\u2019ospedale militare, circa il 40 % dei lavoratori nelle piantagioni sarebbero minorenni.<\/p>\n<p>Il paese a circa 240 chilometri a sud della capitale Tirana \u00e8 considerato il pi\u00f9 importante produttore di hashish del paese. Secondo le autorit\u00e0, circa 900 tonnellate di droga, vale a dire circa 4,5 miliardi di euro, vengono prodotte nella citt\u00e0 vicino al confine con la Grecia, ogni anno.<\/p>\n<p>Nel mese di agosto, la polizia ha arrestato 50 lavoratori stagionali sui campi di cannabis. Due persone sono rimaste ferite in scontri a fuoco con le guardie armate.<\/p>\n<p>E di tutto ci\u00f2 se ne sa pochissimo o quasi nulla, nonostante tali fatti accadano a una distanza irrisoria dalle coste italiane e siano questioni connesse a traffici internazionali che vedono la Terra d\u2019Otranto quale punto di passaggio quasi obbligato di tali attivit\u00e0 criminali.<\/p>\n<p>Per Giovanni D&#8217;Agata, presidente dello \u201cSportello dei Diritti\u201d, se il Salento \u00e8 tornato prepotentemente ad essere il crocevia del traffico di cannabis &#8211; come dimostrano anche i mezzi utilizzati per veicolare la droga tanto che, superato il pi\u00f9 classico dei vettori marini veloci, il gommone, nei giorni scorsi sono stati scoperti trafficanti che si erano ingegnati ad utilizzare addirittura canoe di vetroresina trainate da veloci scooter d\u2019acqua tanto \u00e8 breve la distanza tra le coste della Terra d\u2019Otranto da quelle albanesi &#8211; \u00e8 necessario un grande sforzo congiunto da parte dei governi albanese e italiano per fermare alla fonte la produzione di canapa nel \u201cPaese delle Aquile\u201d e sostituirla con altre colture.<\/p>\n<p>Tale attivit\u00e0 di cooperazione internazionale, infatti, potr\u00e0 evitare sia danni alla salute della popolazione locale che ai giovani italiani che sono diventati grandi consumatori di derivati dalla cannabis anche a causa della notevole riduzione dei costi connessa alla enorme quantit\u00e0 immessa sul mercato.<a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/04\/allarme-sbarchi-di-cannabis-nel-salento-dalla-svizzera-la-notizia-di-un-intero-villaggio-albanese-intossicato-dopo-aver-lavorato-nelle-piantagioni-di-canapa\/cannabis-plants-si\/\" rel=\"attachment wp-att-21480\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/cannabis-plants.si_-150x150.jpg\" alt=\"\" title=\"cannabis-plants.si\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-21480\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/04\/allarme-sbarchi-di-cannabis-nel-salento-dalla-svizzera-la-notizia-di-un-intero-villaggio-albanese-intossicato-dopo-aver-lavorato-nelle-piantagioni-di-canapa\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/04\/allarme-sbarchi-di-cannabis-nel-salento-dalla-svizzera-la-notizia-di-un-intero-villaggio-albanese-intossicato-dopo-aver-lavorato-nelle-piantagioni-di-canapa\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>http:\/\/rt.com\/news\/cannabis-workers-hospital-albania-133\/ Allarme sbarchi di cannabis nel Salento. Sembra essere tornati a qualche anno fa, mentre nel silenzio dei media italiani, viene dalla Svizzera la notizia di un intero villaggio albanese intossicato dopo aver lavorato nelle piantagioni di canapa. Mentre in Italia e nell\u2019estremo lembo del Tacco sembra che non accada nulla, tanta \u00e8 la routine [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21480,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21479"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21479"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21479\/revisions"}],"predecessor-version":[{"id":21484,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21479\/revisions\/21484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21480"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}