{"id":215209,"date":"2023-05-02T17:50:29","date_gmt":"2023-05-02T15:50:29","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=215209"},"modified":"2023-05-02T17:50:31","modified_gmt":"2023-05-02T15:50:31","slug":"in-tre-rapinatori-costretti-alla-fuga-da-unanziana","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/02\/in-tre-rapinatori-costretti-alla-fuga-da-unanziana\/","title":{"rendered":"IN TRE RAPINATORI COSTRETTI ALLA FUGA DA UN&#8217;ANZIANA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"1044\" class=\"wp-image-215225\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/carab.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/carab.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/carab-300x261.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/carab-1024x891.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/carab-768x668.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n\n\n\n<p>(e.l.) ______\u00a0 Inquietante tentata rapina in casa questa notte a Fasano, ai danni di un&#8217;anziana di 79 anni che era sola da sola quando nella sua abitazione all&#8217;improvviso hanno fatto irruzione tre giovani a volto travisato,che hanno tentato di immobilizzarla e poi di intimidrla con violenza.<\/p>\n\n\n\n<p>Ma pur da sola contro tre, l&#8217;anziana non si \u00e8 persa d&#8217;animo, non si \u00e8 spaventata, ha reagito urlando con tutta la forza che aveva in gola e non si \u00e8 fatta sottomettere.<\/p>\n\n\n\n<p>La sua reazione inaspettata ha consigliato ai rapinatori di desistere e di scappare, prima di essere scoperti.<\/p>\n\n\n\n<p>Sulle loro tracce ci sono ora i Carabinieri del locale Comando Compagnia che indagano sull&#8217;accaduto.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/02\/in-tre-rapinatori-costretti-alla-fuga-da-unanziana\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/02\/in-tre-rapinatori-costretti-alla-fuga-da-unanziana\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0 Inquietante tentata rapina in casa questa notte a Fasano, ai danni di un&#8217;anziana di 79 anni che era sola da sola quando nella sua abitazione all&#8217;improvviso hanno fatto irruzione tre giovani a volto travisato,che hanno tentato di immobilizzarla e poi di intimidrla con violenza. Ma pur da sola contro tre, l&#8217;anziana non si [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":215225,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215209"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=215209"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215209\/revisions"}],"predecessor-version":[{"id":215226,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215209\/revisions\/215226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/215225"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=215209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=215209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=215209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}