{"id":215333,"date":"2023-05-05T13:50:35","date_gmt":"2023-05-05T11:50:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=215333"},"modified":"2023-05-05T13:55:58","modified_gmt":"2023-05-05T11:55:58","slug":"la-polizia-postale-nella-giornata-contro-la-pedofilia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/05\/la-polizia-postale-nella-giornata-contro-la-pedofilia\/","title":{"rendered":"LA POLIZIA POSTALE CONTRO LA PEDOFILIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"636\" height=\"348\" class=\"wp-image-215334\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/poliziapostaleedellecomunicazioni.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/poliziapostaleedellecomunicazioni.jpg 636w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/poliziapostaleedellecomunicazioni-300x164.jpg 300w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo il seguente comunicato stampa inviatoci dalla Polizia Postale ______\u00a0<\/p>\n\n\n\n<p>Nella Giornata Nazionale contro la Pedofilia e la Pedopornografia, la Polizia Postale condivide i dati pi\u00f9 significativi di un impegno quotidiano, per la tutela dei minori da ogni forma di rischio cibernetico.<\/p>\n\n\n\n<p>La lotta all\u2019abuso sessuale <em>online<\/em> in danno di minori diventa sempre pi\u00f9 puntuale nel cercare di porre un argine a fenomeni gravi quanto complessi: cresce il numero dei soggetti adulti arrestati per reati di pedopornografia, adescamento online e abuso sessuale di minori.&nbsp; Si tratta di soggetti ad alto livello di pericolosit\u00e0 poich\u00e9 colti in flagranza di reato, perch\u00e9 detentori di grandi quantit\u00e0 di materiale pedopornografico o in quanto abusanti di bambini e ragazzi nelle loro disponibilit\u00e0.<\/p>\n\n\n\n<p>Sono spesso uomini, con un\u2019et\u00e0 inferiore ai 50 anni, che in maniera sistematica, sfruttano le caratteristiche tecniche dei diversi servizi di rete per assicurarsi il miraggio dell\u2019anonimato e dell\u2019impunit\u00e0.<\/p>\n\n\n\n<p>L\u2019adescamento si riconferma come un fenomeno preoccupante che investe fasce di et\u00e0 sempre pi\u00f9 precoci, nei luoghi della massima sicurezza percepita, come le chat con i compagni di scuola e le piattaforme di gaming. Sono le vittime pi\u00f9 fragili e fiduciose verso gli altri, anche quando sconosciuti, e sono quelli che hanno il rapporto pi\u00f9 spontaneo e naturale con le nuove tecnologie.<\/p>\n\n\n\n<p>Per questo appare quanto mai urgente proteggerli dalle attenzioni deviate di soggetti adulti, che si concentrano proprio dove la presenza di minori \u00e8 pi\u00f9 cospicua. I genitori sono il primo baluardo di sicurezza per bambini e ragazzi ed hanno, nell\u2019ascolto e nel dialogo, gli strumenti pi\u00f9 potenti per rendere la tutela dei bambini una realt\u00e0 e la loro sicurezza un fatto.<\/p>\n\n\n\n<p>Il Dossier \u201c<em>Dentro i numeri: la lotta alla pedofilia online<\/em>\u201d contiene non solo numeri in grado di raccontare un rischio attuale ma vuole descrivere un sistema di tutela come quello portato avanti dalla Polizia Postale, fatto di sinergie interistituzionali e attivit\u00e0 multidisciplinari nelle quali la commistione dei saperi e degli impegni miri a costruire soluzioni possibili ed efficaci. La rete \u00e8 oggi il luogo del progresso e dello sviluppo delle societ\u00e0 ma \u00e8 diventata anche strumento di amplificazione della minaccia all\u2019infanzia e all\u2019adolescenza: la protezione dei bambini e dei ragazzi da ogni forma di abuso sessuale \u00e8 possibile, pu\u00f2 diventare realt\u00e0 se sirompe il silenzio, se si creano alleanze, se si condivide la responsabilit\u00e0 di proteggerli anche online, sempre.<\/p>\n\n\n\n<p>Il Centro Operativo per la Sicurezza Cibernetica &#8211; Polizia Postale e delle Comunicazioni \u201cPuglia\u201d, e le dipendenti Sezioni Operative di Lecce, Brindisi, Taranto e Foggia, hanno collaborato con il Servizio Polizia Postale e delle Comunicazioni presso il Dipartimento della Pubblica Sicurezza nelle attivit\u00e0 di prevenzione e monitoraggio della rete contribuendo all\u2019oscuramento e l\u2019inserimento in <em>black-list<\/em> <strong>nel 2022 di 51 e nel 2023 di 21 siti a contenuto pedopornografico<\/strong>.<\/p>\n\n\n\n<p>Per quanto riguarda l\u2019attivit\u00e0 repressiva, il Centro Operativo \u201cPuglia\u201d e le Sezioni provinciali, hanno complessivamente <strong>denunciato 71 soggetti nel 2022 e 35 nel 2023<\/strong> per aver scaricato, condiviso e scambiato foto e video di abuso sessuale di minori, traendo in <strong>arresto 6 persone nel 2022 e 2 nel 2023<\/strong>, con l\u2019ultimo arresto effettuato il 28 aprile a carico di un individuo per detenzione e scambio di un\u2019ingente quantit\u00e0 di materiale pedopornografico (centinaia tra foto e video). Nel corso del 2022 in Puglia sono state complessivamente <strong>8 le persone denunciate per il reato di adescamento online e 7 solo nei primi mesi del 2023<\/strong>.<\/p>\n\n\n\n<p>Accanto all\u2019attivit\u00e0 investigativa e repressiva, il Centro Operativo per la Sicurezza Cibernetica &#8211; Polizia Postale e delle Comunicazioni \u201cPuglia\u201d, e le dipendenti Sezioni Operative, svolgono una costante attivit\u00e0 di prevenzione, attraverso incontri formativi con le scuole e presso i principali luoghi di aggregazione sociale, allo scopo di formare ed informare gli utenti ad un utilizzo consapevole e sicuro della rete.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/05\/la-polizia-postale-nella-giornata-contro-la-pedofilia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/05\/la-polizia-postale-nella-giornata-contro-la-pedofilia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo il seguente comunicato stampa inviatoci dalla Polizia Postale ______\u00a0 Nella Giornata Nazionale contro la Pedofilia e la Pedopornografia, la Polizia Postale condivide i dati pi\u00f9 significativi di un impegno quotidiano, per la tutela dei minori da ogni forma di rischio cibernetico. La lotta all\u2019abuso sessuale online in danno di minori diventa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":215334,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215333"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=215333"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215333\/revisions"}],"predecessor-version":[{"id":215340,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215333\/revisions\/215340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/215334"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=215333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=215333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=215333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}