{"id":215415,"date":"2023-05-07T12:46:56","date_gmt":"2023-05-07T10:46:56","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=215415"},"modified":"2023-05-07T12:47:20","modified_gmt":"2023-05-07T10:47:20","slug":"giornata-della-croce-rossa-alecce-lunedi-8","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/07\/giornata-della-croce-rossa-alecce-lunedi-8\/","title":{"rendered":"GIORNATA DELLA CROCE ROSSA A LECCE LUNEDI&#8217; 8"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1072\" height=\"500\" class=\"wp-image-215416\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/CR.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/CR.jpg 1072w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/CR-300x140.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/CR-1024x478.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/CR-768x358.jpg 768w\" sizes=\"(max-width: 1072px) 100vw, 1072px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. Il presidente del Comitato CRI-Lecce Antonio Zecca ci scrive ______&nbsp;<\/p>\n\n\n\n<p>Anche quest&#8217;anno l\u20198 maggio 2023 si celebrer\u00e0 la Giornata Mondiale della Croce Rossa e Mezzaluna Rossa. <\/p>\n\n\n\n<p>Sar\u00e0 un momento per onorare soprattutto l&#8217;impegno di tutti i volontari che si sono spesi e continuano a spendersi in tutto il mondo con l&#8217;unico obiettivo di alleviare la sofferenza umana. Ogni giorno, con il loro impegno, cercano di stare vicini e dare un aiuto ai vulnerabili accendendo un faro di speranza per andare avanti. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il nostro comitato di Lecce sar\u00e0 impegnato in alcune iniziative, che porter\u00e0 avanti per tutta la prossima settimana, iniziando proprio da luned\u00ec 8 Maggio 2023 con un evento che ci porter\u00e0 in piazza per la campagna nazionale \u201ce poi ci siamo incontrati\u201d che nasce da quel sentimento di profondo smarrimento che viene spazzato via quando, all\u2019improvviso, arriva qualcuno che ci regala un abbraccio o ci guarda negli occhi e ci dice \u201cvedrai che una soluzione si trova\u201d. Luned\u00ec 8 maggio a partire dalle ore 20:00: ci sar\u00e0 una fiaccolata con partenza dalla nostra sede in Viale dell&#8217;Universit\u00e0,33 che muover\u00e0 per le vie del centro di Lecce con arrivo a Palazzo Carafa, sede del Comune di Lecce, dove incontreremo il sindaco Carlo Salvemini a cui consegneremo la bandiera CRI che sar\u00e0 poi esposta, come ogni anno e per tutta la settimana, sulla facciata del palazzo comunale. <\/p>\n\n\n\n<p>Inoltre, grazie al consueto accordo siglato tra CRI e ANCI la sera del 8 e il 9 maggio il \u201cSedile\u201d, storico monumento della citt\u00e0 di Lecce sito in Piazza Sant\u2019Oronzo, sar\u00e0 illuminato di rosso. A seguito della recente uccisione della oncologa, dottoressa Ester Pasqualoni di Teramo, il nostro comitato ha deciso di ricordare la campagna CRI \u201cNON SONO UN BERSAGLIO\u201d e dedica la fiaccolata a tutti i sanitari vittime di inqualificabili aggressioni. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Domenica 14 maggio dalle 9:00 alle 13:00: in Piazza Sant&#8217;Oronzo i nostri volontari, istruttori e soccorritori, insieme ai Giovani CRI proporranno diverse attivit\u00e0 alla cittadinanza leccese come prove audiometriche con personale medico, dimostrazioni di manovre di disostruzione delle vie aeree in et\u00e0 pediatrica, dimostrazioni basic life support, simulazioni e attivit\u00e0 informative di vario genere. <\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/07\/giornata-della-croce-rossa-alecce-lunedi-8\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/07\/giornata-della-croce-rossa-alecce-lunedi-8\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il presidente del Comitato CRI-Lecce Antonio Zecca ci scrive ______&nbsp; Anche quest&#8217;anno l\u20198 maggio 2023 si celebrer\u00e0 la Giornata Mondiale della Croce Rossa e Mezzaluna Rossa. Sar\u00e0 un momento per onorare soprattutto l&#8217;impegno di tutti i volontari che si sono spesi e continuano a spendersi in tutto il mondo con l&#8217;unico [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":215416,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215415"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=215415"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215415\/revisions"}],"predecessor-version":[{"id":215418,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215415\/revisions\/215418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/215416"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=215415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=215415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=215415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}