{"id":215678,"date":"2023-05-07T00:30:00","date_gmt":"2023-05-06T22:30:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=215678"},"modified":"2023-05-12T15:34:47","modified_gmt":"2023-05-12T13:34:47","slug":"calcio-maschile-vs-calcio-femminile-esistono-davvero-differenze-in-campo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/07\/calcio-maschile-vs-calcio-femminile-esistono-davvero-differenze-in-campo\/","title":{"rendered":"CALCIO MASCHILE VS CALCIO FEMMINILE: ESISTONO DAVVERO DIFFERENZE IN CAMPO?"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1280\" height=\"853\" class=\"wp-image-215679\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/Calcio-maschile-vs-calcio-femminile.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/Calcio-maschile-vs-calcio-femminile.jpg 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/Calcio-maschile-vs-calcio-femminile-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/Calcio-maschile-vs-calcio-femminile-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/05\/Calcio-maschile-vs-calcio-femminile-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n\n\n\n<p>Il calcio maschile \u00e8 tra gli sport pi\u00f9 seguiti in Italia, e non solo, ma negli ultimi anni anche il calcio femminile sta vivendo un periodo d\u2019oro grazie alle nuove generazioni di bambine e ragazze che si avvicinano a questa attivit\u00e0, sia in maniera amatoriale, sia agonistica. Sono in numero sempre maggiore, infatti, le giovanissime che frequentano scuole di calcio femminile per ambire al professionismo.<\/p>\n\n\n\n<p>Gioco, divertimento, disciplina, regole di comportamento, tecniche di base, interazione, il calcio \u00e8 tra gli sport pi\u00f9 accessibili e appassionanti. In Italia, il numero delle donne che lo praticano in maniera costante \u00e8 incrementato, soprattutto dopo l\u2019ultimo campionato mondiale del 2019 che ha visto la squadra nazionale femminile ottenere ottimi risultati. L\u2019eco di tale successo calcistico si nota anche osservando le pi\u00f9 importanti piattaforme digitali di scommesse sportive. Un esempio \u00e8 dato da <a href=\"https:\/\/betmasteritalia.info\/\">https:\/\/betmasteritalia.info\/<\/a> su cui numerosi utenti seguono i risultati di match femminili al pari di quelli maschili.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Organismi diversi, stesso gioco<\/h2>\n\n\n\n<p>Quali differenze esistono tra calcio femminile e calcio maschile? In termini di regolamento di gioco nessuna e maschi e femmine non presentano peculiarit\u00e0 di genere fino all\u2019et\u00e0 dello sviluppo che possano influire sulle prestazioni in un modo o nell\u2019altro.<\/p>\n\n\n\n<p>Dalla fase puberale in poi le cose cambiano fisiologicamente e si registrano performance sportive diverse da ricondursi a caratteristiche tipicamente organiche.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Capacit\u00e0 aerobica femminile<\/h2>\n\n\n\n<p>L\u2019<strong>apparato cardiovascolare<\/strong><strong> <\/strong>femminile presenta una minor capacit\u00e0 di trasporto ossigeno&nbsp;dovuta alle caratteristiche di globuli rossi pi\u00f9 piccoli e tasso di emoglobina inferiore. Anche la <strong>gittata sistolica<\/strong>&nbsp;(volume di sangue espulso attraverso arteria polmonare e aorta), a parit\u00e0 di impegno di lavoro, \u00e8 inferiore a quella maschile. Questo si traduce in una <strong>capacit\u00e0 aerobica<\/strong> ridotta del 10% circa rispetto ad un maschio con caratteristiche di peso e altezza simili.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ormoni e ciclo mestruale<\/h2>\n\n\n\n<p>Maschi e femmine hanno una <strong>diversa distribuzione di grasso corporeo<\/strong> e percentuale di acqua nell\u2019organismo che, nelle donne, le espone ad una potenziale maggior disidratazione.<\/p>\n\n\n\n<p>Ulteriori differenze sono dovute agli <strong>ormoni androgeni<\/strong>&nbsp;che influenzano velocit\u00e0, decelerazioni, accelerazioni, rapidit\u00e0, e all\u2019<strong>apparato scheletrico <\/strong>in termini di <strong>densit\u00e0 ossea<\/strong> che nelle donne \u00e8 pi\u00f9 bassa, posizione del <strong>centro di gravit\u00e0 corporeo<\/strong> che interviene nelle attivit\u00e0 fisiche di coordinazione in cui le donne risultano avvantaggiate.<\/p>\n\n\n\n<p>Inoltre, in virt\u00f9 della fisiologia femminile, <strong>legamenti<\/strong> e <strong>articolazioni<\/strong> sono pi\u00f9 flessibili.<\/p>\n\n\n\n<p>Non ultimo, il <strong>ciclo mestruale<\/strong>. Secondo diversi studi, esiste una correlazione tra questo e prestazione sportiva a seconda delle fasi del ciclo stesso che generano una risposta differente dell\u2019organismo sotto sforzo fisico. In ogni caso non \u00e8 un impedimento all\u2019allenamento.<\/p>\n\n\n\n<p>Al di l\u00e0 delle peculiarit\u00e0 fisiche proprie di maschie femmine non v\u2019\u00e8 dubbio che oggi il calcio femminile desti pi\u00f9 attenzione rispetto al passato e la sua storia, la sua evoluzione nel tempo, lo dimostrano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Come nasce il calcio femminile<\/h2>\n\n\n\n<p>A cosa si deve la nascita del calcio femminile?<\/p>\n\n\n\n<p>Le sue origini risalgono alla seconda rivoluzione industriale in Gran Bretagna, tra fine Settecento e met\u00e0 Ottocento del secolo scorso, ad opera della Football Association. \u00c8 in questo periodo, infatti, che le lavoratrici delle fabbriche inglesi iniziano a giocare a calcio come dopolavoro ispirando altre donne al punto che, dopo la prima guerra mondiale, fanno capolino in Scozia e Francia le prime squadre di calcio femminile. Possono giocare, ma non possono farlo sui campi federali o partecipare a determinate competizioni. Non si tratta solo di un cambiamento sportivo, ma anche sociale ed economico. \u00c8 l\u2019inizio della dimostrazione di un nuovo livello di consapevolezza delle donne.<\/p>\n\n\n\n<p>Nel Bel Paese bisogna attendere il 1933 per vedere la prima squadra di calcio femminile, fondata a Milano, ma nonostante gli entusiasmi delle giovani calciatrici dell\u2019epoca, la Figc (Federazione Italiana Gioco Calcio) consente loro il gioco esclusivamente a porte chiuse ritenendo il calcio un\u2019attivit\u00e0 maschile. Solo nel secondo dopoguerra il calcio femminile vive una sorta di riscossa con la formazione delle squadre della citt\u00e0 di Trieste e Napoli.<\/p>\n\n\n\n<p>Oggi, ferme restando le caratteristiche strutturali, naturali, di uomini e donne che non limitano e non impediscono un gioco di pari livello, il calcio femminile presenta differenze importanti:<\/p>\n\n\n\n<p>&#8211; a livello economico rispetto a quello maschile che coinvolge una pi\u00f9 corposa filiera di investimenti;<\/p>\n\n\n\n<p>&#8211; a livello mediatico con minor spazio televisivo, giornalistico, informativo;<\/p>\n\n\n\n<p>&#8211; a livello di retribuzioni pi\u00f9 esigue alle calciatrici.&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/07\/calcio-maschile-vs-calcio-femminile-esistono-davvero-differenze-in-campo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/07\/calcio-maschile-vs-calcio-femminile-esistono-davvero-differenze-in-campo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il calcio maschile \u00e8 tra gli sport pi\u00f9 seguiti in Italia, e non solo, ma negli ultimi anni anche il calcio femminile sta vivendo un periodo d\u2019oro grazie alle nuove generazioni di bambine e ragazze che si avvicinano a questa attivit\u00e0, sia in maniera amatoriale, sia agonistica. Sono in numero sempre maggiore, infatti, le giovanissime [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215678"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=215678"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215678\/revisions"}],"predecessor-version":[{"id":215680,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/215678\/revisions\/215680"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=215678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=215678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=215678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}