{"id":21596,"date":"2013-11-07T08:40:04","date_gmt":"2013-11-07T08:40:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21596"},"modified":"2013-11-07T08:42:25","modified_gmt":"2013-11-07T08:42:25","slug":"dall-ilva-alla-tap-il-vendolismo-malattia-infantile-del-comunismo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/07\/dall-ilva-alla-tap-il-vendolismo-malattia-infantile-del-comunismo\/","title":{"rendered":"Dall&#8217; Ilva alla Tap &#8211; IL VENDOLISMO, MALATTIA INFANTILE DEL COMUNISMO"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/07\/dall-ilva-alla-tap-il-vendolismo-malattia-infantile-del-comunismo\/bandiera11\/\" rel=\"attachment wp-att-21597\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/bandiera11-150x150.jpg\" alt=\"\" title=\"bandiera11\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-21597\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/07\/dall-ilva-alla-tap-il-vendolismo-malattia-infantile-del-comunismo\/nichi-vendola\/\" rel=\"attachment wp-att-21598\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/nichi-vendola-150x150.jpg\" alt=\"\" title=\"nichi-vendola\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-21598\" \/><\/a>(RdL) Proseguono i provvedimenti anche concreti della magistratura contro l\u0092 Ilva, che, sostanzialmente ancora agevolata, se non protetta, dal governo bi \u0096Lletta, continua ad essere inadempiente sul fronte del reale risanamento, della radicale ristrutturazione della produzione, della tutela dell\u0092ambiente e della salute delle persone.<\/p>\n<p style=\"text-align: justify;\">Insomma, il disastro continua. Fino a quando?<\/p>\n<p style=\"text-align: justify;\">Fino a quando la volont\u00e0 popolare non trover\u00e0 uno sbocco politico reale, per avviare lo smantellamento dell\u0092attuale sistema, in una profonda rigenerazione della produzione, su criteri moderni ed efficienti, sotto l\u0092egida dello Stato, che dovrebbe riprendersi il controllo di questo settore, strategico, senza lasciarlo agli approfittatori e agli avventurieri senza scrupoli, come ha fatto in passato.<\/p>\n<p style=\"text-align: justify;\">Le occasioni offerte dal risanamento ambientale, quello ancora possibile, e le nuove prospettive imprenditoriali, faranno poi cadere e finalmente il ricatto occupazionale, su cui ambiguamente si \u00e8 puntellato il sistema di interessi stratosferici e di corruzione totale, di cui ho scritto qualche giorno fa, commentando il coinvolgimento giudiziario del governatore della Regione Puglia Nichi Vendola.<\/p>\n<p style=\"text-align: justify;\">Ora, come \u00e8 stato giustamente rilevato, il pericolo \u00e8 che l\u0092attenzione sociale si appiattisca sugli aspetti giuridici e legali, mentre si distolga dalla politica.<\/p>\n<p style=\"text-align: justify;\">Francamente, da intellettuale, mi interessa poco e punto l\u0092esito delle inchieste dei magistrati, perch\u00e9 quello che mi sta a cuore \u00e8 il giudizio politico.<\/p>\n<p style=\"text-align: justify;\">Al di l\u00e0 degli aspetti penali, al netto delle bucoliche prese di posizione retoriche, oltre i quadretti idilliaci a lungo dipinti, in concreto la Regione Puglia oggettivamente non si \u00e8 mossa contro il sistema dell\u0092Ilva, anzi, implicitamente, cos\u00ec facendo, l\u0092ha agevolato.<\/p>\n<p style=\"text-align: justify;\">Vale pure per la sanit\u00e0, perch\u00e9, vicende giudiziarie a parte, la sanit\u00e0 pugliese costa troppo e funziona male, il tutto sulla pelle e nelle tasche dei Pugliesi.<\/p>\n<p style=\"text-align: justify;\">Questa \u00e8 la verit\u00e0 della cronaca dei fatti, e pure \u0096 vale per tutte le amministrazioni nel frattempo succedutesi \u0096 la verit\u00e0 storica: chi ha ereditato la situazione preesistente, di cui certo non era responsabile, comunque non ha fatto nulla di concreto, nei fatti, per invertire la tendenza, quanto meno per avviare il risanamento.<\/p>\n<p style=\"text-align: justify;\">Tutti zitti e buoni sotto la gigantesca cappa di interessi montati dall\u0092Ilva sopra il cielo di Taranto, e pure delle zone del Salento, raggiunte dai miasmi mortiferi per effetto della circolazione dei venti.<\/p>\n<p style=\"text-align: justify;\">***<\/p>\n<p style=\"text-align: justify;\">Geograficamente colpito a morte dall\u0092inizio alla fine, lungo le coste dei due mari, all\u0092inizio dalla pestilenziale centrale di Cerano, alla fine dal disastroso stabilimento dell\u0092Ilva, il Salento proiettato sull\u0092economia contadina, sulla cultura, sul turismo, vacilla. Il colpo definitivo sul suo equilibrio naturale sta per arrivare, se qualcuno, se qualcosa, non far\u00e0 in tempo a fermarlo, prima che sia realizzato, prima che si abbatta rovinoso, e anzi mortale, sulle genti salentine.<\/p>\n<p style=\"text-align: justify;\">Si tratta del gasdotto trans \u0096 adriatico (TAP) il cui sbocco finale, come \u00e8 noto, \u00e8 previsto sulla spiaggia di San Foca.<\/p>\n<p style=\"text-align: justify;\">Basta studiare un po\u0092 le carte, leggere gli atti burocratici ed amministrativi, confrontare le dichiarazioni politiche, approfondire un minimo, per capire facilmente che si tratta di un\u0092opera utile solamente alle societ\u00e0 multinazionali che la costruiscono e la gestiscono; che in termini gestionali se ne potrebbe fare totalmente a meno; che nel Salento non porter\u00e0 nessun tornaconto economico; che agli Italiani tutti non dar\u00e0 beneficio alcuno, come invece promette mentendo e sapendo di mentire il Letta nipote.<\/p>\n<p style=\"text-align: justify;\">E allora, per favore, muoviamoci prima, non dopo.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 poi, quando sar\u00e0 fatto, con l\u0092ecosistema sconvolto, dar\u00e0 ben misera soddisfazione andare ad individuare le responsabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Qui torniamo a Nichi, massimo esponente istituzionale del territorio, pure leader di un partito che nel nome porta il richiamo preciso all\u0092ecologia e teorico di politica e di letteratura.<\/p>\n<p style=\"text-align: justify;\">Sulla Tap Sel e Pd continuano a fare solamente fumo, senza arrosto, in un gioco delle parti, fra piani nazionali e locali, sovrapposti e incastrati in un sostanziale nulla di fatto.<\/p>\n<p style=\"text-align: justify;\">La realt\u00e0 \u00e8 che nei fatti i progetti delle multinazionali sono in avanzata fase di realizzazione.<\/p>\n<p style=\"text-align: justify;\">Nichi Vendola ne \u00e8 responsabile, sia detto, comunque vada a finire, a futura memoria. Intendo essere preciso. Ho scoperto che la Regione Puglia aveva trenta giorni di tempo per bloccare il progetto del Tap presentato presso i suoi uffici e non l\u0092ha fatto, quindi ha fatto scattare il meccanismo del silenzio \u0096 assenso e cio\u00e8 ha di fatto autorizzato i lavori.<\/p>\n<p style=\"text-align: justify;\">Quindi, poi Nichi Vendola potr\u00e0 pure mettersi a scrivere poesie e a rilasciare affascinanti dichiarazioni in merito, ma questo \u00e8, questo lo inchioda, \u0091stavolta ab origine, non come per l\u0092 Ilva a posteriori, \u0091stavolta a monte, prima, fin dalle origini, alle sue responsabilit\u00e0 precise.<\/p>\n<p style=\"text-align: justify;\">Cos\u0092, alla luce della scelta compiuta, al buio dell\u0092autorizzazione concessa, questo tardo romanticismo risulta francamente insopportabile, come il buonismo di maniera, il politicamente corretto ostentato formalmente, a coprire la verit\u00e0 dei fatti.<\/p>\n<p style=\"text-align: justify;\">Di questo Vendola dovrebbe preoccuparsi, se non fosse troppo occupato a rincorrere i suoi pur legittimi sogni di gloria, su scala nazionale, e a dichiarare sempre e comunque, a ogni proposito e sproposito, su motivi e personaggi mille miglia distanti dagli interessi della Puglia e dei Pugliesi.<\/p>\n<p style=\"text-align: justify;\">Continua invece imperterrito a perpetuare la propria immagine naif, ingenua, disincantata, fanciullesca, tardo giovanilistica, che copre i fallimenti della sostanza, e l\u0092occupazione sistematica del potere, che ha scientificamente attuato, dall\u0092energia, alla cultura.<\/p>\n<p style=\"text-align: justify;\">Nicchi Vendola, che ha una sfasatura infantile della politica, ridotta ad affabulazione trasognante, tutta giocata sulle capacit\u00e0 straordinarie nella comunicazione e nella costruzione dell\u0092immagine e quindi del consenso, piena di suggestioni, da incantatore di serpenti, che incanta, appunto, grazie alle sue capacit\u00e0 e cos\u00ec facendo fa dimenticare \u0096 in codesta versione post comunista del nuovo secolo e del nuovo millennio \u0096 i fallimenti di governo, nei fatti concreti che interessano realmente i popoli e le persone.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/07\/dall-ilva-alla-tap-il-vendolismo-malattia-infantile-del-comunismo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/07\/dall-ilva-alla-tap-il-vendolismo-malattia-infantile-del-comunismo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(RdL) Proseguono i provvedimenti anche concreti della magistratura contro l\u0092 Ilva, che, sostanzialmente ancora agevolata, se non protetta, dal governo bi \u0096Lletta, continua ad essere inadempiente sul fronte del reale risanamento, della radicale ristrutturazione della produzione, della tutela dell\u0092ambiente e della salute delle persone. Insomma, il disastro continua. Fino a quando? Fino a quando la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21597,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21596"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21596"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21596\/revisions"}],"predecessor-version":[{"id":21601,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21596\/revisions\/21601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21597"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}