{"id":21658,"date":"2013-11-08T15:10:54","date_gmt":"2013-11-08T15:10:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21658"},"modified":"2013-11-08T15:11:47","modified_gmt":"2013-11-08T15:11:47","slug":"il-cibo-della-taranta-a-eataly-bari","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/08\/il-cibo-della-taranta-a-eataly-bari\/","title":{"rendered":"IL CIBO DELLA TARANTA  A EATALY BARI"},"content":{"rendered":"<p style=\"text-align: left\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/taranta.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/taranta-196x300.jpg\" alt=\"\" width=\"196\" height=\"300\" class=\"alignleft size-medium wp-image-21659\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/taranta-196x300.jpg 196w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/taranta.jpg 655w\" sizes=\"(max-width: 196px) 100vw, 196px\" \/><\/a>Il Cibo della Taranta sbarca a Eataly Bari. Dal 12 al 17 novembre,\u00a0 20 produttori del Salento faranno gustare\u00a0 gratuitamente oltre 100 prodotti,\u00a0 dalle 10 alle 24 nel tempio del gusto.<\/p>\n<p>Entra cos\u00ec nel vivo il progetto di partenariato tra Eataly, Fondazione La Notte della Taranta e Camera di Commercio di Lecce.<\/p>\n<p>I produttori avranno la possibilit\u00e0 di utilizzare i laboratori messi a disposizione da Eataly e vendere la selezione agroalimentare ai clienti che per una settimana apprezzeranno il valore enogastronomico del Salento.<\/p>\n<p>Responsabilit\u00e0, sostenibilit\u00e0 e condivisione sono le parole chiave del progetto che porter\u00e0 nel mondo il volto e la storia di tanti produttori che costituiscono il meglio dell\u2019enogastronomia salentina. Musica e cibo insieme per un viaggio che a Bari segna la sua prima tappa.<\/p>\n<p>Il 14 novembre, all\u2019interno della settimana dedicata al Salento, in programma il concerto dell\u2019Orchestra Popolare \u201cLa Notte della Taranta\u201d.<\/p>\n<p>Saranno la voce di Anna Cinzia Villani, i tamburelli di Carlo \u201cCanaglia\u201d De Pascali e Piero Balsamo, la fisarmonica di Roberto Gemma e la danza di Laura Boccadamo a trasformare il centro Eataly di Bari che guarda a Levante in una piazza che fa festa con i suoni, i colori e i sapori del Salento.<\/p>\n<p>Fantasia e memoria per avviare un dialogo che consenta di raccontare nei centri Eataly del mondo non solo la musica e la danza della tradizione popolare salentina ma anche la biodiversit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella settimana tutta salentina, lo \u201cchef concertatore\u201d Antonio Bufi preparer\u00e0\u00a0 nel Ristorantino del Pesce di Eataly il piatto creato nella prima edizione\u00a0 de \u201cIl Cibo della Taranta\u201d a Melpignano: POLPO.FICODINDIA (il polpo lascia la pignata e punto da fico d\u2019India balla!).<\/p>\n<p>&nbsp;<\/p>\n<p><em>E\u2019 un progetto, quello tra Eataly e La Fondazione La Notte della Taranta, che nasce dall\u2019incontro di storie che hanno percorso parallelamente binari di rispetto per tradizione, storia e cultura di comunit\u00e0-spiega Francesco Farinetti, amministratore delegato di Eataly-storie che saranno narrate mettendo insieme musica e cibo nelle nostre stazioni del gusto, spazio di innumerevoli nuovi incontri. <\/em><\/p>\n<p><em>Abbiamo messo insieme storie e valori dei nostri produttori-aggiunge Massimo Manera, Presidente della Fondazione La Notte della Taranta-convinti che la partnership con l\u2019azienda Farinetti\u00a0 sia un\u2019opportunit\u00e0 di crescita irripetibile, basti pensare che il centro Eataly di New York \u00e8 il quinto luogo pi\u00f9 visitato dopo il MoMA. <\/em><\/p>\n<p><em>Dopo l\u2019incontro che abbiamo promosso a Melpignano tra i produttori e l\u2019A.D. Farinetti per\u00a0 Alfredo Prete Presidente della Camera di Commercio di Lecce,\u00a0 la tappa di Bari \u00e8 fondamentale per individuare nuovi e importanti traguardi per i prodotti salentini che non sono presenti nella catena internazionale di Eataly.\u00a0<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/08\/il-cibo-della-taranta-a-eataly-bari\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/08\/il-cibo-della-taranta-a-eataly-bari\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il Cibo della Taranta sbarca a Eataly Bari. Dal 12 al 17 novembre,\u00a0 20 produttori del Salento faranno gustare\u00a0 gratuitamente oltre 100 prodotti,\u00a0 dalle 10 alle 24 nel tempio del gusto. Entra cos\u00ec nel vivo il progetto di partenariato tra Eataly, Fondazione La Notte della Taranta e Camera di Commercio di Lecce. I produttori avranno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21659,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21658"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21658"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21658\/revisions"}],"predecessor-version":[{"id":21661,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21658\/revisions\/21661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21659"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}