{"id":216807,"date":"2023-06-03T18:38:35","date_gmt":"2023-06-03T16:38:35","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=216807"},"modified":"2023-06-03T18:38:37","modified_gmt":"2023-06-03T16:38:37","slug":"domenica-4-giugno-ultimo-atto-del-campionato-e-festa-per-il-lecce-ma-e-gia-tempo-di-pensare-al-futuro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/03\/domenica-4-giugno-ultimo-atto-del-campionato-e-festa-per-il-lecce-ma-e-gia-tempo-di-pensare-al-futuro\/","title":{"rendered":"DOMENICA 4 GIUGNO, ULTIMO ATTO DEL CAMPIONATO E FESTA PER IL LECCE. MA E&#8217; GIA&#8217; TEMPO DI PENSARE AL FUTURO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"500\" height=\"261\" class=\"wp-image-216808\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mb.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mb.jpg 500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mb-300x157.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n\n\n\n<p>(e.l.) ______ \u201c<em>Questa squadra ha dato tutto. Ha lavorato sodo sin dal primo minuto e lo far\u00e0 anche domani\u00a0<\/em>\u201d.<\/p>\n\n\n\n<p>Cos\u00ec questo pomeriggio al Via del Mare nella consueta conferenza stampa della vigilia l&#8217;allenatore del Lecce Marco Baroni.<\/p>\n\n\n\n<p>Domani, domenica 4 giugno, ultimo atto del campionato, a salvezza ottenuta con un turno di anticipo, si gioca alle 21.00 e sar\u00e0 festa, prima, durante e dopo, per tutta la citt\u00e0, per i tifosi giallorossi.<\/p>\n\n\n\n<p>Intanto il tecnico ha tenuto ad elencare una lunga lista di dati, cifre e considerazioni sull&#8217;obiettivo raggiunto.<\/p>\n\n\n\n<p><em>\u201cLa stagione che stiamo per chiudere va tenuta ben scolpita nella mente per capire le difficolt\u00e0 di questo campionato. La squadra non \u00e8 mai stata negli ultimi tre posti\u201d<\/em>.<\/p>\n\n\n\n<p>Non ha parlato del suo futuro. E&#8217; giusto cos\u00ec.  Il contratto \u00e8 in scadenza, si vedr\u00e0 nei prossimi giorni.<\/p>\n\n\n\n<p><em>\u201cCi sar\u00e0 tempo per le giuste riflessioni\u201d<\/em> &#8211; ha detto.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/03\/domenica-4-giugno-ultimo-atto-del-campionato-e-festa-per-il-lecce-ma-e-gia-tempo-di-pensare-al-futuro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/03\/domenica-4-giugno-ultimo-atto-del-campionato-e-festa-per-il-lecce-ma-e-gia-tempo-di-pensare-al-futuro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ \u201cQuesta squadra ha dato tutto. Ha lavorato sodo sin dal primo minuto e lo far\u00e0 anche domani\u00a0\u201d. Cos\u00ec questo pomeriggio al Via del Mare nella consueta conferenza stampa della vigilia l&#8217;allenatore del Lecce Marco Baroni. Domani, domenica 4 giugno, ultimo atto del campionato, a salvezza ottenuta con un turno di anticipo, si gioca [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":216808,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216807"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=216807"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216807\/revisions"}],"predecessor-version":[{"id":216809,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216807\/revisions\/216809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/216808"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=216807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=216807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=216807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}