{"id":216825,"date":"2023-06-04T14:34:50","date_gmt":"2023-06-04T12:34:50","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=216825"},"modified":"2023-06-04T19:27:23","modified_gmt":"2023-06-04T17:27:23","slug":"drammatico-incidente-stradale-in-autostrada-pullman-partito-da-lecce-finisce-in-un-burrone","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/04\/drammatico-incidente-stradale-in-autostrada-pullman-partito-da-lecce-finisce-in-un-burrone\/","title":{"rendered":"DRAMMATICO INCIDENTE STRADALE IN AUTOSTRADA, PULLMAN PARTITO DA LECCE FINISCE IN UN BURRONE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1200\" class=\"wp-image-216826\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mexx.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mexx.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mexx-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mexx-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mexx-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mexx-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/mexx-400x300.jpg 400w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p>(e.l.) ______&nbsp; Queta mattina verso le 4.15 sull&#8217;autostrada A 16  Napoli  &#8211; Canosa, nel territorio del comune di Vallesaccarda, in provincia di Avellino, c&#8217;\u00e8 stato un drammatico incidente stradale.<\/p>\n\n\n\n<p>Il bilancio \u00e8 di un morto e di ventitr\u00e8 feriti, di cui uno grave, e dei quali alcuni  si trovano attualmente ricoverati negli ospedali di Avellino, Benevento e Ariano Irpino. La vittima \u00e8 un cittadiono extracomunitario, di cui non si conosce l&#8217;identit\u00e0.<\/p>\n\n\n\n<p>Per cause ancora da accertare, c&#8217;\u00e8 stato un tamponamento a catena, che ha coinvolto cinque macchine. Il pullman della Flixbus, che portava trentasei passeggeri, oltre ai due atisti, era partito da Lecce alle 23 ed era  diretto a Roma, \u00e8 finito in un burrone al lato della carreggiata autostradale.<\/p>\n\n\n\n<p>Sono in corso di svolgimento le ondagini delle Polizia Stradale per accertare l&#8217;esatta dinamica di quanto accaduto e stabilirne le cause.<\/p>\n\n\n\n<p>L&#8217;autostrada \u00e8 stata riaperta al traffico alle 9, a completamento dlle operazioni di soccorso dei sanitari del 118, e dei Vigili del Fuoco (nella foto) .<\/p>\n\n\n\n<p>&nbsp;<strong>\u201d<\/strong><em>L&#8217;autista ha lanciato un grido<\/em> &#8211; ha raccontato Siria, una ragazza di San Michele Salentino &#8211; <em>poi ha virato verso sinistra finendo sul guardrail. C&#8217;\u00e8 stato un testa coda prima di travolgere un\u2019auto ferma sulla carreggiata per poi finire nella scarpata<\/em><strong>\u201d<\/strong>.<\/p>\n\n\n\n<p>Sono numerose le testimonianze condivise sui social dei passeggeri del pullman. Per esempio Biagio Mennella, di Copertino, ha postato sul suo diario di Facebook queste parole<strong>:<\/strong><\/p>\n\n\n\n<p>&nbsp;<em>\u201cMiracolati: Insieme a mio figlio e alla sua ragazza ed altre 36 persone ci siamo capovolti con il flixbus sfondando il guardrail e capovolgendoci in una scarpata. Fortuna che l&#8217;automezzo posizionato in senso verticale \u00e8 stato frenato dalla boscaglia e la rottura di un finestrino ci ha consentito di uscire quasi tutti dall&#8217;abitacolo. All&#8217;interno scene di panico, abbiamo gattonato come dei soldati in una trincea fino ad uscire dell&#8217;abitacolo. I soccorsi vigili del fuoco, autoambulanze ed elicottero sono giunti sul posto dopo circa 20 minuti. A margine mentre ci preoccupavamo per le persone \u00e8 passato un furgone di colore verde senza manco fermarsi\u201d.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/04\/drammatico-incidente-stradale-in-autostrada-pullman-partito-da-lecce-finisce-in-un-burrone\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/04\/drammatico-incidente-stradale-in-autostrada-pullman-partito-da-lecce-finisce-in-un-burrone\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______&nbsp; Queta mattina verso le 4.15 sull&#8217;autostrada A 16 Napoli &#8211; Canosa, nel territorio del comune di Vallesaccarda, in provincia di Avellino, c&#8217;\u00e8 stato un drammatico incidente stradale. Il bilancio \u00e8 di un morto e di ventitr\u00e8 feriti, di cui uno grave, e dei quali alcuni si trovano attualmente ricoverati negli ospedali di Avellino, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":216826,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216825"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=216825"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216825\/revisions"}],"predecessor-version":[{"id":216845,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216825\/revisions\/216845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/216826"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=216825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=216825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=216825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}