{"id":21687,"date":"2013-11-11T09:04:35","date_gmt":"2013-11-11T09:04:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21687"},"modified":"2013-11-11T09:15:20","modified_gmt":"2013-11-11T09:15:20","slug":"gli-zombi-di-alleanza-nazionale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/11\/gli-zombi-di-alleanza-nazionale\/","title":{"rendered":"GLI ZOMBI DI ALLEANZA NAZIONALE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/images-1.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/images-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-21691\" \/><\/a>\u00ab \u00c8 giusto chiedere alla destra italiana di affermare senza reticenza che l&#8217;antifascismo fu un momento storicamente essenziale per il ritorno dei valori democratici che il fascismo aveva conculcato. \u00bb. Lo sottoscrissero tantissimi,a Fiuggi nel gennaio 1995, non solo Fini.<br \/>\nGli stessi che, \u00a0grazie a Berlusconi, da allora fino ad\u00a0<a href=\"https:\/\/webmaildomini.aruba.it\/\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r1b17m7.20120629_1045?lang=it&amp;flavour=orange&amp;theme=ext_aruba\/classic&amp;useSprite=0\">oggi<\/a>\u00a0sono stati poi premiati con incarichi politici da ministro fino ad amministratore pubblico e privato. Rai compresa.<br \/>\nFecero una scelta consapevole e graditissima, allora, gli antifascisti di alleanza nazionale. Si inserirono definitivamente nello &#8220;arco costituzionale&#8221; costituendo un &#8220;plenum&#8221; per questa repubblica democratica ed antifascista, nata dalla resistenza.<br \/>\nBen per loro. E per i sodali democratici che poterono cos\u00ec continuare indisturbati a sgovernare meglio l&#8217;Italia e gli italiani.<br \/>\nEffettivamente la partitocrazia al potere non correva pi\u00f9 il rischio di trovarsi &#8220;a destra&#8221; una forza di certo non fascista ma, neppure, dichiaratamente &#8220;anti&#8221;.<br \/>\nEsattamente come, a sinistra, si mirava a far fuori chiunque avesse il coraggio di richiamarsi al marxismo comunista.<br \/>\n<a href=\"https:\/\/webmaildomini.aruba.it\/\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r1b17m7.20120629_1045?lang=it&amp;flavour=orange&amp;theme=ext_aruba\/classic&amp;useSprite=0\">Oggi<\/a>\u00a0qualcuno riprova a richiamare in vita il cadavere di alleanza nazionale.<br \/>\nStregoni voodoo, pochi in verit\u00e0, hanno ieri iniziato i riti per ritrovare zombie sufficienti a superare gli sbarramenti elettorali previsti per le prossime elezioni.<br \/>\nAltri, con la presenza dello (ex) gran sacerdote Fini, tenteranno tra poco la stessa operazione.<br \/>\nConsiderando che nessuna abiura della abiura di Fiuggi \u00e8 stata proposta da qualcuno, analizzo l&#8217;evento (che parolona !) per quello che \u00e8. Un tentativo da parte di chi ha perduto elezioni ed elettorato per rimettersi in pista e raccattare qualche posizione di potere.<br \/>\nNessuna novit\u00e0, quindi, nello &#8220;arco costituzionale&#8221;.<br \/>\nAntifascisti si erano dichiarati da buoni italiani traditori. Antifascisti restano.<br \/>\nE chi vuole intendere abbia le idee chiare.<\/p>\n<p>P.s. mi rendo perfettamente conto che quanto sopra potrebbe sembrare, a prima lettura, di scarso interesse per chi riceve e legge. Ma, secondo me, serve a chiarire un punto chiave del perch\u00e9, accanto a decine di altre motivazioni, ce ne sia pure una che porta la gente a non votare.<br \/>\nLa partitocrazia democratica e resistenziale ha fallito e tante persone riteniamo sacrosanto non avere niente a che fare con chiunque la rappresenti.<\/p>\n<p>Grazie per l&#8217;attenzione.<br \/>\nVincenzo Mannello<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/11\/gli-zombi-di-alleanza-nazionale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/11\/gli-zombi-di-alleanza-nazionale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00ab \u00c8 giusto chiedere alla destra italiana di affermare senza reticenza che l&#8217;antifascismo fu un momento storicamente essenziale per il ritorno dei valori democratici che il fascismo aveva conculcato. \u00bb. Lo sottoscrissero tantissimi,a Fiuggi nel gennaio 1995, non solo Fini. Gli stessi che, \u00a0grazie a Berlusconi, da allora fino ad\u00a0oggi\u00a0sono stati poi premiati con incarichi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21691,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21687"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21687"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21687\/revisions"}],"predecessor-version":[{"id":21689,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21687\/revisions\/21689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21691"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}