{"id":216890,"date":"2023-06-06T16:24:08","date_gmt":"2023-06-06T14:24:08","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=216890"},"modified":"2023-06-06T16:24:11","modified_gmt":"2023-06-06T14:24:11","slug":"controlli-della-finanza-a-taranto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/06\/controlli-della-finanza-a-taranto\/","title":{"rendered":"CONTROLLI DELLA FINANZA A TARANTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1920\" height=\"1308\" class=\"wp-image-216891\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/06062023_092139_06.06.2023-sicurezza-prodotti.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/06062023_092139_06.06.2023-sicurezza-prodotti.jpg 1920w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/06062023_092139_06.06.2023-sicurezza-prodotti-300x204.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/06062023_092139_06.06.2023-sicurezza-prodotti-1024x698.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/06062023_092139_06.06.2023-sicurezza-prodotti-768x523.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/06062023_092139_06.06.2023-sicurezza-prodotti-1536x1046.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n\n\n\n<p>(e.l.) ______\u00a0Nel corso di controlli specifici militari del Comando Provinciale di Taranto hanno sequestrato oltre 1 milione e 500 mila prodotti, tra i quali cosmetici privi delle prescritte etichette di sicurezza, nonch\u00e9 bigiotteria e articoli in plastica per uso alimentare privi delle informazioni previste dal \u201cCodice del Consumo\u201d.<\/p>\n\n\n\n<p>Tale provvedimento normativo stabilisce, infatti, che i prodotti destinati al consumatore, commercializzati sul territorio nazionale, debbano riportare le indicazioni relative alla denominazione legale o merceologica del prodotto, all\u2019identit\u00e0 del produttore, all\u2019eventuale presenza di sostanze in grado di causare potenziale danno al consumatore, nonch\u00e9 ai materiali impiegati e ai metodi di lavorazione.<\/p>\n\n\n\n<p>All\u2019esito degli approfondimenti investigativi svolti dalle Fiamme Gialle, i titolari delle tre rivendite interessate dai controlli sono stati segnalati alla competente Autorit\u00e0 amministrativa.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/06\/controlli-della-finanza-a-taranto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/06\/controlli-della-finanza-a-taranto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0Nel corso di controlli specifici militari del Comando Provinciale di Taranto hanno sequestrato oltre 1 milione e 500 mila prodotti, tra i quali cosmetici privi delle prescritte etichette di sicurezza, nonch\u00e9 bigiotteria e articoli in plastica per uso alimentare privi delle informazioni previste dal \u201cCodice del Consumo\u201d. Tale provvedimento normativo stabilisce, infatti, che i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":216891,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216890"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=216890"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216890\/revisions"}],"predecessor-version":[{"id":216892,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/216890\/revisions\/216892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/216891"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=216890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=216890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=216890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}