{"id":217094,"date":"2023-06-10T14:29:27","date_gmt":"2023-06-10T12:29:27","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=217094"},"modified":"2023-10-31T14:59:42","modified_gmt":"2023-10-31T13:59:42","slug":"slot-machines-taroccate-a-taranto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/10\/slot-machines-taroccate-a-taranto\/","title":{"rendered":"SLOT MACHINES TAROCCATE A TARANTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"563\" class=\"wp-image-217095\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/10062023_084644_10.06.2023-giochi-illegali.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/10062023_084644_10.06.2023-giochi-illegali.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/10062023_084644_10.06.2023-giochi-illegali-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/10062023_084644_10.06.2023-giochi-illegali-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p>(e.l.) ______ La Guardia di Finanza di Taranto ha sequestrato undici apparecchi da gioco installati in un circolo ricreativo e in due sale giochi, recanti \u2018schede gioco\u2019 modificate, risultate non collegate alla rete telematica dell\u2019Amministrazione Autonoma dei Monopoli di Stato, nonch\u00e9 strumentazioni informatiche, scontrini di giocate e denaro contante profitto del gioco illegale.<\/p>\n\n\n\n<p>I tre titolari sono state denunciati a piede libero perch\u00e9 sprovvisti di autorizzazioni amministrative e per aver consentito la raccolta abusiva di scommesse sportive. ______\u00a0<\/p>\n\n\n\n<p>AGGIORNAMENTO  del 31 ottobre 2023.<\/p>\n\n\n\n<p>Nei giorni scorsi le Fiamme Gialle della Compagnia di Manduria hanno eseguito una serie di controlli a<br>contrasto del gioco illegale, individuando e sottoponendo a sequestro amministrativo, in un bar\/caffetteria di Maruggio, una \u201cslot machine\u201d non collegata alla rete dell\u2019Agenzia delle Dogane e Monopoli. In assenza del previsto collegamento telematico le giocate effettuate attraverso tale apparecchio non sono state rendicontate all\u2019Amministrazione Finanziaria, permettendo al suo titolare di evadere il prelievo unico erariale, imposta che sar\u00e0 precisamente quantificata al termine di una specifica attivit\u00e0 ispettiva.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/10\/slot-machines-taroccate-a-taranto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/10\/slot-machines-taroccate-a-taranto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ La Guardia di Finanza di Taranto ha sequestrato undici apparecchi da gioco installati in un circolo ricreativo e in due sale giochi, recanti \u2018schede gioco\u2019 modificate, risultate non collegate alla rete telematica dell\u2019Amministrazione Autonoma dei Monopoli di Stato, nonch\u00e9 strumentazioni informatiche, scontrini di giocate e denaro contante profitto del gioco illegale. I tre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":217095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217094"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=217094"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217094\/revisions"}],"predecessor-version":[{"id":222625,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217094\/revisions\/222625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/217095"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=217094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=217094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=217094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}