{"id":217467,"date":"2023-06-19T14:02:06","date_gmt":"2023-06-19T12:02:06","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=217467"},"modified":"2023-06-19T14:02:22","modified_gmt":"2023-06-19T12:02:22","slug":"pensilina-rimasta-senza-panchina","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/19\/pensilina-rimasta-senza-panchina\/","title":{"rendered":"PENSILINA RIMASTA SENZA PANCHINA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"483\" height=\"348\" class=\"wp-image-217468\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/pensilina-senza-panchina-1.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/pensilina-senza-panchina-1.png 483w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/pensilina-senza-panchina-1-300x216.png 300w\" sizes=\"(max-width: 483px) 100vw, 483px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. Giovanni D&#8217;Agata ci manda il seguente comunicato  ______<\/p>\n\n\n\n<p>La fermata dell\u2019autobus in viale Otranto senza panchina. Lo \u201cSportello dei Diritti\u201d denuncia il disservizio per le lunghe attese in piedi: \u201cCi pensano i cittadini piazzandoci degli sgabelli da campeggio\u201d<\/p>\n\n\n\n<p>Disagi per i passeggeri delle linee urbane di Lecce alla fermata di viale Otranto nei pressi di piazza Italia per le attese infinite senza panchina. Un disservizio che i cittadini, anziani, disabili e turisti stanno, loro malgrado, gestendo con creativit\u00e0. Per l\u2019attesa, sovente lunga, i cittadini portano delle sedie, sgabellini da campeggio o si \u201caccomodano\u201d lungo il bordo delle aiuole scambiate per \u00ablatrine canine\u00bb. Giovanni D&#8217;Agata, presidente dello \u201c<a href=\"http:\/\/www.sportellodeidiritti.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sportello dei Diritti<\/a>\u201d, che ha ricevuto le lamentele dei tanti tra turisti e cittadini, denuncia la situazione e chiede un intervento all\u2019amministrazione comunale e a S.G.M. affinch\u00e8 ogni fermata venga dotata di idonei sedili anche perch\u00e9 la stagione turistica \u00e8 gi\u00e0 ben avviata e non \u00e8 un belvedere quanto accade che non \u00e8 neanche un bel biglietto da visita per la citt\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/19\/pensilina-rimasta-senza-panchina\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/19\/pensilina-rimasta-senza-panchina\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Giovanni D&#8217;Agata ci manda il seguente comunicato ______ La fermata dell\u2019autobus in viale Otranto senza panchina. Lo \u201cSportello dei Diritti\u201d denuncia il disservizio per le lunghe attese in piedi: \u201cCi pensano i cittadini piazzandoci degli sgabelli da campeggio\u201d Disagi per i passeggeri delle linee urbane di Lecce alla fermata di viale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217467"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=217467"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217467\/revisions"}],"predecessor-version":[{"id":217469,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217467\/revisions\/217469"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=217467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=217467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=217467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}