{"id":217526,"date":"2023-06-20T18:15:23","date_gmt":"2023-06-20T16:15:23","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=217526"},"modified":"2023-06-20T18:18:39","modified_gmt":"2023-06-20T16:18:39","slug":"il-premio-isabella-2023-riconoscimento-speciale-a-persone-speciali-a-lecce-venerdi-23","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/20\/il-premio-isabella-2023-riconoscimento-speciale-a-persone-speciali-a-lecce-venerdi-23\/","title":{"rendered":"IL \u201cPremio Isabella 2023\u201d, PROMOSSO DALLE &#8216;GIUBBE VERDI&#8217; DI COPERTINO, RICONOSCIMENTO SPECIALE A PERSONE SPECIALI, A LECCE VENERDI&#8217; 23"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" class=\"wp-image-217527\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-conferenza-foto-2.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-conferenza-foto-2.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-conferenza-foto-2-300x225.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-conferenza-foto-2-768x576.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-conferenza-foto-2-400x300.jpeg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. L&#8217;ufficio stampa della Provincia di Lecce ci manda il seguente comunicato con il resonconto della conferenza stampa di questa mattina ______<\/p>\n\n\n\n<p><strong>UN RICONOSCIMENTO SPECIALE A PERSONE SPECIALI:<\/strong> <strong>AL CIRCOLO CITTADINO DI LECCE<\/strong><\/p>\n\n\n\n<p><strong>ARRIVA IL \u201cPREMIO ISABELLA 2023\u201d<\/strong> <strong>DEDICATO A PERSONE CON DISABILITA\u2019<\/strong><\/p>\n\n\n\n<p>Sar\u00e0 un evento \u201cfuori dal comune\u201d quello che andr\u00e0 in scena venerd\u00ec prossimo 23 giugno, alle ore 20.30, nel Circolo cittadino di Lecce. E\u2019 il \u201c<strong>Premio Isabella 2023<\/strong>\u201d per le incredibili \u201ceccellenze italiane\u201d, promosso dall\u2019associazione di volontariato <strong>Giubbe Verdi Compagnia Salento di Copertino<\/strong>, per <strong>riconoscere e premiare i risultati e i traguardi delle persone con disabilit\u00e0<\/strong>.<\/p>\n\n\n\n<p>Patrocinata da <strong><u>Provincia di Lecce<\/u><\/strong> e Regione Puglia, la seconda edizione \u00e8 stata presentata questa mattina a&nbsp; Palazzo Adorno a Lecce, dal vice presidente della Provincia <strong>Antonio Leo<\/strong>, dal direttore tecnico organizzativo <strong>Gianluca Cal\u00f2<\/strong>, dal direttore artistico <strong>Maria Antonietta Vacca<\/strong> e <strong>dai ragazzi del direttivo delle Giubbe Verdi Chiara Rotundo, Domenico D\u2019Agostino <\/strong>e <strong>Giulietta Fratinardo<\/strong>.<\/p>\n\n\n\n<p>Nella serata, che vedr\u00e0 la partecipazione anche del noto avvocato <strong>Anna Maria Bernardini De Pace<\/strong> in qualit\u00e0 di madrina, saranno premiati candidati prevalentemente salentini, scelti attraverso un\u2019accurata ricerca, esempi di resilienza e che si sono contraddistinti in ambito sportivo, culturale e lavorativo. \u201cI premi, che saranno assegnati nel corso della straordinaria serata, hanno l\u2019obiettivo di sensibilizzare e aprire a una nuova visione della disabilit\u00e0, facendo emergere prima ancora dei limiti, i punti di forza e la gioia di vivere di queste persone, nel perseguire e raggiungere i propri sogni e obiettivi, nonostante le numerose barriere che incontrano sul loro cammino\u201d, ha evidenziato <strong>Antonio Leo<\/strong>, vicepresidente della Provincia di Lecce.&nbsp;<\/p>\n\n\n\n<p>Ecco i candidati 2023: <strong>Pierluigi Maggio<\/strong>, originario di Muro Leccese, campione italiano paralimpico Fispes e autore dell\u2019ebook \u201c4 importanti regole per una vita sana e consapevole\u201d; <strong>Brigida Nigro<\/strong>, giovane promessa del mondo dell\u2019equitazione, originaria di Latiano, che a soli 27 anni vanta una carriera di successo; <strong>Davide Dongiovanni,<\/strong> leccese laureato in Scienze della comunicazione, conduce su radio Portalecce il programma \u201cIl mio punto di vista\u201d ed \u00e8 vicepresidente, allenatore e giocatore della Ascus Lecce; <strong>Serena Grasso<\/strong>, donna determinata, laureata in Scienze Politiche e iscritta alla facolt\u00e0 di Psicologia, ha fondato \u201cPiacere per tutti\u201d, un\u2019associazione che si occupa del benessere sessuale anche delle persone con disabilit\u00e0; <strong>Paolo De Vizzi<\/strong>, atleta originario di Manduria, ha all\u2019attivo una serie di record mondiali di immersioni, di permanenza e di profondit\u00e0, e nel 2016 \u00e8 stato il primo uomo al mondo a rimanere sott\u2019acqua per 51 ore e 56 minuti a 10 metri. &nbsp;<\/p>\n\n\n\n<p>Il premio va, dunque, a quei ragazzi che hanno saputo trasformare le loro difficolt\u00e0 in opportunit\u00e0: non a caso una <strong>fenice<\/strong> \u00e8 il simbolo del premio, dedicato alla docente e avvocato <strong>Isabella Bellisario Bernardini De Pace<\/strong>, milanese con origini pugliesi, che ha trascorso gli ultimi trent\u2019anni della sua lunga vita (\u00e8 scomparsa a 95 anni) a Lecce. Questa donna straordinaria nel lavoro e nella vita privata (4 figli, 16 nipoti, 15 pronipoti) era innamorata dei ragazzi speciali delle Giubbe Verdi e ha partecipato attivamente alla loro formazione e ai loro successi.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Tra le <strong>categorie<\/strong> anche una \u201cspeciale\u201d, relativa all\u2019<strong>attivismo sociale<\/strong> per la disabilit\u00e0, rivolta ai candidati che si sono distinti per aver acceso i riflettori su tutte quelle problematiche e difficolt\u00e0 che una persona con disabilit\u00e0 si trova ad affrontare nella quotidianit\u00e0, mettendo cos\u00ec la loro esperienza al servizio sia di chi \u00e8 in una condizione simile sia di quanti, per un motivo o per un altro, si trovano a dover approcciare a questo mondo.<\/p>\n\n\n\n<p>La serata di premiazione vedr\u00e0 la <strong>partecipazione inclusiva dei ragazzi speciali<\/strong> che cureranno il servizio d\u2019ordine e hostess. In programma anche momenti di musica inclusiva e danza, grazie alla partecipazione di <strong>Riccardo D\u2019Ostuni<\/strong> con il suo inedito \u201cAll\u2019ombra di un pensiero\u201d, del balletto di <strong>Letizia Durante<\/strong> e le sue allieve, dei <strong>Cori Mani bianche e Armoniasonora<\/strong> dell\u2019associazione Junior Band aps di Melissano.<\/p>\n\n\n\n<p>\u201cA presentare la serata sar\u00e0 una persona con una sua unicit\u00e0, proprio perch\u00e9 il mondo dello spettacolo \u00e8 rappresentato nella maggior parte delle volte, se non esclusivamente, da normodotati, mentre noi stiamo cercando di fare uno spettacolo fuori dal comune\u201d, ha spiegato il direttore tecnico organizzativo <strong>Gianluca Cal\u00f2<\/strong>, riferendosi a <strong>Maria De Giovanni<\/strong>,presidente dell\u2019associazione Sunrise onlus e promotrice del progetto \u201cIl mare di tutti\u201d, da anni impegnata nel sociale, unica donna del Salento ad aver ricevuto, il 2 giugno scorso, l\u2019ambito riconoscimento di \u201cCommendatore ordine al merito della Repubblica italiana\u201d.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1097\" height=\"1600\" class=\"wp-image-217528\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-locandina.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-locandina.jpeg 1097w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-locandina-206x300.jpeg 206w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-locandina-702x1024.jpeg 702w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-locandina-768x1120.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/Premio-Isabella-locandina-1053x1536.jpeg 1053w\" sizes=\"(max-width: 1097px) 100vw, 1097px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/20\/il-premio-isabella-2023-riconoscimento-speciale-a-persone-speciali-a-lecce-venerdi-23\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/20\/il-premio-isabella-2023-riconoscimento-speciale-a-persone-speciali-a-lecce-venerdi-23\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L&#8217;ufficio stampa della Provincia di Lecce ci manda il seguente comunicato con il resonconto della conferenza stampa di questa mattina ______ UN RICONOSCIMENTO SPECIALE A PERSONE SPECIALI: AL CIRCOLO CITTADINO DI LECCE ARRIVA IL \u201cPREMIO ISABELLA 2023\u201d DEDICATO A PERSONE CON DISABILITA\u2019 Sar\u00e0 un evento \u201cfuori dal comune\u201d quello che andr\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":217527,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217526"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=217526"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217526\/revisions"}],"predecessor-version":[{"id":217533,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217526\/revisions\/217533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/217527"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=217526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=217526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=217526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}