{"id":21773,"date":"2013-11-11T19:04:16","date_gmt":"2013-11-11T19:04:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21773"},"modified":"2013-11-11T19:04:16","modified_gmt":"2013-11-11T19:04:16","slug":"nati-per-leggere-a-cavallino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/11\/nati-per-leggere-a-cavallino\/","title":{"rendered":"NATI PER LEGGERE A CAVALLINO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/06\/260px-Cavallino_Piazza_Castromediano.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/06\/260px-Cavallino_Piazza_Castromediano-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-18193\" \/><\/a>Si terr\u00e0 <strong>Marted\u00ec 12 Novembre 2013<\/strong>, alle <strong>ore 10.30<\/strong> presso la <strong>Sala Lettura della Biblioteca Comunale \u201cGino Rizzo\u201d di Cavallino<\/strong> la conferenza stampa con cui saranno illustrate le attivit\u00e0 della stessa Biblioteca per l\u2019anno 2013\/2014, tra le quali lo Spazio Mostre, le attivit\u00e0 di laboratori pomeridiani, la partecipazione ad eventi nazionali (<em>Il maggio dei libri<\/em>), la proposta di protocollo d\u2019intesa con la Asl di Lecce per la promozione della lettura dei libri in spazi non istituzionali (consultori familiari, ambulatori pediatrici), gli sviluppi del Progetto \u00abNati per leggere a Cavallino\u00bb e la rete territoriale (famiglie, pediatri, nidi, scuole), la presentazione del gruppo di lettori volontari.<\/p>\n<p>Alla conferenza parteciperanno il <strong>Sindaco della Citt\u00e0 di Cavallino Avv. Michele Lombardi, <\/strong>l\u2019<strong>Assessore alla Cultura On. Avv. Gaetano Gorgoni, <\/strong>il <strong>dottor Rodolfo Rollo, <\/strong>Direttore del Distretto Socio Sanitario della Asl di Lecce, la <strong>Responsabile della Biblioteca <\/strong><strong>\u00ab<\/strong><strong>Gino Rizzo<\/strong><strong>\u00bb<\/strong><strong> dottoressa Giovanna Rosato<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/11\/nati-per-leggere-a-cavallino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/11\/nati-per-leggere-a-cavallino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Si terr\u00e0 Marted\u00ec 12 Novembre 2013, alle ore 10.30 presso la Sala Lettura della Biblioteca Comunale \u201cGino Rizzo\u201d di Cavallino la conferenza stampa con cui saranno illustrate le attivit\u00e0 della stessa Biblioteca per l\u2019anno 2013\/2014, tra le quali lo Spazio Mostre, le attivit\u00e0 di laboratori pomeridiani, la partecipazione ad eventi nazionali (Il maggio dei libri), [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18193,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21773"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21773"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21773\/revisions"}],"predecessor-version":[{"id":21774,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21773\/revisions\/21774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/18193"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}