{"id":217748,"date":"2023-06-26T19:18:26","date_gmt":"2023-06-26T17:18:26","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=217748"},"modified":"2023-06-26T19:27:51","modified_gmt":"2023-06-26T17:27:51","slug":"217748","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/26\/217748\/","title":{"rendered":"IL PROCESSO TAP VA AVANTI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1567\" class=\"wp-image-217753\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/AUBU-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/AUBU-scaled.jpg 2560w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/AUBU-300x184.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/AUBU-1024x627.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/AUBU-768x470.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/AUBU-1536x940.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/06\/AUBU-2048x1254.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n\n\n\n<p>(g.p.) ______\u00a0\u00a0Nuova udienza questa mattina nell&#8217;aula bunker di Borgo San Nicola (nella foto) del processo Tap, che, dopo precedenti rinvii, era ricominciato l&#8217;8 giugno scorso, sempre con le audizioni tei testi dell&#8217;accusa, sostenuta dal pm Alessandro Prontera, e sempre con il giudice unico Maria Francesca Mariano,  che si temeva dovesse essere destinata ad altro incarico.<\/p>\n\n\n\n<p>Il teste previsto per oggi non si \u00e8 presentato in aula, dove si doveva parlare uno dei principali capi di accusa a carico di Tap, relativo all&#8217;inquinamento della zona del cantiere di San Basilio.<\/p>\n\n\n\n<p>L\u2019 avvocato\u00a0Angelo Nanni, del collegio difensivo, ha chiesto un ulteriore rinvio, rigettato per\u00f2 dal giudice &#8211;  \u201c<em>Assolutamente no<\/em>\u201d &#8211; che ha fissato la prossima udienza per gioved\u00ec 13 luglio. ______<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>LA RICERCA nei nostri due ultimi articoli, del 23 marzo e del 13 aprile scorsi<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"fwRuJKIdOo\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/23\/ludienza-di-questa-mattinadel-processo-tap-e-battaglia-legale-sulla-validita-delle-autorizzazioni\/\">L&#8217;UDIENZA DI QUESTA MATTINA DEL PROCESSO TAP. E&#8217; BATTAGLIA LEGALE SULLA VALIDITA&#8217; DEI PERMESSI<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;L&#8217;UDIENZA DI QUESTA MATTINA DEL PROCESSO TAP. E&#8217; BATTAGLIA LEGALE SULLA VALIDITA&#8217; DEI PERMESSI&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/03\/23\/ludienza-di-questa-mattinadel-processo-tap-e-battaglia-legale-sulla-validita-delle-autorizzazioni\/embed\/#?secret=U9JJuqntTP#?secret=fwRuJKIdOo\" data-secret=\"fwRuJKIdOo\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"OUGe9lUCmC\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/04\/13\/legittimo-impedimento-di-due-imputati-salta-ludienza-di-questa-mattina-del-processo-tap\/\">LEGITTIMO IMPEDIMENTO DI DUE IMPUTATI, SALTA L&#8217;UDIENZA DI QUESTA MATTINA DEL PROCESSO TAP<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;LEGITTIMO IMPEDIMENTO DI DUE IMPUTATI, SALTA L&#8217;UDIENZA DI QUESTA MATTINA DEL PROCESSO TAP&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/04\/13\/legittimo-impedimento-di-due-imputati-salta-ludienza-di-questa-mattina-del-processo-tap\/embed\/#?secret=8iodEX27UM#?secret=OUGe9lUCmC\" data-secret=\"OUGe9lUCmC\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/26\/217748\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/06\/26\/217748\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.) ______\u00a0\u00a0Nuova udienza questa mattina nell&#8217;aula bunker di Borgo San Nicola (nella foto) del processo Tap, che, dopo precedenti rinvii, era ricominciato l&#8217;8 giugno scorso, sempre con le audizioni tei testi dell&#8217;accusa, sostenuta dal pm Alessandro Prontera, e sempre con il giudice unico Maria Francesca Mariano, che si temeva dovesse essere destinata ad altro incarico. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":217753,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217748"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=217748"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217748\/revisions"}],"predecessor-version":[{"id":217754,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/217748\/revisions\/217754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/217753"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=217748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=217748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=217748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}