{"id":218053,"date":"2023-07-03T12:11:00","date_gmt":"2023-07-03T10:11:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218053"},"modified":"2023-07-03T14:27:16","modified_gmt":"2023-07-03T12:27:16","slug":"rapina-a-mano-armata-bottino-misero","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/03\/rapina-a-mano-armata-bottino-misero\/","title":{"rendered":"RAPINA A MANO ARMATA, BOTTINO MISERO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"512\" height=\"282\" class=\"wp-image-218054\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/unnamed-1-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/unnamed-1-1.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/unnamed-1-1-300x165.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>(e.l.) ______&nbsp;Ieri sera a Nard\u00f2 c&#8217;\u00e8 stata una rapina presso il minimarket \u201cPosto di Blocco\u201d, sulla strada per la marina di Santa Caterina.<\/p>\n\n\n\n<p>Un giovane armato di pistola e a volto coperto da un passamontagna si \u00e8 fatto consegnare i soldi della cassa &#8211; circa 100 euro -ed \u00e8 poi fuggito a bordo di una Fiat 127 guidata da un complice.<\/p>\n\n\n\n<p>Indagini della Polizia di Stato del Commissariato di Nard\u00f2 in corso di svolgimento.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/03\/rapina-a-mano-armata-bottino-misero\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/03\/rapina-a-mano-armata-bottino-misero\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______&nbsp;Ieri sera a Nard\u00f2 c&#8217;\u00e8 stata una rapina presso il minimarket \u201cPosto di Blocco\u201d, sulla strada per la marina di Santa Caterina. Un giovane armato di pistola e a volto coperto da un passamontagna si \u00e8 fatto consegnare i soldi della cassa &#8211; circa 100 euro -ed \u00e8 poi fuggito a bordo di una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218054,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218053"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218053"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218053\/revisions"}],"predecessor-version":[{"id":218058,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218053\/revisions\/218058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218054"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}