{"id":218114,"date":"2023-07-06T00:02:00","date_gmt":"2023-07-05T22:02:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218114"},"modified":"2023-07-05T18:22:04","modified_gmt":"2023-07-05T16:22:04","slug":"novita-editoriali-ultimi-studi-sul-fenomeno-del-tarantismo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/06\/novita-editoriali-ultimi-studi-sul-fenomeno-del-tarantismo\/","title":{"rendered":"NOVITA\u2019 EDITORIALI \/ ULTIMI STUDI SUL FENOMENO DEL TARANTISMO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"659\" height=\"455\" class=\"wp-image-218115\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Taranta-tarantata.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Taranta-tarantata.jpg 659w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Taranta-tarantata-300x207.jpg 300w\" sizes=\"(max-width: 659px) 100vw, 659px\" \/><\/p>\n\n\n\n<p>di <strong>Raffaele Polo ______\u00a0<\/strong><\/p>\n\n\n\n<p>In francese, il termine &#8216;transe&#8217; indica specificatamente l&#8217;ansia, l&#8217;angoscia. E, in questo contesto, un nuovo misticismo contemporaneo fa capolino in questa raccolta di saggi che intreccia i significati legati al mito della \u201ctarantola\u201d alla simbologia magnogreca e paleomediterranea. Uno sguardo storiografico e antropologico illumina il rituale sincretico del tarantismo decifrandone i lati oscuri attraverso nuovi documenti e recenti scoperte.<\/p>\n\n\n\n<p><br>Otto importanti studiosi italiani ripartono dalla grande lezione di Ernesto De Martino per scandagliare l\u2019inquietante universo dell\u2019animale mitico ripercorrendo il dibattito medioevale sui veleni, la magia naturale e la stregoneria, la medicina iatromeccanicistica alle soglie dell\u2019illuminismo e le sue nuove configurazioni nell\u2019epoca della postmodernit\u00e0.<\/p>\n\n\n\n<p>Sono decisamente interessanti gli interventi di E.Imbriani, G.Salvatore, B.Fantini, G.L. Di Mitri, M.R. Tambl\u00e8, V.Lanternari, P.Apolito, G.Mina raccolti da Besa in questo <em><strong>\u201cTranse guarigione mito Antropologia e storia del tarantismo\u201d<\/strong><\/em> (pagine 255, euro 17). Un testo agevole e leggibile, che spiega, rivela e interpreta aspetti fino ad ora celati o controversi relativi al ragno, simbolo del Salento.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"1491\" class=\"wp-image-218116\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/transe.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/transe.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/transe-201x300.jpg 201w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/transe-687x1024.jpg 687w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/transe-768x1145.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/06\/novita-editoriali-ultimi-studi-sul-fenomeno-del-tarantismo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/06\/novita-editoriali-ultimi-studi-sul-fenomeno-del-tarantismo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo ______\u00a0 In francese, il termine &#8216;transe&#8217; indica specificatamente l&#8217;ansia, l&#8217;angoscia. E, in questo contesto, un nuovo misticismo contemporaneo fa capolino in questa raccolta di saggi che intreccia i significati legati al mito della \u201ctarantola\u201d alla simbologia magnogreca e paleomediterranea. Uno sguardo storiografico e antropologico illumina il rituale sincretico del tarantismo decifrandone i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218115,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218114"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218114"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218114\/revisions"}],"predecessor-version":[{"id":218117,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218114\/revisions\/218117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218115"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}