{"id":21828,"date":"2013-11-12T17:28:24","date_gmt":"2013-11-12T17:28:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=21828"},"modified":"2013-11-12T17:28:24","modified_gmt":"2013-11-12T17:28:24","slug":"pianificazione-paesaggistica-e-archeologie-giardino-paesaggio-domani-la-presentazione-delle-giornate-di-studio-con-gabellone-e-gli-esperti-di-aiapp-puglia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/12\/pianificazione-paesaggistica-e-archeologie-giardino-paesaggio-domani-la-presentazione-delle-giornate-di-studio-con-gabellone-e-gli-esperti-di-aiapp-puglia\/","title":{"rendered":"\u201cPIANIFICAZIONE PAESAGGISTICA\u201d  E \u201cARCHEOLOGIE, GIARDINO, PAESAGGIO\u201d:  DOMANI LA PRESENTAZIONE DELLE GIORNATE DI STUDIO CON GABELLONE E GLI ESPERTI DI AIAPP PUGLIA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/09\/incidente-mortale-nelle-campagne-di-soleto\/ulivo-di-soleta\/\" rel=\"attachment wp-att-5785\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/ulivo-di-soleta-150x150.jpg\" alt=\"\" title=\"ulivo di soleto\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-5785\" \/><\/a>\u201cPianificazione paesaggistica: strumenti, obiettivi e partecipazione sociale\u201d e \u201cArcheologie, Giardino, Paesaggi\u201d: sono questi i temi delle due giornate di studio che saranno presentate domani, mercoled\u00ec 13 novembre, alle ore 11, a Palazzo Adorno, a Lecce,<\/p>\n<p>Promosse dall\u2019Associazione Italiana di Architettura del Paesaggio (Aiapp) &#8211; Sezione Puglia, in collaborazione con la Provincia di Lecce, sono due giornate nelle quali sono previsti il coinvolgimento di esperti di fama nazionale ed internazionale e con le quali la sezione pugliese dell\u2019Aiapp intende dare un segno tangibile dell\u2019impegno che su vari fronti sta portando avanti sul territorio, al fine di diffondere la \u201ccultura del paesaggio\u201d.<\/p>\n<p>Alla presentazione interverranno il presidente della Provincia di Lecce Antonio Gabellone, con il direttore generale dell\u2019Ente Giovanni Refolo, la presidente Aiapp Puglia Tiziana Lettere, l\u2019agronomo e segretario Aiapp Puglia Francesco Tarantino, l\u2019agrononono Marilena Manoni e l\u2019architetto e socio onorario dell\u2019Aiapp Vincenzo Cazzato.<\/p>\n<p>La prima giornata di studio (\u201cLa pianificazione paesaggistica: strumenti, obiettivi, progetti e partecipazione sociale\u201d) \u00e8 in programma a Maglie, presso la sala etnografica del Museo Alca, il prossimo 21 novembre, ed \u00e8 dedicata ai grandi temi del paesaggio ed ai principi fondamentali che dovrebbero guidare le sue trasformazioni, in un momento che vede la Puglia coinvolta in materia di tutela del paesaggio. Il secondo appuntamento (\u201cArcheologie, Giardino, Paesaggi\u201d), previsto per il 29 novembre presso la sala teatrino dell\u2019ex Convitto Palmieri a Lecce, sar\u00e0 incentrato su uno degli ambiti pi\u00f9 affascinanti dell\u2019architettura del paesaggio, il \u201cgiardino storico\u201d.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/12\/pianificazione-paesaggistica-e-archeologie-giardino-paesaggio-domani-la-presentazione-delle-giornate-di-studio-con-gabellone-e-gli-esperti-di-aiapp-puglia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/12\/pianificazione-paesaggistica-e-archeologie-giardino-paesaggio-domani-la-presentazione-delle-giornate-di-studio-con-gabellone-e-gli-esperti-di-aiapp-puglia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cPianificazione paesaggistica: strumenti, obiettivi e partecipazione sociale\u201d e \u201cArcheologie, Giardino, Paesaggi\u201d: sono questi i temi delle due giornate di studio che saranno presentate domani, mercoled\u00ec 13 novembre, alle ore 11, a Palazzo Adorno, a Lecce, Promosse dall\u2019Associazione Italiana di Architettura del Paesaggio (Aiapp) &#8211; Sezione Puglia, in collaborazione con la Provincia di Lecce, sono due [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5785,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21828"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21828"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21828\/revisions"}],"predecessor-version":[{"id":21831,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/21828\/revisions\/21831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/5785"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=21828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=21828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=21828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}