{"id":218303,"date":"2023-07-10T11:26:00","date_gmt":"2023-07-10T09:26:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218303"},"modified":"2023-07-20T13:06:46","modified_gmt":"2023-07-20T11:06:46","slug":"riccardo-corino-e-il-nuovo-chief-business-officer-del-gruppo-bcc-iccrea","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/10\/riccardo-corino-e-il-nuovo-chief-business-officer-del-gruppo-bcc-iccrea\/","title":{"rendered":"RICCARDO CORINO E&#8217; IL NUOVO CHIEF BUSINESS OFFICER DEL GRUPPO BCC"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2229\" height=\"2560\" class=\"wp-image-218304\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Riccardo-Corino_gruppo-bcc-1-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Riccardo-Corino_gruppo-bcc-1-scaled.jpg 2229w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Riccardo-Corino_gruppo-bcc-1-261x300.jpg 261w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Riccardo-Corino_gruppo-bcc-1-892x1024.jpg 892w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Riccardo-Corino_gruppo-bcc-1-768x882.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Riccardo-Corino_gruppo-bcc-1-1337x1536.jpg 1337w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Riccardo-Corino_gruppo-bcc-1-1783x2048.jpg 1783w\" sizes=\"(max-width: 2229px) 100vw, 2229px\" \/><\/p>\n\n\n\n<p>Riccardo Corino \u00e8 il nuovo Chief Business Officer del Gruppo BCC Iccrea.<\/p>\n\n\n\n<p><em>Subentra a Luca Gasparini, nuovo Direttore Generale di BCC CreditoConsumo, la societ\u00e0 di credito al consumo del Gruppo BCC Iccrea<\/em>.<\/p>\n\n\n\n<p>Roma, 10 luglio 2023<\/p>\n\n\n\n<p>Il Consiglio di Amministrazione di BCC Banca Iccrea ha nominato Riccardo Corino nuovo Chief Business Officer del Gruppo.<\/p>\n\n\n\n<p>Riccardo Corino prende il posto di Luca Gasparini, nominato Direttore Generale di BCC Credito Consumo.<\/p>\n\n\n\n<p>Il nuovo CBO avr\u00e0 l\u2019obiettivo di contribuire a rafforzare il posizionamento commerciale delle 117 BCC del Gruppo attraverso lo sviluppo di nuove strategie e offerte di prodotti e servizi per clientela retail e corporate, anche per il tramite delle societ\u00e0 del perimetro diretto, delle strutture interne della capogruppo, delle 6 aree territoriali mercato e delle partnership con soggetti esterni.<\/p>\n\n\n\n<p>Riccardo Corino dal 2010 ha ricoperto la carica di Direttore Generale di Banca d\u2019Alba, oggi tra le pi\u00f9 grandi Banche di Credito Cooperativo aderenti al Gruppo BCC Iccrea, con oltre 62.000 soci, 11 miliardi di prodotto bancario, 170 mila clienti e 73 filiali.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sotto la sua Direzione, Banca d\u2019Alba ha realizzato un percorso di crescita molto importante e di grande attenzione alla clientela e alla compagine sociale sino a diventare la prima Banca di Credito Cooperativo in Italia per numero di soci.<\/h2>\n\n\n\n<p>Oggi il Gruppo BCC Iccrea copre l\u2019intera gamma dell\u2019offerta retail e corporate attraverso strutture specializzate nei comparti del risparmio gestito, del credito al consumo compresa la cessione del quinto, della bancassurance, del leasing, del noleggio, del factoring, della finanza strutturata e consulenza d\u2019impresa, delle operazioni con l\u2019estero, con un focus in particolare sul settore agrario e turistico.<\/p>\n\n\n\n<p>\u201cDesidero ringraziare Luca Gasparini per l\u2019impegno profuso in questi anni come CBO all\u2019interno del Gruppo BCC Iccrea e augurare buon lavoro a Riccardo Corino per le sfide che lo attendono \u2013 ha commentato Mauro Pastore, Direttore Generale del Gruppo BCC Iccrea. Oggi l\u2019intero Gruppo guarda a obiettivi particolarmente ambiziosi sul fronte dello sviluppo delle soluzioni da offrire al mercato e che permettano a ogni BCC di essere ogni giorno pi\u00f9 competitiva nel suo territorio di riferimento, e un manager con l\u2019esperienza di Corino sapr\u00e0 dare il suo contributo di valore\u201d.<\/p>\n\n\n\n<p><a>Il Gruppo BCC Iccrea \u00e8 il maggiore gruppo bancario cooperativo, il quarto gruppo bancario in Italia per attivo, il secondo per numero di sportelli in Italia e l\u2019unico gruppo bancario nazionale a capitale interamente italiano. Il Gruppo BCC Iccrea, con un attivo di 171, 5 miliardi di euro (al 31 marzo 2023), \u00e8 costituito oggi da 117 Banche di Credito Cooperativo, presenti in oltre 1.700 comuni italiani con quasi 2.500 sportelli, e da altre societ\u00e0 bancarie, finanziarie e strumentali controllate da BCC Banca Iccrea. Le BCC del Gruppo al 31 marzo 2023 hanno realizzato su tutto il territorio italiano 90 miliardi di euro di impieghi netti e una raccolta diretta da clientela pari a circa 129 miliardi di euro, contando oltre 5 milioni di clienti e circa 850 mila soci. Il Gruppo BCC Iccrea \u00e8 tra i migliori gruppi bancari per qualit\u00e0 del patrimonio con un CET 1 Ratio del 19,3% (dati al 31 marzo 2023).<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/10\/riccardo-corino-e-il-nuovo-chief-business-officer-del-gruppo-bcc-iccrea\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/10\/riccardo-corino-e-il-nuovo-chief-business-officer-del-gruppo-bcc-iccrea\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riccardo Corino \u00e8 il nuovo Chief Business Officer del Gruppo BCC Iccrea. Subentra a Luca Gasparini, nuovo Direttore Generale di BCC CreditoConsumo, la societ\u00e0 di credito al consumo del Gruppo BCC Iccrea. Roma, 10 luglio 2023 Il Consiglio di Amministrazione di BCC Banca Iccrea ha nominato Riccardo Corino nuovo Chief Business Officer del Gruppo. Riccardo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218304,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218303"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218303"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218303\/revisions"}],"predecessor-version":[{"id":218306,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218303\/revisions\/218306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218304"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}