{"id":218357,"date":"2023-07-11T00:05:00","date_gmt":"2023-07-10T22:05:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218357"},"modified":"2023-07-15T12:11:02","modified_gmt":"2023-07-15T10:11:02","slug":"218357","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/11\/218357\/","title":{"rendered":"NUOVE POLEMCHE SUL DOCUMENTARIO \u201cIl Tempo Dei Giganti\u201d"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1387\" class=\"wp-image-218358\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/ulivi-sani-1-scaled.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/ulivi-sani-1-scaled.jpeg 2560w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/ulivi-sani-1-300x163.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/ulivi-sani-1-1024x555.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/ulivi-sani-1-768x416.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/ulivi-sani-1-1536x832.jpeg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/ulivi-sani-1-2048x1109.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n\n\n\n<p><strong>OGGI ARRIVA UNA MOTIVATA STRONCATURA DA PARTE DEL GRUPPO &#8220;Salviamo gli ulivi del Salento&#8221;&nbsp;<\/strong><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. Chiara Idrusa Scrimieri, portavoce del gruppo &#8220;Salviamo gli ulivi del Salento&#8221;, ci scrive ______&nbsp;<\/p>\n\n\n\n<p>Gent.mi,<\/p>\n\n\n\n<p>con la presente intendiamo rendere pubblica la nostra presa di distanza dal film &#8220;Il tempo dei giganti&#8221; di Davide Barletti e Lorenzo Conte, prodotto da Dinamo Film, in cui il gruppo ecologista &#8220;Salviamo gli ulivi  Del Salento&#8221; compare come tassello di cronaca sulla denuncia dell&#8217;emergenza incendi nel Salento.&nbsp;<\/p>\n\n\n\n<p>Argomentazioni e motivazioni sono nel comunicato allegato.&nbsp;______&nbsp;<\/p>\n\n\n\n<p>\u00c8 estate e il film \u201cIl tempo dei giganti\u201d, con la regia di Davide Barletti e Lorenzo Conte e prodotto da Dinamo Film, torna in programmazione nel territorio salentino. Si fa dunque necessaria una nostra comunicazione pubblica al riguardo per esprimere la nostra presa di distanza dal film, in cui il gruppo \u201cSalviamo gli ulivi del Salento\u201d compare come tassello di cronaca sugli incendi rurali che attanagliano il territorio salentino, ad oggi per la quarta estate consecutiva.<\/p>\n\n\n\n<p><br>Questa partecipazione ci ha messi nella condizione, nei mesi appena trascorsi, di essere associati all\u2019operazione narrativa del film e alle sue tesi, che trovano numerose corrispondenze nella letteratura giornalistica pubblicata a precedere e a seguire sullo stesso tema (Martella, Rielli, Liberti). <\/p>\n\n\n\n<p>Ebbene, pubblichiamo questo comunicato per eliminare ogni possibilit\u00e0 di ulteriore equivoco al riguardo, offrendo qualche doverosa argomentazione a chi ci segue, alle 40mila firme che hanno sostenuto la nostra campagna di sensibilizzazione sull&#8217;emergenza agro-ambientale salentina su change.org e alle 61 associazioni firmatarie del faticoso documento programmatico che ne \u00e8 seguito, che contiene proposte di rigenerazione agro-ambientale per un dialogo istituzionale.<\/p>\n\n\n\n<p><br>Abbiamo visto il film per la prima volta in apertura del Festival del Cinema Europeo a Lecce a fine 2022, in sala come tutti e senza anteprime private (ad oggi, la copia del film in distribuzione \u00e8 quella che \u00e8 stata ampiamente ripulita dalle sue espressioni pi\u00f9 infelici in seguito alle nostre immediate rimostranze e di altri protagonisti del film: non troverete pi\u00f9 allusioni esplicite a \u201csantoni\u201d, \u201cisterie collettive\u201d e altre frasi simili usate per denigrare chi si \u00e8 espresso in modo critico nei confronti della gestione dell\u2019emergenza Xylella).<\/p>\n\n\n\n<p><br>Abbiamo preso atto di trovarci di fronte a un!opera la cui tesi giunge parecchio in ritardo rispetto allo svolgersi di un\u2019emergenza (che dopo dieci anni non pu\u00f2 pi\u00f9 fisiologicamente definirsi tale) e si sintetizza nell!estrema semplificazione di un tema complesso. La crisi epocale della ruralit\u00e0 e della salute ambientale che vive da decenni il territorio salentino (la &#8220;questione rurale\u201d, come la chiamammo a suo tempo) \u00e8 ridotta al microscopio di un fenomeno batterico, pur con tutte le conseguenti crisi di comparto e di paesaggio.<br>Eppure il team di uomini di scienze, comprese quelle umanistiche, coinvolti nella narrazione ci sarebbe anche nel film, se non altro per variet\u00e0 di rappresentanza di ambiti di conoscenze e competenza. Peccato che sia prevalentemente chiamato a fare romanzo di colpe di una complessa vicenda scientifica, umana, culturale, economica, politica e sociale, che ancora oggi vive la mancanza di un approccio onesto e maturo da parte di tutta la societ\u00e0 civile, in cui ognuno dovrebbe assumersi la propria responsabilit\u00e0. <\/p>\n\n\n\n<p>Ancora nel 2023 il contributo al dibattito salentino sul gravissimo tema del disseccamento degli ulivi resta ancorato alla polarizzazione tra chi si \u00e8 opposto alle eradicazioni, chiedendo che gli ulivi potessero essere curati e chi le eradicazioni le sosteneva e tuttora sostiene febbrilmente. Irresponsabili ambientalisti stigmatizzati come \u201csantoni\u201d da un lato e scienziati commiserati dall\u2019altro, inibiti a fare il proprio dovere salvifico da una generica &#8220;Politica\u201d un po\u2019 bloccata dalla magistratura e un po\u2019 anche indecisa e incapace di gestire adeguatamente l\u2019emergenza.<\/p>\n\n\n\n<p>Una trama che si snoda sullo sfondo di uno scenario narrativo mel\u00f2, con una sorta di lirica funebre di ulivi, olivicoltori e paesaggio, come nei migliori copioni dell\u2019Opera lirica sospesa tra ineluttabilit\u00e0 e mesta rassegnazione al fato.<br>Con, attori principali, gli olivicoltori anziani, increduli e testardi di fronte alla modernit\u00e0 distopica raccontatagli dai figli (che nel film passa come \u201cla realt\u00e0\u201d) e una non ben precisata popolazione di proprietari terrieri sullo sfondo, anche questi commiserati, ma nella scelta (!) di dar fuoco agli ulivi per liberarsi dall\u2019ingombro del cadavere (senza fare troppa attenzione ad avallare un comportamento giuridicamente criminale).<\/p>\n\n\n\n<p><br>Nessuna completezza di analisi o contributo di nuovi dati al fenomeno (come forse ci si attenderebbe da un film \u201cdocumentario\u201d), assente lo sguardo sulla variegata attualit\u00e0 rurale del territorio salentino, nessuna visione in prospettiva o analisi inclusiva di quella fitta e articolata attivit\u00e0 di rigenerazione agroambientale in atto da anni, compresa la cura degli stessi alberi di ulivo. <\/p>\n\n\n\n<p>Negata la presenza dei numerosi protagonisti della rinascita, del ripensamento rurale, delle nuove pratiche agricole rigenerative, delle attivit\u00e0 di campo ma anche di informazione e comunicazione messe in piedi ormai da tempo per fare nuova economia, rete, ricostruzione e visione di un futuro agricolo, rurale e paesaggistico integrato, per ripensare l\u2019arretratezza agricola salentina e superare la crisi della fitopatia.<br>Per andare avanti.<br>Noi &#8220;Salviamo gli ulivi del Salento\u201d, che siamo un movimento ecologista e di coscienza, vocato allo studio, alla connessione tra i saperi, alla ricerca e alla conoscenza, ci chiediamo come si faccia, in coscienza, ad essere pubblicamente cos\u00ec approssimativi e a perpetrare un torto narrativo e di postura cos\u00ec grave nei confronti della propria terra. Tanto pi\u00f9 in un momento storico che avrebbe bisogno di svecchiare questa consunzione culturale del territorio che porta a chiudere, colpevolizzare, polarizzare nel conflitto anzich\u00e9 attivare a tutti i livelli gli anticorpi della crisi, sul campo e anche dentro al pensiero e alla visione, che onsieme fanno il patrimonio culturale dell\u2019esperienza collettiva e l\u2019evoluzione di una societ\u00e0 civile.<\/p>\n\n\n\n<p><br>Ci sentiamo inoltre a disagio perch\u00e9 in una narrazione filmica non \u00e8 corretto accusare, citare impropriamente o alludere a persone che non possono replicare o difendersi proprio in virt\u00f9 del perimetro chiuso di un\u2019opera edita e conclusa. Persone, giornalisti, operatori, voci della societ\u00e0 civile rei di pronunciarsi personalmente su un tema che, invece, \u00e8 patrimonio collettivo, sono accusati di sentimentalismo antiscientista da giornalisti e sociologi del film che &#8220;scienziati&#8221; o specialisti non sono neanche loro, chiamati a raccolta intorno a un sentimento di livore incomprensibile. <\/p>\n\n\n\n<p>E poi ci sarebbe da chiedersi come si possa ringraziare nei titoli di coda qualcuno che non c\u2019\u00e8 pi\u00f9, come Luigi Russo, giornalista d\u2019inchiesta morto qualche anno fa, che del tema si \u00e8 occupato eccome, ma di cui nel film non compare traccia. O Maril\u00f9 Mastrogiovanni, anche lei giornalista d\u2019inchiesta che ha scritto approfonditamente sul tema, a quanto pare ripetutamente contattata dagli autori e per\u00f2 mai intervistata e ascoltata. O Ivano Gioffreda, rappresentante di quei tanti contadini che vivono e operano sul campo e con approccio integrato hanno sperimentato cure degli ulivi con buoni risultati come alternativa all\u2019eradicazione (anche di lui, nel film, non c\u2019\u00e8 traccia).<\/p>\n\n\n\n<p><br>Volendo sintetizzare in modo estremo la questione \u00e8 che la realt\u00e0 non \u00e8 una nostra propriet\u00e0 e non possiamo farne ci\u00f2 che vogliamo, soprattutto in ambito di comunicazione pubblica. Dietro allusioni, citazioni e nomi propri di persona ci sono vissuti, storie, vite che abbiamo il dovere di ascoltare e di rispettare per il loro valore intrinseco. <\/p>\n\n\n\n<p>Dopo dieci anni di emergenza riteniamo che il teatrino delle colpe sia scaduto e stantio. <\/p>\n\n\n\n<p>Crediamo che il Salento non abbia bisogno di narrazioni melodrammatiche o compianti sul Cristo morto, ma di una critica riattivazione della consapevolezza personale e collettiva su quel bene pubblico che \u00e8 la terra, fonte di sostentamento e autosufficienza alimentare, condizione per la garanzia delle forme di vita. Anche perch\u00e9, da come enuncia la foto a corredo dell\u2019articolo, nonostante i numerosi cadaveri lasciati a morire dall\u2019uomo sul campo invece di curarsene, forse quel Cristo non \u00e8 affatto e ovunque morto, ma ancora vive e lotta insieme a noi.<br>(In allegato foto di uliveto con alberi secolari verdi) ______&nbsp;<\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo di ieri<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"jYH8YJ1HZp\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/10\/la-polemica-margherita-damico-e-ivano-gioffreda-diffidano-legalmente-i-produttori-del-documentario-il-tempo-dei-giganti-non-nel-nostro-nome\/\">LA POLEMICA \u00a0\/\u00a0MARGHERITA D&#8217;AMICO E IVANO GIOFFREDA DIFFIDANO LEGALMENTE I PRODUTTORI DEL DOCUMENTARIO \u201cIl Tempo Dei Giganti\u201d: \u201cNon nel nostro nome\u201d<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;LA POLEMICA \u00a0\/\u00a0MARGHERITA D&#8217;AMICO E IVANO GIOFFREDA DIFFIDANO LEGALMENTE I PRODUTTORI DEL DOCUMENTARIO \u201cIl Tempo Dei Giganti\u201d: \u201cNon nel nostro nome\u201d&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/10\/la-polemica-margherita-damico-e-ivano-gioffreda-diffidano-legalmente-i-produttori-del-documentario-il-tempo-dei-giganti-non-nel-nostro-nome\/embed\/#?secret=cBPPOjhL9w#?secret=jYH8YJ1HZp\" data-secret=\"jYH8YJ1HZp\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/11\/218357\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/11\/218357\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>OGGI ARRIVA UNA MOTIVATA STRONCATURA DA PARTE DEL GRUPPO &#8220;Salviamo gli ulivi del Salento&#8221;&nbsp; Riceviamo e volentieri pubblichiamo. Chiara Idrusa Scrimieri, portavoce del gruppo &#8220;Salviamo gli ulivi del Salento&#8221;, ci scrive ______&nbsp; Gent.mi, con la presente intendiamo rendere pubblica la nostra presa di distanza dal film &#8220;Il tempo dei giganti&#8221; di Davide Barletti e Lorenzo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218357"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218357"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218357\/revisions"}],"predecessor-version":[{"id":218553,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218357\/revisions\/218553"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}