{"id":218604,"date":"2023-07-16T14:22:08","date_gmt":"2023-07-16T12:22:08","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218604"},"modified":"2023-07-16T16:58:08","modified_gmt":"2023-07-16T14:58:08","slug":"nuova-comunicazione-dellapoliia-di-stato-perla-sicurezza-stradale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/16\/nuova-comunicazione-dellapoliia-di-stato-perla-sicurezza-stradale\/","title":{"rendered":"NUOVA COMUNICAZIONE POLIZIA DI STATO PER LA SICUREZZA STRADALE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"282\" height=\"179\" class=\"wp-image-218605\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/download-9.jpg\" alt=\"\"><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Basta con le distrazioni. Basta con l\u2019uso del cellulare. Basta con l\u2019uso di alcol e droghe. Mettersi alla guida dell\u2019auto \u00e8 un atto di responsabilit\u00e0 e di rispetto delle regole. Il viaggio su strada non pu\u00f2 rappresentare un rischio per la propria vita e quella degli altri.<\/p>\n\n\n\n<p>Nel nuovo spot sulla sicurezza stradale, presentato oggi, Anas (Societ\u00e0 del Polo Infrastrutture del Gruppo FS Italiane) rilancia questi messaggi che dal 2015 sta divulgando nella sua campagna con uno slogan diretto e chiaro: \u201cQuando guidi, Guida e Basta\u201d<\/p>\n\n\n\n<p>Il video \u00e8 stato realizzato da Anas in collaborazione con il Ministero delle Infrastrutture e dei Trasporti e la Polizia di Stato, in versione televisiva e radiofonica.<\/p>\n\n\n\n<p>&nbsp;\u201cL&#8217;impegno di Anas per garantire sicurezza sulle nostre strade \u00e8 costante e quotidiano \u2013 ha dichiarato l\u2019AD Aldo Isi \u2013 attraverso la manutenzione, il controllo e il monitoraggio delle infrastrutture. Ma si deve affiancare il comportamento corretto alla guida. Rispettare il codice della strada e guidare senza distrazioni non pu\u00f2 essere un optional, ma un dovere di tutti. Solo cos\u00ec possiamo raggiungere l&#8217;obiettivo, in linea con le strategie della Capogruppo FS, di riduzione degli incidenti del 50% entro il 2030 e zero vittime entro il 2050. Ricordiamo che oltre il 93% degli incidenti stradali deriva dal comportamento del guidatore: distrazione, velocit\u00e0 eccessiva, guida in stato di alterazione. E\u2019 responsabilit\u00e0 e priorit\u00e0 di tutti noi \u2013 sottolinea l\u2019ad di Anas &#8211; sensibilizzare soprattutto le nuove generazioni e diffondere in ogni settore sociale una nuova cultura della sicurezza stradale. La campagna \u201cGuida e Basta\u201d nata nel 2015 \u2013 ha proseguito Isi &#8211; \u00e8 dedicata proprio ai rischi che derivano dalle cattive abitudini alla guida. Siamo impegnati anche in numerosi progetti educativi realizzati con il supporto di testimonial del mondo dello spettacolo e dello sport, finalizzati alla prevenzione e al contrasto dell\u2019incidentalit\u00e0\u201d<\/p>\n\n\n\n<p>\u201cPurtroppo, quest\u2019anno stiamo registrando, nell\u2019incidentalit\u00e0 stradale, un trend lineare con dati che devono far riflettere seriamente sulle strategie da adottare per aggredire l\u2019obiettivo europeo del 2030 del dimezzamento del numero di vittime sulle nostre strade.\u201d Dichiara Filiberto Mastrapasqua, direttore del Servizio Polizia Stradale \u2013 \u201cFra le altre, la prevenzione realizzata attraverso la comunicazione \u00e8 senza dubbio la chiave di volta per affrontare efficacemente il fenomeno dell\u2019incidentalit\u00e0 che vede, quale prima causa, la distrazione seguita dalla velocit\u00e0. Telefonare, chattare o riprendersi mentre si guida, sono comportamenti azzardati e pericolosi che devono essere evitati. Guidare con prudenza deve entrare a far parte del bagaglio culturale di ciascuno di noi.\u201d<\/p>\n\n\n\n<p>Il nuovo spot di Anas, diventato un appuntamento annuale, \u00e8 stato realizzato nelle due versioni da 30 e 15 secondi e sar\u00e0 trasmesso, a partire da domenica 16 luglio, sui principali circuiti radio-televisivi nazionali.<\/p>\n\n\n\n<p>Lo spot sar\u00e0 presente anche sui profili social di Anas: Facebook, Twitter, Instagram e sul canale Youtube e tutte le informazioni sulla campagna \u201cGUIDAeBASTA\u201d sono disponibili alla pagina&nbsp;<a href=\"https:\/\/webpec-interno.infocert.it\/webmail\/?cn=ministerointerno\">guidaebasta.it<\/a>&nbsp;<\/p>\n\n\n\n<p>L\u2019impianto della narrazione dello spot \u00e8 incentrato su due gruppi di giovani, il target principale a cui destinato il messaggio, che stanno andando in discoteca su due diverse vetture. Con un montaggio alternato e l\u2019uso di inquadrature verticali, che richiamano il linguaggio dei social network, si notano i comportamenti contrapposti: la condotta scorretta degli uni (uso del cellulare, realizzazione di video e foto, cintura di sicurezza non indossata) contro quella corretta degli altri.<\/p>\n\n\n\n<p>&nbsp;&nbsp;Solo questi ultimi giungeranno a destinazione.&nbsp;Il messaggio \u00e8 chiaro: la distrazione, l\u2019uso smodato del telefono e dei social durante la guida sono comportamenti pericolosi per s\u00e9 e per gli altri.<\/p>\n\n\n\n<p>Molto spesso risultano fatali.&nbsp;Oltre alla distrazione, anche l\u2019eccessiva sicurezza nel comportamento alla guida \u00e8 un dato significativo che contribuisce all\u2019aumento degli incidenti stradali\u2026<\/p>\n\n\n\n<p><strong>AL LINK IL VIDEO<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.poliziadistato.it\/pressarea\/Share\/link\/804a34ac-22e2-11ee-b322-736d736f6674\">https:\/\/www.poliziadistato.it\/pressarea\/Share\/link\/804a34ac-22e2-11ee-b322-736d736f6674<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/16\/nuova-comunicazione-dellapoliia-di-stato-perla-sicurezza-stradale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/16\/nuova-comunicazione-dellapoliia-di-stato-perla-sicurezza-stradale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Basta con le distrazioni. Basta con l\u2019uso del cellulare. Basta con l\u2019uso di alcol e droghe. Mettersi alla guida dell\u2019auto \u00e8 un atto di responsabilit\u00e0 e di rispetto delle regole. Il viaggio su strada non pu\u00f2 rappresentare un rischio per la propria vita e quella degli altri. Nel nuovo spot sulla sicurezza stradale, presentato oggi, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218605,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218604"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218604"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218604\/revisions"}],"predecessor-version":[{"id":218607,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218604\/revisions\/218607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218605"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}