{"id":218608,"date":"2023-07-16T17:51:40","date_gmt":"2023-07-16T15:51:40","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218608"},"modified":"2023-07-16T18:04:52","modified_gmt":"2023-07-16T16:04:52","slug":"addio-ad-antonello","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/16\/addio-ad-antonello\/","title":{"rendered":"ADDIO AD ANTONELLO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1135\" height=\"1135\" class=\"wp-image-218609\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/73322473_2464220910358704_7417726231807787008_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/73322473_2464220910358704_7417726231807787008_n.jpg 1135w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/73322473_2464220910358704_7417726231807787008_n-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/73322473_2464220910358704_7417726231807787008_n-1024x1024.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/73322473_2464220910358704_7417726231807787008_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/73322473_2464220910358704_7417726231807787008_n-768x768.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/73322473_2464220910358704_7417726231807787008_n-60x60.jpg 60w\" sizes=\"(max-width: 1135px) 100vw, 1135px\" \/>(e.l.) ______ Questa caldissima domenica di luglio deve registrare un incidente stradale mortale, avvenuto verso le 13 sulla statale dei Trulli nei pressi di Laureto, frazione di Fasano.<\/p>\n\n\n\n<p>La vittima \u00e8 Antonello Savoia, 61 anni, di Fasano, commercialista.<\/p>\n\n\n\n<p>Per cause ancora da accertare, ha perso il controllo della moto da corsa &#8216;fuoristrada&#8217; che guidava e si \u00e8 schiantato violentemente per terra e sul muro di pietre ai margini della carreggiata.<\/p>\n\n\n\n<p>E&#8217; morto sul colpo, inutili i tentativi di soccorrerlo.<\/p>\n\n\n\n<p>In queste poche ore sono gi\u00e0 numerosi e strazianti sui social i messaggi di amici e conoscenti.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/16\/addio-ad-antonello\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/16\/addio-ad-antonello\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Questa caldissima domenica di luglio deve registrare un incidente stradale mortale, avvenuto verso le 13 sulla statale dei Trulli nei pressi di Laureto, frazione di Fasano. La vittima \u00e8 Antonello Savoia, 61 anni, di Fasano, commercialista. Per cause ancora da accertare, ha perso il controllo della moto da corsa &#8216;fuoristrada&#8217; che guidava e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218609,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218608"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218608"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218608\/revisions"}],"predecessor-version":[{"id":218610,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218608\/revisions\/218610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218609"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}