{"id":218624,"date":"2023-07-17T11:11:00","date_gmt":"2023-07-17T09:11:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218624"},"modified":"2023-07-17T12:09:06","modified_gmt":"2023-07-17T10:09:06","slug":"comunicazione-dei-carabinieri-sui-controlli-effettuati-sulla-movida","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/17\/comunicazione-dei-carabinieri-sui-controlli-effettuati-sulla-movida\/","title":{"rendered":"COMUNICAZIONE DEI CARABINIERI SUI CONTROLLI EFFETTUATI SULLA &#8216;MOVIDA&#8217;"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1053\" height=\"679\" class=\"wp-image-218625\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/G8.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/G8.jpg 1053w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/G8-300x193.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/G8-1024x660.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/G8-768x495.jpg 768w\" sizes=\"(max-width: 1053px) 100vw, 1053px\" \/><\/p>\n\n\n\n<p><strong><em>La stagione estiva \u00e8 oramai entrata nel vivo e cresce l\u2019incisivit\u00e0 dei controlli dell\u2019Arma, sempre pi\u00f9 presente per garantire una maggiore sicurezza percepita, soprattutto nelle ore serali e notturne della vita salentina.<\/em><\/strong><\/p>\n\n\n\n<p>Nell\u2019ambito dell\u2019intensificazione dei controlli pianificati in sede di Tavolo Tecnico, da parte di tutte le Forze di Polizia presenti sul territorio, lo scorso fine settimana, <strong>i Carabinieri della Compagnia di Gallipoli,<\/strong> con il supporto dei <strong>colleghi del Comando Provinciale di Lecce<\/strong> e <strong>del Nas<\/strong>, hanno effettuato serrati controlli nelle principali aree della c.d. <em>movida<\/em>, al fine di contrastare i reati in genere, soprattutto quelli relativi alla sicurezza stradale, alla prevenzione del consumo di alcolici da parte di minori, e quelli connessi allo spaccio di sostanze stupefacenti.<\/p>\n\n\n\n<p>Durante l\u2019attivit\u00e0 di controllo straordinario del territorio, che ha interessato in particolar modo <strong>le marine di Gallipoli e Nard\u00f2,<\/strong> il personale del Nas ha espletato la verifica di diverse attivit\u00e0 di somministrazione ambulante, rilevando sanzioni amministrative per l\u2019illecita vendita di bevande alcoliche nonch\u00e9 per carenze igienico &#8211; strutturali segnalate all\u2019Autorit\u00e0 sanitaria.<\/p>\n\n\n\n<p>Nell\u2019ambito del servizio coordinato sono state identificate oltre 300 persone e controllati circa 200 veicoli, rilevando diverse violazioni al codice della strada, anche in relazione al servizio navetta esercitato abusivamente, senza la prevista licenza.<\/p>\n\n\n\n<p>Inoltre, nel corso dell\u2019attivit\u00e0 finalizzata al contrasto all\u2019uso e allo spaccio di droga, i Carabinieri hanno eseguito 11 segnalazioni alla competente Prefettura per consumo non terapeutico di sostanza stupefacente.<\/p>\n\n\n\n<p>Tutti sanno che la capacit\u00e0 di guida, soprattutto in termini di attenzione e concentrazione \u00e8 influenzata negativamente dalla assunzione di alcool e\/o sostanze stupefacenti.<\/p>\n\n\n\n<p>La guida sotto l&#8217;effetto di sostanze alcoliche \u00e8 tra le principali cause degli incidenti stradali gravi e mortali, in particolare fra i giovani. Si stima che almeno il 35% degli incidenti stradali sia causato da guida in stato di ebrezza alcolica. Recenti studi nazionali hanno dimostrato che pi\u00f9 di 3 giovani su 4 fanno uso di bevande alcoliche.<\/p>\n\n\n\n<p>L&#8217;alcool ha un effetto sedativo e riduce la vigilanza, crea euforia, facilita l&#8217;assunzione di comportamenti imprudenti, esagera la fiducia nelle proprie abilit\u00e0 e falsa la percezione delle distanze e della velocit\u00e0.<\/p>\n\n\n\n<p>A parit\u00e0 di concentrazione di alcool nel sangue, il rischio aumenta molto rapidamente quanto minore \u00e8 l&#8217;et\u00e0 del conducente e quanto \u00e8 pi\u00f9 rara la frequenza con cui si consumano usualmente bevande alcoliche.<\/p>\n\n\n\n<p>L&#8217;uso di sostanze stupefacenti \u00e8 un altro fattore che influenza negativamente la capacit\u00e0 di guida del conducente generando situazioni di pericolo per s\u00e9 e per gli altri. L&#8217;assunzione di sostanze stupefacenti provoca una modificazione delle funzioni del sistema nervoso centrale ed un&#8217;alterazione dello stato di coscienza.<\/p>\n\n\n\n<p>Guidare sotto l&#8217;effetto di queste sostanze significa mettere a repentaglio la propria vita e quella degli altri, oltre che rischiare di incorrere nell&#8217;arresto o in sanzioni amministrative (di natura pecuniaria e di sospensione della patente).<\/p>\n\n\n\n<p>Gli effetti negativi dell&#8217;assunzione delle sostanze stupefacenti e dell&#8217;alcool sulla capacit\u00e0 di guida sono noti e, in maniera pi\u00f9 diffusa, sono trattati nella sezione &#8220;Questioni di vita&#8221; sotto le voci &#8220;<strong>Tossicodipendenza da sostanze stupefacenti<\/strong>&#8221; e &#8220;<strong>Alcool: una vita persa in un bicchiere<\/strong>&#8221; del sito istituzionale dell\u2019Arma dei carabinieri. (www.Carabinieri.it)<\/p>\n\n\n\n<p>Il servizio di controllo del territorio, continuer\u00e0 regolarmente anche nelle prossime settimane, intensificandosi gradualmente nel periodo clou della stagione estiva, momento sempre complesso e delicato soprattutto per la grande affluenza di turisti e visitatori della costa salentina.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/17\/comunicazione-dei-carabinieri-sui-controlli-effettuati-sulla-movida\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/17\/comunicazione-dei-carabinieri-sui-controlli-effettuati-sulla-movida\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La stagione estiva \u00e8 oramai entrata nel vivo e cresce l\u2019incisivit\u00e0 dei controlli dell\u2019Arma, sempre pi\u00f9 presente per garantire una maggiore sicurezza percepita, soprattutto nelle ore serali e notturne della vita salentina. Nell\u2019ambito dell\u2019intensificazione dei controlli pianificati in sede di Tavolo Tecnico, da parte di tutte le Forze di Polizia presenti sul territorio, lo scorso [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218625,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218624"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218624"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218624\/revisions"}],"predecessor-version":[{"id":218626,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218624\/revisions\/218626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218625"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}