{"id":218726,"date":"2023-07-19T14:20:22","date_gmt":"2023-07-19T12:20:22","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218726"},"modified":"2023-07-19T14:21:35","modified_gmt":"2023-07-19T12:21:35","slug":"calciomercato-lecce-corvino-pesca-nei-mari-della-serie-c-svedese","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/19\/calciomercato-lecce-corvino-pesca-nei-mari-della-serie-c-svedese\/","title":{"rendered":"CALCIOMERCATO LECCE \/\u00a0CORVINO PESCA NEI MARI DELLA SERIE C SVEDESE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" class=\"wp-image-218727\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/download-12.jpg\" alt=\"\"><\/p>\n\n\n\n<p>(Rdl) ______ L&#8217;U.S. Lecce comunica di aver acquisito, a titolo definitivo, il diritto alle prestazioni sportive del calciatore Zinedin Smajlovic dal T\u00e4by FK.<\/p>\n\n\n\n<p>Il difensore svedese classe 2003 ha sottoscritto un accordo della durata di tre anni con opzione per i successivi due.<\/p>\n\n\n\n<p>Zinedin Smajlovic, difensore centrale, \u00e8 nato a Stoccolma il 20 dicembre 2003. E&#8217; di origini bosniache ed ha la doppia nazionalit\u00e0, appunto bosniaca e svedese.<\/p>\n\n\n\n<p>Quest&#8217;anno ha  giocato nel Taby FK, squadra di Taby, un comune svedese di 63.000 abitanti, situato nella contea di Stoccolma, nella regione dell&#8217;Uppland, che milita nella serie C svedese.<\/p>\n\n\n\n<p>E&#8217;arrivato in prestito gratuito a met\u00e0 campionato ed ha fatto registrare 13 presenze e 5 gol.<\/p>\n\n\n\n<p>Si tratta chiaramente di un altro giocatore &#8216;scoperto&#8217; da Pantaleo Corvino e preso a costo praticamente zero, tipo Banda e Ceesay.<\/p>\n\n\n\n<p>Il campo dir\u00e0 se il direttore dell&#8217;area tecnica del Lecce ha visto giusto. ______<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>LA RICRCA nel nostro articolo di ieri<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"9FLAAIYmUM\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/18\/calciomercato-lecce-una-speranzauna-scommessa-tunisina-hamza-rafia\/\">CALCIOMERCATO LECCE \/ UNA SCOMMESSA TUNISINA: HAMZA RAFIA<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;CALCIOMERCATO LECCE \/ UNA SCOMMESSA TUNISINA: HAMZA RAFIA&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/18\/calciomercato-lecce-una-speranzauna-scommessa-tunisina-hamza-rafia\/embed\/#?secret=dmOPpcNk0U#?secret=9FLAAIYmUM\" data-secret=\"9FLAAIYmUM\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/19\/calciomercato-lecce-corvino-pesca-nei-mari-della-serie-c-svedese\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/19\/calciomercato-lecce-corvino-pesca-nei-mari-della-serie-c-svedese\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ______ L&#8217;U.S. Lecce comunica di aver acquisito, a titolo definitivo, il diritto alle prestazioni sportive del calciatore Zinedin Smajlovic dal T\u00e4by FK. Il difensore svedese classe 2003 ha sottoscritto un accordo della durata di tre anni con opzione per i successivi due. Zinedin Smajlovic, difensore centrale, \u00e8 nato a Stoccolma il 20 dicembre 2003. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218727,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218726"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218726"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218726\/revisions"}],"predecessor-version":[{"id":218730,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218726\/revisions\/218730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218727"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}